{"id":23711,"date":"2024-12-03T20:30:18","date_gmt":"2024-12-04T02:30:18","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=23711"},"modified":"2024-12-03T20:30:18","modified_gmt":"2024-12-04T02:30:18","slug":"seguimos-fortaleciendo-las-relaciones-internacionales-de-coahuila-manolo","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/12\/03\/seguimos-fortaleciendo-las-relaciones-internacionales-de-coahuila-manolo\/","title":{"rendered":"SEGUIMOS FORTALECIENDO LAS RELACIONES INTERNACIONALES DE COAHUILA: MANOLO."},"content":{"rendered":"\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong><em>Se re\u00fanen Gobernador y su esposa Paola Rodr\u00edguez con Embajadoras de diversos pa\u00edses<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 02 de diciembre de 2024.- El gobernador Manolo Jim\u00e9nez Salinas y su esposa Paola Rodr\u00edguez L\u00f3pez, presidenta honoraria de Inspira Coahuila, recibieron en Palacio de Gobierno a Embajadoras en M\u00e9xico de distintos pa\u00edses, con quienes estrecharon lazos de amistad y acordaron trabajar en conjunto en temas que son de inter\u00e9s tanto para Coahuila como para sus respectivas naciones.<\/p>\n\n\n\n<p>&#8220;Tuvimos una excelente reuni\u00f3n con 7 embajadoras de diferentes pa\u00edses. Seguiremos trabajando para promocionar a Coahuila ante M\u00e9xico y el mundo. \u00a1Bienvenidas, esta es su casa!&#8221;, destac\u00f3 el gobernador.<\/p>\n\n\n\n<p>En esta reuni\u00f3n estuvieron presentes las Excelent\u00edsimas Embajadoras Elisabeth Kehrer, de Austria; Ter\u00e9zia \u0160ajgal\u00edkov\u00e1, de Eslovaquia; Tatjana Conic, de Serbia; Gloria Yrma Amarilla Acosta, de Paraguay; Abida Islam, de Bangladesh; Lilybeth R. Deapera, de Filipinas; y Julia Hyatt, de Jamaica.<\/p>\n\n\n\n<p>Adem\u00e1s de Hilda Flores Escalera, representante del Gobierno de Coahuila en la Ciudad de M\u00e9xico; Liliana Salinas Vald\u00e9s, presidenta honoraria del DIF Coahuila; Luz Elena Morales N\u00fa\u00f1ez, diputada presidenta de la Junta de Gobierno del Congreso del Estado; Cristina Amezcua Gonz\u00e1lez, secretaria de Turismo; Cecilia de la Garza Mart\u00ednez, directora general de Inspira Coahuila.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez dio la bienvenida a Coahuila a este grupo de Embajadoras a quienes les reiter\u00f3 su total disposici\u00f3n de trabajo y apertura para alcanzar los proyectos, acciones y estrategias conjuntas que sean de beneficio para cada pa\u00eds que representan y para Coahuila.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que Coahuila cuenta con una gran diversidad de temas en los que se puede colaborar e intercambiar experiencias de \u00e9xito con sus respectivos pa\u00edses, como el de promoci\u00f3n econ\u00f3mica, turismo, vitivinicultura, Derechos Humanos, educaci\u00f3n, cultura, desarrollo sostenible, agua, seguridad, cooperaci\u00f3n para el desarrollo, entre otros.<\/p>\n\n\n\n<p>Paola Rodr\u00edguez record\u00f3 que hace algunos meses se reuni\u00f3 en la Ciudad de M\u00e9xico con algunas Embajadoras, gracias a las gestiones de Hilda Flores, representante de Coahuila en la Ciudad de M\u00e9xico, en mesa de trabajo donde se plantearon las bases para acciones en conjunto con cada uno de los pa\u00edses que representan y el Gobierno del Estado, y en donde se hizo la invitaci\u00f3n para que visitaran nuestra entidad.<\/p>\n\n\n\n<p>Tambi\u00e9n agradeci\u00f3 a todas las representantes diplom\u00e1ticas por aceptar la invitaci\u00f3n y por tener la apertura y disponibilidad para acordar una agenda conjunta de trabajo que sea de beneficio para todos.<\/p>\n\n\n\n<p>Indic\u00f3 que desde Inspira Coahuila se apoya al gobierno de Manolo Jim\u00e9nez para cumplir con varios de los compromisos que se hicieron con las y los coahuilenses, por lo que desde el inicio de la administraci\u00f3n estatal se ha buscado hacer sinergias con diferentes organizaciones de la sociedad civil, iniciativa privada, y de manera transversal con las dependencias del gobierno estatal.<\/p>\n\n\n\n<p>Por su parte, las Embajadoras que estuvieron este d\u00eda en Palacio de Gobierno compartieron, en su intervenci\u00f3n, los temas de inter\u00e9s de trabajo en conjunto con el Gobierno del Estado de Coahuila.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Se re\u00fanen Gobernador y su esposa Paola Rodr\u00edguez con Embajadoras de diversos pa\u00edses Saltillo, Coahuila de Zaragoza; a 02 de diciembre de 2024.- El gobernador Manolo Jim\u00e9nez Salinas y su esposa Paola Rodr\u00edguez L\u00f3pez, presidenta honoraria de Inspira Coahuila, recibieron en Palacio de Gobierno a Embajadoras en M\u00e9xico de distintos pa\u00edses, con quienes estrecharon lazos de amistad y acordaron trabajar en conjunto en temas que son de inter\u00e9s tanto para&#8230;<\/p>\n","protected":false},"author":1,"featured_media":23712,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15],"tags":[],"class_list":["post-23711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","wpcat-5-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=23711"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23711\/revisions"}],"predecessor-version":[{"id":23713,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23711\/revisions\/23713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/23712"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=23711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=23711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=23711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}