{"id":23939,"date":"2024-12-19T20:03:41","date_gmt":"2024-12-20T02:03:41","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=23939"},"modified":"2024-12-19T20:03:41","modified_gmt":"2024-12-20T02:03:41","slug":"convoca-uadec-a-aprender-sobre-cinematografia-e-inscribirse-al-taller-de-cortometraje","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/12\/19\/convoca-uadec-a-aprender-sobre-cinematografia-e-inscribirse-al-taller-de-cortometraje\/","title":{"rendered":"Convoca UAdeC a Aprender sobre Cinematograf\u00eda e Inscribirse al Taller de Cortometraje."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 18 de diciembre de 2024. Como parte del compromiso de<br>innovaci\u00f3n y pertinencia en la oferta educativa, la Universidad Aut\u00f3noma de<br>Coahuila, a trav\u00e9s de la Coordinaci\u00f3n de Difusi\u00f3n y Patrimonio Cultural y del Recinto<br>Universitario \u201cAurora Morales de L\u00f3pez\u201d, ofrecer\u00e1 por primera vez el Taller de<br>Cortometraje en el periodo enero-junio 2025.<\/p>\n\n\n\n<p>Este programa acad\u00e9mico est\u00e1 dirigido a la comunidad universitaria y p\u00fablico en<br>general, y tiene como objetivo que los j\u00f3venes y adultos participantes conozcan<br>sobre el mundo cinematogr\u00e1fico y audiovisual de forma pr\u00e1ctica y l\u00fadica, mientras<br>realizan un Cineminuto y experimentan las 3 etapas de la realizaci\u00f3n: la<br>preproducci\u00f3n, producci\u00f3n y postproducci\u00f3n.<\/p>\n\n\n\n<p>En el Recinto Aurora Morales de L\u00f3pez ser\u00e1n las clases que iniciar\u00e1n el 13 de enero<br>de 2025 los lunes y viernes de 7 a 8 pm en el Centro Hist\u00f3rico de Saltillo, en la calle<br>de Ramos Arizpe #229 antes de llegar a la calle de Allende; la inscripci\u00f3n es de $350<br>pesos y mensualidades de $600 para alumnos\/trabajadores UAdeC y $800 para<br>externos, informes al tel\u00e9fono del Recinto 844 410 32 03 o en el WhatsApp 844 481<br>88 88.<\/p>\n\n\n\n<p>El Taller de Cortometraje ser\u00e1 impartido por el Licenciado en Producci\u00f3n<br>Cinematogr\u00e1fica Fernando Recio Valadez, egresado de Epic Film Institute, quien<br>tambi\u00e9n tiene capacitaci\u00f3n de Lenguaje y Producci\u00f3n Audiovisual por la Facultad de<br>Artes Visuales de la Universidad Aut\u00f3noma de Nuevo Le\u00f3n.<\/p>\n\n\n\n<p>Adem\u00e1s, cuenta con estudios sobre guion, audio, dise\u00f1o de producci\u00f3n, fotograf\u00eda,<br>direcci\u00f3n y edici\u00f3n a trav\u00e9s de talleres impartidos por el Instituto Mexicano de<br>Cinematograf\u00eda IMCINE, y por Talleres de la Muestra de Cine Coahuila; Diplomado<br>en Producci\u00f3n para la Carpeta de EFICINE; Guion Cinematogr\u00e1fico por Panda<br>Grosero Films, y con Besani Producciones \u201cC\u00f3mo hacer un casting para cine\u201d.<\/p>\n\n\n\n<p>Fue Galardonado este a\u00f1o con la Presea Drag\u00f3n al M\u00e9rito Cultural por su<br>participaci\u00f3n en m\u00e1s de 20 cortometrajes, comerciales, documentales y videoclips;<br>fungi\u00f3 como Segundo Asistente de c\u00e1mara de la pel\u00edcula \u201cEl Desaire\u201d, fue ganador<br>de la Convocatoria \u201cArte para Valorarte\u201d de la Secretar\u00eda de Salud de Coahuila y de<br>la Comisi\u00f3n Nacional Fronteriza Coahuila-Estados Unidos.<\/p>\n\n\n\n<p>Para ello, escribi\u00f3 y dirigi\u00f3 el mediometraje \u201c\u00bfPor qu\u00e9 est\u00e1s aqu\u00ed?\u201d, que se proyecta<br>en diversas ciudades de Coahuila y del pa\u00eds para la prevenci\u00f3n del suicidio dirigido a<br>alumnos de secundaria, preparatoria y profesional; obtuvo el Premio Estatal de<br>Periodismo Cultural \u201cArmando Fuentes Aguirre\u201d de la Universidad Aut\u00f3noma de<br>Coahuila en la categor\u00eda infantil.<\/p>\n\n\n\n<p>Es actor y miembro fundador del Club de Artes Esc\u00e9nicas de la UCA, ha cursado<br>talleres de actuaci\u00f3n con los actores mexicanos Dar\u00edo Ripoll y Julio Bracho, y ha<\/p>\n\n\n\n<p>protagonizado diversas puestas en escena de teatro y cortometrajes como \u201cAadi\u201d<br>que ha sido seleccionados en diversos festivales de cine a nivel internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 18 de diciembre de 2024. Como parte del compromiso deinnovaci\u00f3n y pertinencia en la oferta educativa, la Universidad Aut\u00f3noma deCoahuila, a trav\u00e9s de la Coordinaci\u00f3n de Difusi\u00f3n y Patrimonio Cultural y del RecintoUniversitario \u201cAurora Morales de L\u00f3pez\u201d, ofrecer\u00e1 por primera vez el Taller deCortometraje en el periodo enero-junio 2025. Este programa acad\u00e9mico est\u00e1 dirigido a la comunidad universitaria y p\u00fablico engeneral, y tiene como objetivo que los j\u00f3venes&#8230;<\/p>\n","protected":false},"author":1,"featured_media":23940,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-23939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=23939"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23939\/revisions"}],"predecessor-version":[{"id":23941,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23939\/revisions\/23941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/23940"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=23939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=23939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=23939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}