{"id":23970,"date":"2024-12-22T20:31:16","date_gmt":"2024-12-23T02:31:16","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=23970"},"modified":"2024-12-22T20:31:16","modified_gmt":"2024-12-23T02:31:16","slug":"aqui-laguna-374","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/12\/22\/aqui-laguna-374\/","title":{"rendered":"Aqu\u00ed Laguna."},"content":{"rendered":"\n<p>En el umbral \u00a0 de la Navidad, con una mayor\u00eda de\u00a0 humanos dispuestos\u00a0 a abrir un comp\u00e1s en\u00a0 sus vidas, de que\u00a0 este\u00a0 breve\u00a0 lapso del tiempo que\u00a0 Dios nos deja alcanzar y vivir,\u00a0 sirva a todos para encontrar \u00a0 la\u00a0 paz del alma, dejando atr\u00e1s odios, envidias\u00a0 y resentimientos\u00a0 gestados con razones o sin ellas,\u00a0 en el pasado. Y en tanto\u00a0 en otra expresi\u00f3n \u00a0 del tiempo que hoy vivimos tambi\u00e9n, la mayor\u00eda de la poblaci\u00f3n se dispone a festejarlo, siendo casi siempre los menores, ajenos a los rigores de la realidad quienes mejor lo disfrutan, no la mayor\u00eda digo, como fuera deseable pues ser\u00e1n muchos los menores tambi\u00e9n que \u00a0 desprotegidos de afectos y bienes vean con pena el arribo y t\u00e9rmino de los tiempos citados, no por ello\u00a0por\u00a0 las m\u00e1s diversas razones, olvidados o desprotegidos\u00a0 en sus vidas,\u00a0 bien a trav\u00e9s de sus agrupaciones\u00a0 o de\u00a0 manera personal,\u00a0 las que se suman las realizadas a cargo de los organismos gubernamentales, asociaciones de orden privado, algunos de\u00a0 origen\u00a0 religioso \u00a0 o bien sujetos\u00a0 con aspiraciones pol\u00edticas en campa\u00f1a, en las que todos juntos, resultan\u00a0 no ser aun suficientes\u00a0 para cubrir\u00a0 tan basta\u00a0 y creciente\u00a0 poblaci\u00f3n que\u00a0 demanda\u00a0 su atenci\u00f3n\u00a0 y cuidados que merecen tales vidas.<\/p>\n\n\n\n<p>Tiempo de hacer cuentas, reflexionar\u00a0 sobre el\u00a0 arribo de un nuevo a\u00f1o,\u00a0 en el fluir eterno del tiempo\u00a0 en los que navegan nuestras vidas, analizar, preveer en lo posible\u00a0 el como sortear \u00a0 los escollos que dicen se avizoran \u00a0 en la\u00a0 realidad mundial y con ella la de nuestro pa\u00eds, en especial, los que est\u00e1n ligados al arribo\u00a0 dicen, del pr\u00f3ximo y vociferante nuevo\u00a0 presidente de Estados Unidos, Donald Trump \u00a0 y con ello no solo el calificar de terroristas a los c\u00e1rteles de la droga, y el trato que dice \u00a0 estar\u00e1 aplic\u00e1ndoles, amen de los anunciados aranceles en el \u00e1mbito de la econom\u00eda,\u00a0 pues con todo y lo extremo\u00a0 que esto represente, queda aun otro de mayores impactos, es decir,\u00a0 el que corresponde al de la inmigraci\u00f3n, en el que anticipa\u00a0 la expulsi\u00f3n de los migrantes y un muro impenetrable para los que aspiren a ello en la frontera sur de EUA.\u00a0 <\/p>\n\n\n\n<p>Y ya vemos que por precauci\u00f3n, solo por eso,\u00a0 Claudia Sheinbaum ya se puso las pilas y anuncia la creaci\u00f3n de 25 albergues para dar cobijo a tal marea humana, en alguna de las ciudades mexicanas ubicadas\u00a0 en alguno de sus 3,000 kil\u00f3metros de frontera\u00a0 y de la\u00a0 cual Coahuila forma parte y que\u00a0 no se dude algunas de\u00a0 tales ciudades\u00a0 acabar\u00e1n\u00a0 constituy\u00e9ndose como ciudades santuarios. Dios nos agarre confesados y a las autoridades mexicanas tambi\u00e9n, pues el tema ser\u00e1 una presi\u00f3n\u00a0 contante e ineludible en t\u00e9rminos humanitarios, no por el solo impactar\u00e1n en\u00a0 la econom\u00eda de la regi\u00f3n, en el tema de seguridad y delincuencia\u00a0 y tambi\u00e9n del\u00a0 sanitario.<\/p>\n\n\n\n<p>Y en tanto en Torre\u00f3n, rumores y m\u00e1s rumores, y que seg\u00fan sea su fuente de emisiones, cargados de insidia y mala f\u00e9 en torno a los motivos de la prolongada ausencia del alcalde Rom\u00e1n Alberto Cepeda Gonzalez en tan significativos tiempos de \u00a0 la escena pol\u00edtica que le corresponde por ley, presidir\u00a0 y en los que algunos dice que el ahora alcalde reelecto &#8220;ha perdido&#8221; no solo la salud pol\u00edtica, sino tambi\u00e9n la f\u00edsica, personal, pues\u00a0 ha ingresado por dos ocasiones en ocho d\u00edas, al\u00a0 sanatorio m\u00e9dico m\u00e1s importante de la ciudad, si bien no se atreven a\u00a0 informar, como debe de ser su amplia y costosa \u00e1rea de \u00a0 Comunicaci\u00f3n Social\u00a0 y Relaciones P\u00fablicas\u00a0 de\u00a0 tal ausencia y mucho menos, pero mucho menos\u00a0 Jorge Luis Cuerda Serna\u00a0 aun primer regidor del cabildo en funciones, y miembro \u00a0 de la siguiente, pues ya se sabe, es peque\u00f1o para todo, y mucho m\u00e1s\u00a0 para\u00a0 presidir las acciones de gobierno que \u00a0 con todo y la aton\u00eda que registran las actividades p\u00fablicas deben cubrirse. <\/p>\n\n\n\n<p>Por cierto en estas destaca la obligada Sesi\u00f3n de Cabildo, que no deber\u00e1 ser por zoom, como est\u00e1n acostumbrados en las ultimas\u00a0 realizadas, de manera virtual con todo y la importancia que algunos temas revisten,\u00a0 haciendo suponer que la batuta qued\u00f3 a manos de la actual Secretaria del Ayuntamiento\u00a0 Natalia Fern\u00e1ndez es la relacionada con volver a dar posesi\u00f3n de su cargo como segunda regidora a Olga X\u00f3chitl Cepeda, a quien el Tribunal Electoral del Poder Judicial de la Federaci\u00f3n le revoc\u00f3 la suspensi\u00f3n del cargo que le dictara el Congreso del Estado de suspenderla en tales funciones debido a que se encuentra sujeta a un proceso penal por su participaci\u00f3n en un incidente menor \u00a0 en la que en compa\u00f1\u00eda de su padre, el regidor\u00a0 electo Mario Cepeda Ram\u00edrez,\u00a0 le\u00a0 infringieran\u00a0&#8220;lesiones\u00a0 lev\u00edsimas&#8221; a\u00a0 Silvia Villarreal,\u00a0 entonces y aun\u00a0 funcionaria de\u00a0 muy\u00a0 sensible piel, y quien \u00a0 se desempe\u00f1aba all\u00e1 por\u00a0 agosto del 2022\u00a0 las\u00a0 important\u00edsimas funciones de &#8220;acomoda sillas&#8221; en el \u00e1rea de Relaciones P\u00fablicas\u00a0 de\u00a0 la pasada \u00a0 administraci\u00f3n estatal.<\/p>\n\n\n\n<p>Silvia Villarreal, es por cierto, &#8220;sobrina pol\u00edtica&#8221; de\u00a0 su \u00a0 hoy,\u00a0 defenestrado \u00a0 y controversial\u00a0 t\u00edo, regidor \u00a0 por cuyo motivo hoy tiene\u00a0 sobre su cabeza, cual Espada de Dam\u00f3cles el fallo que a su favor o en contra\u00a0 emitan autoridades\u00a0 para que pueda o no, tomar posesi\u00f3n del cargo como\u00a0 regidor \u00a0 integrante del pr\u00f3ximo cabildo de Torre\u00f3n el\u00a0 pr\u00f3ximo 1 de\u00a0 enero\u00a0 del 2025, decisi\u00f3n importante, pues\u00a0 el citado alcanza ya sus\u00a0 casi 80 a\u00f1os de vida y como que ya no anda para \u00a0 encarar tales trotes. <\/p>\n\n\n\n<p>Por cierto, se comenta que\u00a0 la se\u00f1ora X\u00f3chitl Cepeda, con todo y la suspensi\u00f3n\u00a0 que registr\u00f3 su funci\u00f3n como regidora no dej\u00f3 de percibir por ello ni\u00a0 dietas, ni aguinaldo,\u00a0 pues entre los elementos a\u00a0 su favor esgrimi\u00f3 ante juzgadora\u00a0 no contar con otros ingresos propios que los que devengara como representante popular, si bien\u00a0 a su favor cuenta\u00a0 con los invaluables servicios profesionales\u00a0 del\u00a0 controversial litigante\u00a0 Omar\u00a0Pulido. <\/p>\n\n\n\n<p>Esperemos\u00a0 que\u00a0 para su bien y la del municipio, su alcalde Cepeda Gonz\u00e1lez, recobre siquiera la salud f\u00edsica que ahora tiene dicen, afectada y que la salud pol\u00edtica \u00a0 tambien, \u00a0 cuando en puerta tiene el\u00a0 inicio de una nueva gesti\u00f3n que generosamente la ciudadan\u00eda le otorg\u00f3 con su voto y en la que debe\u00a0 concluir \u00a0 no solo con nuevas metas, sino con las que se le quedaron\u00a0 en calidad de pendientes y que son varios que \u00a0 hoy son eso, meros pryectos en la que hoy esta por concluir. Dicen que estar\u00e1 sorprendiendo a los torreonenses con el reclutamiento de nuevas caras \u00a0 para desempe\u00f1ar \u00a0 en los principales cargos, y otras no lo ser\u00e1n tanto, pues se menciona con el ahora\u00a0&#8220;bendito&#8221;\u00a0 Pepe Ganem\u00a0 luego de su\u00a0 reciente visita al Vaticano acompa\u00f1ando a su matachina mayor, la Licenciada Martha Rodr\u00edguez, dicen que la cercan\u00eda alcanzada por el ex regidor en la administraci\u00f3n del licenciado Olmos Castro arrastrar\u00e1\u00a0a su consentido \u00a0 Adelaido Flores\u00a0 al favor del edil,\u00a0 no descarando, aunque parezca imposible que acceda al cargo de titular de la Direcci\u00f3n P\u00fablica Municipal con quien hiciera en otros tiempos aciagos, singular mancuerna. \u00a0 <\/p>\n\n\n\n<p>Y aunque faltan algunos d\u00edas para llegar al 28 de diciembre, se rumorea que el Ingeniero Lauro Villarreal, est\u00e1 m\u00e1s que puesto para dejar el CEAS y regresar al cargo de titular del Sistema Municipal de Aguas y Saneamiento de\u00a0 Torre\u00f3n, por ahora en manos de recomendados regiomontanos, en su Direcci\u00f3n y \u00e1rea t\u00e9cnica, los cuales, no muestran ni inter\u00e9s\u00a0 o af\u00e1n alguno por mostrar los n\u00fameros\u00a0 a la ciudadania, pues nadan de muertito\u00a0al igual que lo registra la singular administraci\u00f3n de la m\u00e1s importante, por no decir unica paramunicipal de Torre\u00f3n.<\/p>\n\n\n\n<p>Y\u00a0 por hoy solo resta sumarnos a contar todos, con unos d\u00edas de\u00a0 paz en compa\u00f1ia de nuestros\u00a0 amigos y seres queridos \u00a1Feliz\u00a0 Navidad!\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el umbral \u00a0 de la Navidad, con una mayor\u00eda de\u00a0 humanos dispuestos\u00a0 a abrir un comp\u00e1s en\u00a0 sus vidas, de que\u00a0 este\u00a0 breve\u00a0 lapso del tiempo que\u00a0 Dios nos deja alcanzar y vivir,\u00a0 sirva a todos para encontrar \u00a0 la\u00a0 paz del alma, dejando atr\u00e1s odios, envidias\u00a0 y resentimientos\u00a0 gestados con razones o sin ellas,\u00a0 en el pasado. Y en tanto\u00a0 en otra expresi\u00f3n \u00a0 del tiempo que hoy&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-23970","post","type-post","status-publish","format-standard","hentry","category-aqui-laguna","wpcat-8-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=23970"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23970\/revisions"}],"predecessor-version":[{"id":23971,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23970\/revisions\/23971"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=23970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=23970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=23970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}