{"id":25307,"date":"2025-03-25T17:52:48","date_gmt":"2025-03-25T23:52:48","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=25307"},"modified":"2025-03-25T17:52:48","modified_gmt":"2025-03-25T23:52:48","slug":"firman-hospital-universitario-de-la-uadec-y-club-rotario-de-saltillo-convenio-de-colaboracion-y-asistencia-social","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2025\/03\/25\/firman-hospital-universitario-de-la-uadec-y-club-rotario-de-saltillo-convenio-de-colaboracion-y-asistencia-social\/","title":{"rendered":"Firman Hospital Universitario de la UAdeC y Club Rotario de Saltillo Convenio de Colaboraci\u00f3n y Asistencia Social."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 25 de marzo de 2025. En un esfuerzo por fortalecer la<br>colaboraci\u00f3n y asistencia social en beneficio de la sociedad coahuilense el Hospital<br>Universitario de Saltillo (HUS) &#8220;Dr. Gonzalo Vald\u00e9s Vald\u00e9s&#8221; de la Universidad<br>Aut\u00f3noma de Coahuila, la instituci\u00f3n firm\u00f3 un Convenio con el Club Rotario de<br>Saltillo A.C.<\/p>\n\n\n\n<p>El acuerdo establece las bases de cooperaci\u00f3n mediante las cuales el Club Rotario<br>entregar\u00e1 directamente aparatos ortop\u00e9dicos a las personas que lo necesiten y que<br>sean previamente seleccionados por el Hospital Universitario, garantizando que la<br>asistencia llegue a quienes m\u00e1s lo necesitan; asimismo, ambas partes se<br>comprometen a mantener una comunicaci\u00f3n constante y transparente para fortalecer<br>el impacto de este apoyo.<\/p>\n\n\n\n<p>El documento fue signado en el Aula Magna \u201cCarlos Avil\u00e9s Falco\u201d del Hospital<br>Universitario por el rector de la UAdeC, Octavio Pimentel Mart\u00ednez y el presidente del<br>Club Rotario de Saltillo, Horacio Villarreal M\u00e1rquez, acompa\u00f1ados por la<br>coordinadora de Unidad Sureste, Eva Kerena Hern\u00e1ndez, la coordinadora de<br>Vinculaci\u00f3n e Innovaci\u00f3n Productiva, Karla Patricia Vald\u00e9s Garc\u00eda.<\/p>\n\n\n\n<p>Adem\u00e1s, por el director del Hospital Universitario, Jos\u00e9 Lauro Cort\u00e9s Hern\u00e1ndez; el<br>representante legal del Club Rotario, Jes\u00fas G\u00f3mez Moreno; la presidenta de la<br>Fundaci\u00f3n del Empresariado Coahuilense A.C., Luc\u00eda Garza Guerra, as\u00ed como<br>funcionariado universitario y personal de ambas instituciones.<\/p>\n\n\n\n<p>En su mensaje de bienvenida, el director del HU, Jos\u00e9 Lauro Cort\u00e9s, celebr\u00f3 la larga<br>trayectoria de colaboraci\u00f3n entre el Club Rotario de Saltillo A.C. y la Universidad<br>Aut\u00f3noma de Coahuila, al se\u00f1alar que esta alianza ha generado importantes frutos a<br>lo largo de los a\u00f1os.<\/p>\n\n\n\n<p>Record\u00f3 la labor del Dr. Miguel \u00c1ngel Talam\u00e1s Dieck, exdirector del Hospital<br>Universitario y miembro distinguido del Club Rotario, quien impuls\u00f3 con pasi\u00f3n esta<br>cooperaci\u00f3n, al tiempo que agradeci\u00f3 y reconoci\u00f3 el legado de quienes han<br>contribuido al fortalecimiento de esta relaci\u00f3n.<\/p>\n\n\n\n<p>Por su parte, el rector\u00a0Octavio Pimentel Mart\u00ednez, destac\u00f3 la importancia de la<br>colaboraci\u00f3n entre universidades, gobierno, sector privado y sociedad civil para<br>impulsar proyectos en beneficio de la comunidad, al tiempo que celebr\u00f3 el centenario<br>del Club Rotario de Saltillo A.C.<\/p>\n\n\n\n<p>Enfatiz\u00f3 que el convenio firmado deber\u00e1 traducirse en acciones concretas que<br>fortalezcan el bienestar social, en especial a trav\u00e9s del apoyo al Hospital<br>Universitario, al que consider\u00f3 un referente en salud en la regi\u00f3n.<\/p>\n\n\n\n<p>Asimismo, reiter\u00f3 el compromiso de la UAdeC de trabajar en unidad con distintas<br>instituciones para generar un impacto positivo en el desarrollo del estado, siempre<br>con la misi\u00f3n de servir a la comunidad universitaria y a la sociedad en general.<\/p>\n\n\n\n<p>En su intervenci\u00f3n, el presidente del Club Rotario de Saltillo, Horacio Villarreal<br>M\u00e1rquez reconoci\u00f3 la estrecha relaci\u00f3n que su organizaci\u00f3n ha mantenido con la<br>Universidad Aut\u00f3noma de Coahuila a lo largo de los a\u00f1os, por lo que se\u00f1al\u00f3 que la<br>firma del convenio es un acto protocolario pues ambas instituciones han trabajado<br>juntas durante largo tiempo.<\/p>\n\n\n\n<p>Mencion\u00f3 en particular el Programa de aparatos ortop\u00e9dicos, instituido hace siete<br>a\u00f1os en la Asociaci\u00f3n y, el cual ha operado en coordinaci\u00f3n con el Hospital<br>Universitario y la Facultad de de Trabajo Social de la UAdeC; por lo que reiter\u00f3 el<br>compromiso del Club Rotario con la comunidad y con la Universidad.<\/p>\n\n\n\n<p>Durante el evento, las autoridades hicieron entrega de una silla de ruedas infantil al<br>ni\u00f1o Dimas Tadeo Salas, paciente del Hospital Universitario, y al hospital otros<br>aparatos ortop\u00e9dicos como una andadera con silla, una silla de ruedas PCI especial<br>para personas con par\u00e1lisis cerebral y una silla de ruedas todo terreno para adulto;<br>por parte del Club Rotario entregaron un reconocimiento a la UAdeC en<br>agradecimiento por su labor y colaboraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 25 de marzo de 2025. En un esfuerzo por fortalecer lacolaboraci\u00f3n y asistencia social en beneficio de la sociedad coahuilense el HospitalUniversitario de Saltillo (HUS) &#8220;Dr. Gonzalo Vald\u00e9s Vald\u00e9s&#8221; de la UniversidadAut\u00f3noma de Coahuila, la instituci\u00f3n firm\u00f3 un Convenio con el Club Rotario deSaltillo A.C. El acuerdo establece las bases de cooperaci\u00f3n mediante las cuales el Club Rotarioentregar\u00e1 directamente aparatos ortop\u00e9dicos a las personas que lo necesiten y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":25308,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/25307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=25307"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/25307\/revisions"}],"predecessor-version":[{"id":25309,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/25307\/revisions\/25309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/25308"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=25307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=25307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=25307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}