{"id":25471,"date":"2025-04-04T17:32:14","date_gmt":"2025-04-04T23:32:14","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=25471"},"modified":"2025-04-04T17:32:14","modified_gmt":"2025-04-04T23:32:14","slug":"presentan-en-la-uadec-los-avances-del-proyecto-de-acreditacion-de-programas-educativos","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2025\/04\/04\/presentan-en-la-uadec-los-avances-del-proyecto-de-acreditacion-de-programas-educativos\/","title":{"rendered":"Presentan en la UAdeC los Avances del Proyecto de Acreditaci\u00f3n de Programas Educativos."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 4 de abril de 2025. El rector de la Universidad Aut\u00f3noma de<br>Coahuila, Octavio Pimentel Mart\u00ednez y el director de Planeaci\u00f3n, Jes\u00fas Alberto<br>Montalvo Morales, presentaron los avances del Proyecto de Acreditaci\u00f3n de<br>Programas Educativos, el cual forma parte del Plan de Desarrollo Institucional 2024-<br>2027, aprobado por el H. Consejo Universitario, en donde se estableci\u00f3 el reto de<br>lograr que la mayor cantidad de matr\u00edcula de la instituci\u00f3n se encuentre inscrita en<br>programas educativos reconocidos por su calidad.<\/p>\n\n\n\n<p>Se\u00f1alaron que se ten\u00edan 97 programas educativos de licenciatura, 78 acreditables,<br>20 acreditados y 58 no acreditados, por lo cual se pretende acreditar al 77 por ciento<br>de la matr\u00edcula, es decir que 19 mil 228 estudiantes tengan la certeza, de que sus<br>programas educativos de las carreras que estudian son certificados por su calidad.<br>Para estos resultados y acreditar 30 programas educativos de las Escuelas y<br>Facultades de las Unidades Saltillo, Torre\u00f3n y Norte de la Universidad, el 30 de<br>agosto de 2024 se present\u00f3 a trav\u00e9s de la Direcci\u00f3n de Planeaci\u00f3n, el Marco<br>General de Evaluaci\u00f3n 2024 desarrollado por los Comit\u00e9s Interinstitucionales para la<br>Evaluaci\u00f3n de la Educaci\u00f3n Superior (CIEES).<\/p>\n\n\n\n<p>Mientras que, el 20 de septiembre de 2024 se anunci\u00f3 el inicio de la acreditaci\u00f3n de<br>nueve programas educativos que tienen enfoque en la ense\u00f1anza de la contadur\u00eda y<br>administraci\u00f3n, esto a trav\u00e9s del Consejo de Acreditaci\u00f3n en Ciencias<br>Administrativas, Contables y Afines (CACECA).<\/p>\n\n\n\n<p>Para este proyecto se invierte en 30 programas educativos con CIEES<br>$2,412,000.00 pesos y 9 programas educativos con CACECA con una cifra de<br>$1,672,363.80, danto un total de $4,084,363.80 pesos.<\/p>\n\n\n\n<p>Se acudi\u00f3 a cada unidad regional y se invit\u00f3 a que las y los directores de cada<br>programa educativo participaran en esta estrategia de acreditaci\u00f3n, el 25 de<br>septiembre de 2024 en Unidad Sureste, el 26 de septiembre en Unidad Norte y el 27<br>de septiembre en Unidad Laguna.<\/p>\n\n\n\n<p>La matr\u00edcula a acreditar en Unidad sureste es de 4 mil 593, de Unidad Laguna 6 mil<br>957 y de Unidad Norte mil 698, dando un total de matr\u00edcula a acreditar de 39<br>programas educativos es de 13 mil 248.<\/p>\n\n\n\n<p><br>Para articular el proceso de acreditaci\u00f3n se conformaron comit\u00e9s, la capacitaci\u00f3n de<br>estos y tiempos de trabajo, para la capacitaci\u00f3n de CIEES se llev\u00f3 a cabo el Taller de<br>Capacitaci\u00f3n para la Planeaci\u00f3n y Desarrollo de la Autoevaluaci\u00f3n de Programas<br>Educativos de Tipo Superior el 19, 20, 21 y 22 de noviembre de 2024 a trav\u00e9s de la<br>plataforma Zoom con los siguientes temas: Marco general de evaluaci\u00f3n de los<\/p>\n\n\n\n<p>CIEES, Manual de Procedimientos de Visita de Evaluaci\u00f3n, Lineamientos para<br>otorgar las Vigencias de Acreditaci\u00f3n, Tiempos del proceso, Criterios orientadores y<br>Llenado de la Gu\u00eda para la Autoevaluaci\u00f3n de Programas de Educaci\u00f3n Superior<br>(GAPES).<\/p>\n\n\n\n<p>Mientras que, para el proceso de capacitaci\u00f3n de CACECA se llev\u00f3 a cabo la<br>Capacitaci\u00f3n del Instrumento de Evaluaci\u00f3n CACECA el 2,3 y 4 de diciembre de<br>2024 por Google Meet, con el temario: Ficha t\u00e9cnica, Llenado del Instrumento<br>Did\u00e1ctico de Evaluaci\u00f3n del CACECA, Ejercicios de Pr\u00e1ctica de cada una de las<br>categor\u00edas, Ejercicios de C\u00e1lculo, Llenado de la plataforma y Reporte de<br>autoevaluaci\u00f3n y visita de campo.<\/p>\n\n\n\n<p>Despu\u00e9s del 4 de diciembre de 2024 quedaron conformados los comit\u00e9s ya<br>capacitados y con conocimiento total del proceso de acreditaci\u00f3n; se llev\u00f3 a cabo la<br>exposici\u00f3n del Plan de Trabajo para el Proceso de Acreditaci\u00f3n, el 20 de enero de<br>2025 del CIEES y el 28 de enero de 2025 de CACECA, entre los meses de enero a<br>abril se realizan las entregas y revisiones a la Direcci\u00f3n de Planeaci\u00f3n por parte de<br>los Programas Educativos.<\/p>\n\n\n\n<p>El instrumento de evaluaci\u00f3n para CIEES es en los ejes Fundamento y Dise\u00f1o,<br>(contexto y prop\u00f3sito y condiciones generales para su operaci\u00f3n); Estrategia de<br>Formaci\u00f3n (plan de estudios y trayectoria de Formaci\u00f3n); Gesti\u00f3n de la Formaci\u00f3n<br>(personal acad\u00e9mico, infraestructura acad\u00e9mica y servicio de apoyo); Resultados del<br>Programa Educativo (resultados del aprendizaje de los estudiantes egresados).<\/p>\n\n\n\n<p>El instrumento de evaluaci\u00f3n de CACECA es en las siguientes categor\u00edas: Personal<br>acad\u00e9mico, Estudiantes, Plan de Estudios, Evaluaci\u00f3n de Aprendizaje, Formaci\u00f3n<br>Integral, Servicio de Apoyo para el Aprendizaje, Vinculaci\u00f3n-Extensi\u00f3n, Investigaci\u00f3n,<br>Infraestructura y Equipamiento, Gesti\u00f3n Administrativa y Financiamiento.<\/p>\n\n\n\n<p>Los siguientes pasos a seguir son que la Direcci\u00f3n de Planeaci\u00f3n llene la Plataforma<br>de todos los Programas Educativos, enviar instrumento a CIEES o CACECA,<br>programar visitas de pares evaluadores y el objetivo final es acreditar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 4 de abril de 2025. El rector de la Universidad Aut\u00f3noma deCoahuila, Octavio Pimentel Mart\u00ednez y el director de Planeaci\u00f3n, Jes\u00fas AlbertoMontalvo Morales, presentaron los avances del Proyecto de Acreditaci\u00f3n deProgramas Educativos, el cual forma parte del Plan de Desarrollo Institucional 2024-2027, aprobado por el H. Consejo Universitario, en donde se estableci\u00f3 el reto delograr que la mayor cantidad de matr\u00edcula de la instituci\u00f3n se encuentre inscrita enprogramas&#8230;<\/p>\n","protected":false},"author":1,"featured_media":25472,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/25471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=25471"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/25471\/revisions"}],"predecessor-version":[{"id":25473,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/25471\/revisions\/25473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/25472"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=25471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=25471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=25471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}