{"id":25814,"date":"2025-04-29T20:20:45","date_gmt":"2025-04-30T02:20:45","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=25814"},"modified":"2025-04-29T20:20:45","modified_gmt":"2025-04-30T02:20:45","slug":"roman-alberto-cepeda-gonzalez-presenta-el-plan-municipal-de-desarrollo-2025-2027","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2025\/04\/29\/roman-alberto-cepeda-gonzalez-presenta-el-plan-municipal-de-desarrollo-2025-2027\/","title":{"rendered":"Rom\u00e1n Alberto Cepeda Gonz\u00e1lez presenta el Plan Municipal de Desarrollo 2025-2027."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 29 de abril de 2025.<\/p>\n\n\n\n<p>Este martes, el alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez present\u00f3 el Plan<br>Municipal de Desarrollo para la Administraci\u00f3n 2025-2027, compuesto por los<br>cinco ejes tem\u00e1ticos de su Gobierno: Seguridad y Orden, Infraestructura y<br>Servicios de Calidad, Participaci\u00f3n y Buen Gobierno, Fortalecimiento Econ\u00f3mico,<br>y Unidad y Desarrollo Humano, de los cuales se derivan m\u00e1s de 500 programas<br>en beneficio de los y las torreonenses.<\/p>\n\n\n\n<p>En su mensaje, el Presidente Municipal se\u00f1al\u00f3 que el Plan Municipal de<br>Desarrollo, m\u00e1s que un documento, es una gu\u00eda clara, precisa y visionaria que<br>marca el rumbo hacia el progreso sostenido, y est\u00e1 alineado al Plan Nacional al<br>Plan Estatal de Desarrollo.<\/p>\n\n\n\n<p>\u201cEn mi toma de protesta refrend\u00e9 mi compromiso con todos y cada uno de<br>ustedes, hoy, una vez m\u00e1s lo ratifico con la presentaci\u00f3n de un plan dise\u00f1ado<br>directamente por y para la ciudadan\u00eda, que responde efectivamente a lo que<br>nuestra ciudad demanda, con la integraci\u00f3n de los ejes prioritarios para el<br>bienestar social, para la seguridad, la econom\u00eda y con visi\u00f3n a futuro\u201d, dijo.<\/p>\n\n\n\n<p>Asimismo, el edil destac\u00f3 la coordinaci\u00f3n con el gobernador de Coahuila, Manolo<br>Jim\u00e9nez Salinas, para seguir trabajando en la construcci\u00f3n de un mejor Torre\u00f3n.<\/p>\n\n\n\n<p>Cepeda Gonz\u00e1lez dijo que durante la Administraci\u00f3n 22- 24 se propusieron obras<br>estrat\u00e9gicas como Casa Nana, el Giro Independencia, el Sistema Vial Cuatro<br>Caminos, Paso Villa Florida, el nuevo Centro de Justicia, y el corredor Matamoros,<br>entre muchas otras, que no son s\u00f3lo infraestructura sino s\u00edmbolos del compromiso<br>con Torre\u00f3n.<\/p>\n\n\n\n<p>Sin embargo, dijo que en la actual Administraci\u00f3n, Torre\u00f3n va por m\u00e1s desarrollo,<br>m\u00e1s seguridad y m\u00e1s oportunidades. \u201cNuestro objetivo es seguir impulsando<br>grandes proyectos estrat\u00e9gicos de la mano del Gobierno Estatal y Federal,<br>fortaleciendo la infraestructura, la seguridad, la econom\u00eda y el desarrollo social.<\/p>\n\n\n\n<p>Porque estamos seguros de que juntos podemos alcanzar cualquier meta\u201d.<br>En ese sentido, detall\u00f3 que el Plan Municipal de Desarrollo se divide en cinco ejes<br>con m\u00e1s de 500 programas espec\u00edficos, y destac\u00f3 que fue creado gracias a la<br>participaci\u00f3n de m\u00e1s de 5 mil ciudadanos que se expresaron su confianza a trav\u00e9s<\/p>\n\n\n\n<p>de las mesas de trabajo y encuestas en l\u00ednea, adem\u00e1s de las peticiones recibidas<br>durante recorridos.<\/p>\n\n\n\n<p>Dijo que el primero de los ejes es y seguir\u00e1 siendo la Seguridad, por lo que habr\u00e1<br>de seguir impulsando una seguridad p\u00fablica y seguridad vial m\u00e1s cercana,<br>humana y eficiente, dando continuidad a la profesionalizaci\u00f3n de la polic\u00eda, a su<br>dignificaci\u00f3n y equipamiento, siempre con un enfoque en derechos humanos.<br>\u201cFortaleceremos las estrategias de inteligencia, la prevenci\u00f3n y la capacitaci\u00f3n<br>continua, para proteger la integridad y el patrimonio de las familias torreonenses\u201d.<\/p>\n\n\n\n<p>Del segundo eje, Infraestructura y Servicios de Calidad, se\u00f1al\u00f3 que el objetivo<br>es continuar modernizando y optimizando la movilidad urbana.<\/p>\n\n\n\n<p>En cuanto a la Participaci\u00f3n y Buen Gobierno, el Alcalde manifest\u00f3 que<br>seguir\u00e1 consolidando una administraci\u00f3n moderna, eficiente y transparente, con la<br>digitalizaci\u00f3n de tr\u00e1mites, y en la construcci\u00f3n de un gobierno cada vez m\u00e1s<br>cercano, accesible y confiable.<\/p>\n\n\n\n<p>Sobre el cuarto eje, Fortalecimiento Econ\u00f3mico, dijo que habr\u00e1 de impulsar<br>con m\u00e1s fuerza la atracci\u00f3n de inversiones, nacionales e internacionales.<br>\u201cFomentaremos el empleo, la innovaci\u00f3n y la competitividad empresarial,<br>apoyando a nuestros emprendedores y negocios locales. As\u00ed como los servicios<br>tur\u00edsticos y posicionaremos a Torre\u00f3n como un referente econ\u00f3mico a nivel<br>regional y global\u201d.<\/p>\n\n\n\n<p>Respecto al eje de Unidad y Desarrollo Humano, el edil coment\u00f3 que seguir\u00e1<br>promoviendo un desarrollo social incluyente, equitativo y sostenible, con pol\u00edticas<br>que favorezcan la calidad de vida, la cohesi\u00f3n familiar y el fortalecimiento del<br>tejido social.<\/p>\n\n\n\n<p>El Presidente Municipal dijo que ya se est\u00e1 trabajando y logrando los primeros<br>resultados, con programas como el de \u201cEl alcalde y su equipo en tu colonia<br>hacemos m\u00e1s\u201d, y \u201cM\u00e1s de 100 Plazas de 0 a 100\u201d, los cuales ya iniciaron.<\/p>\n\n\n\n<p>Adem\u00e1s, Cepeda Gonz\u00e1lez anunci\u00f3 obras claves en materia de movilidad como la<br>soluci\u00f3n vial Diana Laura; el Bulevar Torre\u00f3n 2000 y el Bulevar Torre\u00f3n Norte, as\u00ed<br>como la siguiente etapa del Paso Villa Florida.<\/p>\n\n\n\n<p>\u201cTambi\u00e9n, coordinados con el Gobierno del Estado iniciaremos la construcci\u00f3n del<br>Paso a desnivel Independencia-Abastos, con lo que mejoraremos vialidades,<br>reduciremos tiempos de traslado y haremos m\u00e1s seguros los trayectos\u201d, dijo.<\/p>\n\n\n\n<p>Anunci\u00f3 tambi\u00e9n proyectos en puerta como el Parque Lineal Oriente y el Parque<br>Lineal Zaragoza; el programa de abastecimiento de agua, donde destac\u00f3 que se<br>contar\u00e1 con una nueva planta de tratamiento que cumple con la normativa federal,<\/p>\n\n\n\n<p>adem\u00e1s de cuidar el medio ambiente y garantizar la sustentabilidad h\u00eddrica de la<br>regi\u00f3n.<\/p>\n\n\n\n<p>Destac\u00f3 tambi\u00e9n el lanzamiento de \u201cLa Torreonense: la tarjeta poder M\u00c1S\u201d; as\u00ed<br>como programas sociales de alimentaci\u00f3n y mejora de vivienda, y en cultura,<br>Torre\u00f3n ser\u00e1 el primer y \u00fanico municipio que pondr\u00e1 en marcha un gran proyecto:<br>Torre\u00f3n TV.<\/p>\n\n\n\n<p>Tambi\u00e9n resalt\u00f3 el desarrollo del Centro Cultural del Norte, proyecto emblem\u00e1tico,<br>\u00fanico en el norte del pa\u00eds que reforzar\u00e1 la identidad regional y abrir\u00e1 nuevas<br>puertas al arte y al talento local, porque la seguridad tambi\u00e9n se construye con<br>prevenci\u00f3n y con oportunidades de vida basadas en el deporte y la cultura.<\/p>\n\n\n\n<p>Rom\u00e1n Alberto Cepeda Gonz\u00e1lez dijo que a trav\u00e9s del DIF Torre\u00f3n, la obra<br>emblem\u00e1tica ser\u00e1 ahora para los adultos mayores con \u201cFuerza Mayor\u201d, un espacio<br>dise\u00f1ado para el fortalecimiento f\u00edsico, fomentar la convivencia y garantizar su vida<br>plena.<\/p>\n\n\n\n<p>Lo anterior, se\u00f1al\u00f3 el Alcalde, no son promesas, son realidades tangibles reflejo<br>de una Administraci\u00f3n que planea, act\u00faa, que cumple, y que trabaja con visi\u00f3n de<br>futuro.<\/p>\n\n\n\n<p>\u201cHoy, desde aqu\u00ed, refrendamos nuestro compromiso de seguir avanzando, de<br>seguir construyendo un mejor futuro para todos los torreonenses. No dejemos que<br>las voces de quienes no aman la ciudad nos dividan. Respondamos con trabajo y<br>unidad. Nada nos detiene. El futuro es nuestro. Vayamos hacia un Torre\u00f3n m\u00e1s<br>pr\u00f3spero, m\u00e1s seguro, m\u00e1s unido. Porque siempre podemos m\u00e1s, porque Torre\u00f3n<br>es nuestra casa, nuestro orgullo, nuestro legado. Torre\u00f3n es para siempre\u201d,<br>expres\u00f3.<\/p>\n\n\n\n<p>Previo a su mensaje, Cepeda Gonz\u00e1lez entreg\u00f3 el Plan Municipal de Desarrollo a<br>Hugo D\u00e1vila Prado, coordinador de Mejora en Coahuila, en representaci\u00f3n del<br>gobernador Manolo Jim\u00e9nez Salinas, quien felicit\u00f3 al Alcalde por escuchar a todos<br>los sectores de la poblaci\u00f3n para la construcci\u00f3n de la ruta de trabajo.<\/p>\n\n\n\n<p>Asimismo, Jos\u00e9 Eleazar Pi\u00f1a \u00c1lvarez, y Sandra L\u00f3pez Chavarr\u00eda, en<br>representaci\u00f3n de los sectores empresarial y acad\u00e9mico, respectivamente,<br>reconocieron la voluntad de di\u00e1logo, apertura y cercan\u00eda de la Administraci\u00f3n<br>Municipal hacia los diferentes sectores ciudadanos.<\/p>\n\n\n\n<p>Tambi\u00e9n estuvieron presentes en el evento que se desarroll\u00f3 la ma\u00f1ana de este<br>martes en el Centro de Convenciones de Torre\u00f3n, el diputado local Felipe<br>Gonz\u00e1lez Miranda, en representaci\u00f3n del Poder Legislativo; el Gral. Brigadier del<br>Estado Mayor Said Gerardo Gonzalez, sub jefe operativo; en representaci\u00f3n del<br>Gral. de Divisi\u00f3n D.E.M. Eufemio Alberto Ibarra, comandante de la la XI Regi\u00f3n<br>Militar; General Brigadier D.E.M. Pedro Alberto Hern\u00e1ndez Gallardo, Comandante<\/p>\n\n\n\n<p>Mando Especial de la Laguna, e invitados especiales representantes de los<br>diferentes sectores de la poblaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 29 de abril de 2025. Este martes, el alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez present\u00f3 el PlanMunicipal de Desarrollo para la Administraci\u00f3n 2025-2027, compuesto por loscinco ejes tem\u00e1ticos de su Gobierno: Seguridad y Orden, Infraestructura yServicios de Calidad, Participaci\u00f3n y Buen Gobierno, Fortalecimiento Econ\u00f3mico,y Unidad y Desarrollo Humano, de los cuales se derivan m\u00e1s de 500 programasen beneficio de los y las torreonenses. En su mensaje, el Presidente&#8230;<\/p>\n","protected":false},"author":1,"featured_media":25815,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-25814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/25814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=25814"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/25814\/revisions"}],"predecessor-version":[{"id":25816,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/25814\/revisions\/25816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/25815"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=25814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=25814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=25814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}