{"id":2638,"date":"2021-06-07T14:07:45","date_gmt":"2021-06-07T19:07:45","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=2638"},"modified":"2021-06-07T14:07:46","modified_gmt":"2021-06-07T19:07:46","slug":"convoca-uadec-a-estudiantes-a-participar-en-la-presea-lobo-2021","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/06\/07\/convoca-uadec-a-estudiantes-a-participar-en-la-presea-lobo-2021\/","title":{"rendered":"Convoca UAdeC a Estudiantes a Participar en la Presea Lobo 2021."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 7 de junio de 2021.- La Universidad Aut\u00f3noma de Coahuila a<br>trav\u00e9s de la Coordinaci\u00f3n de Unidad Saltillo, convoca a alumnos de escuelas,<br>facultades e institutos a postularse para la Presea Lobo 2021, galard\u00f3n que<br>reconoce a estudiantes destacados en diversos \u00e1mbitos.<\/p>\n\n\n\n<p>Podr\u00e1n participar alumnos que se consideren con m\u00e9ritos en las siguientes<br>categor\u00edas: Actividades Acad\u00e9micas, Art\u00edsticas, Innovaci\u00f3n, Compromiso Social,<br>Protecci\u00f3n al Ambiente, Capacidades Diferentes e Integraci\u00f3n Social, Liderazgo,<br>Deportivas y Compromiso Institucional; se otorgar\u00e1 un premio por categor\u00eda para<br>cada uno de los planteles.<\/p>\n\n\n\n<p>Los candidatos deber\u00e1n ser alumnos inscritos en el a\u00f1o 2020 y pertenecer a<br>alguno de las escuelas oficiales de la Unidad Saltillo de la UAdeC, asimismo,<br>haberse distinguido en alguna de las nueve categor\u00edas y ser propuesto por el<br>Consejo Directivo; si el estudiante solicita su registro personalmente, debe contar<br>con la aprobaci\u00f3n de los consejeros de su plantel.<\/p>\n\n\n\n<p>En caso de que el candidato sea miembro del Consejo Directivo, \u00e9ste no<br>participar\u00e1 en la sesi\u00f3n de Consejo en la que se eval\u00faen las propuestas para el<br>premio y no deber\u00e1 de haber sido galardonado con anterioridad en la misma<br>categor\u00eda; las obras o acciones que acrediten el merecimiento del premio, tienen<br>que corresponder a la trayectoria universitaria del estudiante, consideradas hasta<br>el mes de diciembre de 2020.<\/p>\n\n\n\n<p>El registro de la candidatura debe solicitarse por cada Consejo Directivo a la<br>Coordinaci\u00f3n de Unidad Saltillo, a trav\u00e9s de una carta de propuesta emitida por<br>dicho \u00f3rgano; la documentaci\u00f3n a presentar es la siguiente: portada que incluya el<br>nombre completo del postulante, direcci\u00f3n, tel\u00e9fono, correo electr\u00f3nico, escuela a<br>la que pertenece y categor\u00eda para la que se le propone.<\/p>\n\n\n\n<p>As\u00ed como, una carta de aceptaci\u00f3n a participar y recibir personalmente el premio<br>por parte del alumno, copia de la credencial de estudiante o constancia por parte<br>de la escuela que avale su vigencia como alumno durante 2020 y curr\u00edculum<br>actualizado con informaci\u00f3n que respalde su candidatura a la Presea.<\/p>\n\n\n\n<p>La fecha l\u00edmite para la recepci\u00f3n de propuestas ser\u00e1 el viernes 9 de julio de 2021<br>a las 23:59 horas, las escuelas, institutos y facultades, deber\u00e1n realizar el registro<br>y la carga de archivos en <a href=\"https:\/\/forms.office.com\/r\/puaabEybRH\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/forms.office.com\/r\/puaabEybRH<\/a> (un registro y un archivo PDF por candidato), nombrando a cada archivo como \u201cCategor\u00eda-Primer<br>Apellido\u201d, por ejemplo, Deportivas-Mendoza.<\/p>\n\n\n\n<p>El Comit\u00e9 Evaluador de la Unidad se conformar\u00e1 por personas de amplia<br>trayectoria universitaria y con experiencia en cada una de las \u00e1reas, la<br>documentaci\u00f3n que se remita al Comit\u00e9 Evaluador ser\u00e1 manejada en forma<br>confidencial, el dictamen emitido por el Comit\u00e9 Evaluador ser\u00e1 inapelable y el<br>comit\u00e9 tendr\u00e1 la facultad de declarar desierta cualquiera de sus categor\u00edas,<br>cuando as\u00ed lo considere conveniente.<\/p>\n\n\n\n<p>La Coordinaci\u00f3n de Unidad informar\u00e1 oportunamente el resultado a los<br>participantes y a las escuelas, as\u00ed como el lugar, fecha y hora de la ceremonia, lo<br>que ser\u00e1 publicado en la p\u00e1gina <a href=\"http:\/\/www.cus.uadec.mx\" data-type=\"URL\" data-id=\"www.cus.uadec.mx\" target=\"_blank\" rel=\"noreferrer noopener\">www.cus.uadec.mx<\/a> y en Facebook Coordinaci\u00f3n<br>Unidad Saltillo.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n, consultar la convocatoria completa en la p\u00e1gina<br><a href=\"http:\/\/www.cus.uadec.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.cus.uadec.mx\/<\/a>, tambi\u00e9n pueden comunicarse directamente con la Mtra.<br>Hayd\u00e9e de la Garza Rodr\u00edguez en el correo haydee.garza@uadec.edu.mx y con la<br>Mtra. Martha Magdalena Adame Moncada al correo madame@uadec.edu.mx o<br>llamar al Departamento de Asuntos Acad\u00e9micos de la CUS en el tel\u00e9fono (844)<br>414 99 36 Ext. 107 y 117.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 7 de junio de 2021.- La Universidad Aut\u00f3noma de Coahuila atrav\u00e9s de la Coordinaci\u00f3n de Unidad Saltillo, convoca a alumnos de escuelas,facultades e institutos a postularse para la Presea Lobo 2021, galard\u00f3n quereconoce a estudiantes destacados en diversos \u00e1mbitos. Podr\u00e1n participar alumnos que se consideren con m\u00e9ritos en las siguientescategor\u00edas: Actividades Acad\u00e9micas, Art\u00edsticas, Innovaci\u00f3n, Compromiso Social,Protecci\u00f3n al Ambiente, Capacidades Diferentes e Integraci\u00f3n Social, Liderazgo,Deportivas y Compromiso Institucional; se&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2639,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=2638"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2638\/revisions"}],"predecessor-version":[{"id":2640,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2638\/revisions\/2640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/2639"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=2638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=2638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=2638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}