{"id":27600,"date":"2025-08-07T22:20:34","date_gmt":"2025-08-08T04:20:34","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=27600"},"modified":"2025-08-07T22:20:34","modified_gmt":"2025-08-08T04:20:34","slug":"presentan-nuevo-canal-de-television-del-municipio-torreon-tv","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2025\/08\/07\/presentan-nuevo-canal-de-television-del-municipio-torreon-tv\/","title":{"rendered":"Presentan nuevo canal de televisi\u00f3n del municipio, Torre\u00f3n TV."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila.-\u00a0 Por si alguien tiene inter\u00e9s en saberlo, Armando Cobi\u00e1n Lafont el Director del Proyecto\u00a0Torre\u00f3n TV,\u00a0primer canal de\u00a0televisi\u00f3n\u00a0que\u00a0a trav\u00e9s de Concesi\u00f3n Federal\u00a0otorgada hasta hoy, a municipio alguno en este pa\u00eds, para ser operada por\u00a0una administraci\u00f3n municipal, sostiene que\u00a0entrar\u00e1 en operaciones\u00a0conforme a lo convenido, a saber el pr\u00f3ximo 15 de septiembre,\u00a0 con el objetivo de\u00a0 constituirse en un espacio de convergencia de\u00a0todos los laguneros, que tendr\u00e1n en tal\u00a0 empresa p\u00fablica \u00a0 la herramienta\u00a0de comunicaci\u00f3n que impulse\u00a0la narrativa\u00a0que coloque a Torre\u00f3n en el centro del inter\u00e9s del pa\u00eds.<\/p>\n\n\n\n<p>Esto se desprende de las consideraciones que sobre el tema\u00a0que por ahora ocupa el mayor de su inter\u00e9s, al Director del proyecto citado, enumer\u00f3 que en cuanto al avance del\u00a0 obra que albergar\u00e1 la estaci\u00f3n televisiva alcanza al d\u00eda de hoy un 90 % de avance, y \u00e9sta se encuentra localizada en la parte bajo de las instalaciones que alberga, Radio Torre\u00f3n, donde antiguamente era la Biblioteca\u00a0Municipal del Centro\u00a0J. R. Mijares.\u00a0\u00a0<\/p>\n\n\n\n<p>\u00a0Ah\u00ed va a quedar, dijo, &#8220;en todo ese espacio. Empezamos de cero y ya la obra&#8221;, reiter\u00f3, &#8220;est\u00e1 en un 90%. Ya estamos en el tema de los detalles, de iniciar con el proceso pues de equipamiento&#8221;.<\/p>\n\n\n\n<p>&#8220;Este ultimo lo llevaremos en tres etapas, siendo el primero el tema constructivo que\u00a0ya estamos al 90%,\u00a0 en la fase de acondicionar\u00a0tal espacio, para seguir en segundo lugar con su equipamiento&#8221;, asegurando que, &#8220;ya adquirimos el 100 %, y tercero, este\u00a0s\u00e1bado\/domingo estar\u00e1n llegando a Torre\u00f3n todos los especialistas de Monterrey para iniciar el proceso de instalaci\u00f3n del mismo&#8221;.<\/p>\n\n\n\n<p>En ese mismo lapso, asegur\u00f3, &#8220;vamos a trasladar el trasmisor y la antena\u00a0para ubicarlos, hacer las primeras pruebas y a mediados de agosto, ya todo nuestro equipo\u00a0 est\u00e9 listo&#8221;.<\/p>\n\n\n\n<p>&#8220;En\u00a0ese \u00ednter se termina el 10%\u00a0de los pisos, que son los del los estudios, los sets, que son especiales y que debemos dejarlos seis d\u00edas para que queden firmes, y que ya se puedan utilizar. Y entonces entra la fase que corresponde a las escenograf\u00edas&#8221;.\u00a0\u00a0<\/p>\n\n\n\n<p>&#8220;Todo este ultimo tema, ya tenemos a la empresa que nos la va a realizar, pr\u00e1cticamente pues, el vestido de\u00a0todo lo que va a ser el canal&#8221;.<\/p>\n\n\n\n<p><strong>CONTENIDOS.<\/strong><\/p>\n\n\n\n<p>En este tema, el\u00a0funcionario municipal,\u00a0 asegur\u00f3 tener ya la &#8220;barra&#8221; lista para arrancar, todo de producci\u00f3n local, de orden cultural, educativo, cient\u00edfico,\u00a0de salud, deportivo amateur y profesional, adem\u00e1s de una barra infantil &#8220;muy padre&#8221; para los ni\u00f1os.\u00a0<\/p>\n\n\n\n<p>&#8220;Adem\u00e1s, tendremos\u00a0 programas de trova, programas\u00a0de la camerata, programa de sinf\u00f3nica,\u00a0con dos programas especiales que el Instituto Municipal de Cultura y Educaci\u00f3n, donde vamos a\u00a0 tocar temas literarios, de\u00a0 artes visuales, biblioteca, espacio pues destinados a la cultura&#8221;.<\/p>\n\n\n\n<p>&#8220;Vamos a tener con nosotros, al Teatro Isauro Martinez,\u00a0al teatro Nazas,\u00a0la participaci\u00f3n del Instituto de M\u00fasica, vamos a retrasmitir los conciertos de la Camerata de Coahuila.<\/p>\n\n\n\n<p>&#8220;Todo lo que t\u00fa vas a ver, es todo lo que se mueva en Torreon TV&#8221;.\u00a0\u00a0<\/p>\n\n\n\n<p>En \u00e1mbito pol\u00edtico, asegur\u00f3 que habr\u00e1 lo que la pluralidad exige, &#8220;tendremos Mesas de An\u00e1lisis\u00a0con temas de la regi\u00f3n, adem\u00e1s\u00a0 de una mesa de an\u00e1lisis\u00a0sobre deporte y cultura, para que todos sus actores\u00a0expresen lo que nos hace falta, y que nos mueve&#8221;.\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p>&#8220;Ah\u00ed va estar toda la gente&#8221;, asegur\u00f3.<\/p>\n\n\n\n<p><strong>ACCESOS.<\/strong><\/p>\n\n\n\n<p>&#8220;Torre\u00f3n TV\u00a0 ser\u00e1 accesible en la barra de tu aparato televisivo,\u00a0 en el canal abierto de\u00a0una TV,\u00a0 pero nosotros, vamos a aparecer tambi\u00e9n en el sistema de cable, porque la ley federal de Telecomunicaciones\u00a0 obliga a las empresas de cable a subir\u00a0nuestro canal&#8221;.<\/p>\n\n\n\n<p>&#8220;Ya estamos en el proceso&#8221;, revel\u00f3, &#8220;con las empresas de cable para que ellos\u00a0nos abran el canal que pudiera\u00a0ser en este caso, ejemplo el\u00a0128 en el sistema de cable para que la gente, por esa v\u00eda tambi\u00e9n nos pueda seguir&#8221;.<\/p>\n\n\n\n<p>Vamos, dijo optimista,\u00a0&#8220;a contar con redes sociales. Va a estar Tiik Tok, Instagram, YouTube, etc.,\u00a0vamos a estar conectados con toda la comunidad, y lo m\u00e1s importante, que todo talento es local&#8221;.<\/p>\n\n\n\n<p>&#8220;Todos los muchachos, los artistas,\u00a0todos los que van a conducir\u00a0los programas&#8221;, reiter\u00f3, &#8220;con\u00a0 locales. Vamos a contar con toda la comunidad. No necesitamos gente de fuera,\u00a0ni contratarlos. Esa, esa es la instrucci\u00f3n del alcalde&#8221;.<\/p>\n\n\n\n<p>El proyecto va, afirm\u00f3, &#8220;nosotros vamos seg\u00fan un los tiempos que nos trazamos, vamos muy bien. Ya estamos trabajando con el Instituto Mexicano\u00a0de la Propiedad Intelectual -IMPI-, para registrar nuestra marca, nuestro logo, nuestras frases y algunos de los programas que ser\u00e1n exclusivos precisamente de esta administraci\u00f3n&#8221;.<\/p>\n\n\n\n<p>&#8220;El otro proceso, el \u00faltimo&#8221;, dijo, &#8220;que son los par\u00e1metros\u00a0 satelitales\u00a0de la cobertura que tendr\u00e1 el espectro que abarcar\u00e1 50 kil\u00f3metros a la redonda, alcanzando\u00a0el municipio de San Pedro y una partecita de Parras&#8221;.<\/p>\n\n\n\n<p>Tal cobertura, dijo Cobi\u00e1n Lafont, &#8220;nos va a permitir\u00a0abarcar toda la zona Metropolitana de la Laguna, que era lo que\u00a0quer\u00eda el alcalde\u00a0y en el\u00a0documento&#8221;, dijo,\u00a0&#8220;solo nos falta la validaci\u00f3n\u00a0 para que nosotros podamos\u00a0subir al trasmisor y lo empecemos a ver, con pruebas en la tele&#8221;.<\/p>\n\n\n\n<p>&#8220;Esto est\u00e1 en una semana\u00a0m\u00e1s para que lo liberen y ya estamos as\u00ed al cien por ciento legalmente, en esta primera concesi\u00f3n en M\u00e9xico de orden municipal y este es un gran trabajo, que ser\u00e1 el legado que dejar\u00e1\u00a0 Rom\u00e1n Alberto Cepeda en los Sistemas de Comunicaciones para Torre\u00f3n&#8221;.<\/p>\n\n\n\n<p>&#8220;No es una\u00a0pantalla verde, no es un jugar a la tele, es un canal de television\u00a0que\u00a0 cubre todo\u00a0 su reglamento administrativo, operativo\u00a0y todo un esquema de producci\u00f3n a cargo de j\u00f3venes\u00a0 profesionales, provenientes de empresas como Televisa, TV Azteca, son\u00a0 laguneros pues,\u00a0de Torre\u00f3n que ven\u00edan trabajando fuera\u00a0y que hoy pueden retornar\u00a0 a estas tierras&#8221;.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila.-\u00a0 Por si alguien tiene inter\u00e9s en saberlo, Armando Cobi\u00e1n Lafont el Director del Proyecto\u00a0Torre\u00f3n TV,\u00a0primer canal de\u00a0televisi\u00f3n\u00a0que\u00a0a trav\u00e9s de Concesi\u00f3n Federal\u00a0otorgada hasta hoy, a municipio alguno en este pa\u00eds, para ser operada por\u00a0una administraci\u00f3n municipal, sostiene que\u00a0entrar\u00e1 en operaciones\u00a0conforme a lo convenido, a saber el pr\u00f3ximo 15 de septiembre,\u00a0 con el objetivo de\u00a0 constituirse en un espacio de convergencia de\u00a0todos los laguneros, que tendr\u00e1n en tal\u00a0 empresa p\u00fablica&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-27600","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/27600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=27600"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/27600\/revisions"}],"predecessor-version":[{"id":27601,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/27600\/revisions\/27601"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=27600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=27600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=27600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}