{"id":2866,"date":"2021-06-21T00:16:56","date_gmt":"2021-06-21T05:16:56","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=2866"},"modified":"2021-06-21T00:16:57","modified_gmt":"2021-06-21T05:16:57","slug":"coahuila-listo-para-los-nacionales-conade-2021","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/06\/21\/coahuila-listo-para-los-nacionales-conade-2021\/","title":{"rendered":"COAHUILA, LISTO PARA LOS NACIONALES CONADE 2021."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 20 de Junio de 2021.- Alina Garza Herrera, Directora General del Instituto Estatal del Deporte de Coahuila (INEDEC), asegur\u00f3 que Coahuila se declara listo para los Juegos Nacionales CONADE 2021.<\/p>\n\n\n\n<p>La titular del INEDEC mencion\u00f3 que gracias al apoyo del gobernador Miguel \u00c1ngel Riquelme Sol\u00eds los atletas de nuestra entidad tendr\u00e1n participaci\u00f3n en 28 disciplinas dentro de lo que es la m\u00e1xima competencia deportiva a nivel amateur de nuestro pa\u00eds.<\/p>\n\n\n\n<p>\u201cEn esta ocasi\u00f3n, la Delegaci\u00f3n Coahuila est\u00e1 integrada por 422 participantes que representar\u00e1n a nuestro estado en las ocho sedes designadas para albergar estos Nacionales CONADE 2021\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>Garza Herrera destac\u00f3 que este n\u00famero de participaci\u00f3n supera a la de la edici\u00f3n anterior, que fue de 235: \u201cLo que refleja que se est\u00e1 trabajando bien con nuestros atletas\u201d.<\/p>\n\n\n\n<p>Record\u00f3 que Coahuila llev\u00f3 a cabo sus procesos estatales de cada deporte, en los que participaron miles de ni\u00f1as, ni\u00f1os y j\u00f3venes de los 38 municipios, y al final de los mismos se conformaron los diferentes selectivos.<\/p>\n\n\n\n<p>Asimismo, la Directora del INEDEC record\u00f3 que Coahuila alberg\u00f3 dos deportes de la etapa Regional, y dos m\u00e1s de la etapa Macro regional, eventos que tuvieron la participaci\u00f3n de alrededor de mil deportistas de distintos estados del Pa\u00eds.<\/p>\n\n\n\n<p>\u201cPara los Nacionales CONADE 2021 Coahuila ser\u00e1 sede de seis disciplinas deportivas, designaci\u00f3n que se nos hizo gracias al buen manejo de la pandemia del Covid-19 que ha tenido el Gobierno del Estado\u201d, inform\u00f3.<\/p>\n\n\n\n<p>En ese sentido, explic\u00f3 que Saltillo ser\u00e1 anfitri\u00f3n de los mejores exponentes del Beisbol, Softbol, Basquetbol 3&#215;3 y Front\u00f3n; mientras que Torre\u00f3n recibir\u00e1 los deportes de Raquetbol y Rugby 7.<\/p>\n\n\n\n<p>\u201cEsperamos la participaci\u00f3n de alrededor de 3 mil 500 atletas y entrenadores durante la celebraci\u00f3n de estas seis disciplinas en su Fase Nacional, siempre priorizando la salud de todos los visitantes, aplicando los protocolos sanitarios para este tipo de eventos\u201d, se\u00f1al\u00f3 Garza Herrera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 20 de Junio de 2021.- Alina Garza Herrera, Directora General del Instituto Estatal del Deporte de Coahuila (INEDEC), asegur\u00f3 que Coahuila se declara listo para los Juegos Nacionales CONADE 2021. La titular del INEDEC mencion\u00f3 que gracias al apoyo del gobernador Miguel \u00c1ngel Riquelme Sol\u00eds los atletas de nuestra entidad tendr\u00e1n participaci\u00f3n en 28 disciplinas dentro de lo que es la m\u00e1xima competencia deportiva a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2867,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,33,15],"tags":[],"class_list":["post-2866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-deporte","category-gobierno-de-coahuila","wpcat-5-id","wpcat-33-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=2866"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2866\/revisions"}],"predecessor-version":[{"id":2868,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2866\/revisions\/2868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/2867"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=2866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=2866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=2866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}