{"id":2924,"date":"2021-06-23T18:04:24","date_gmt":"2021-06-23T23:04:24","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=2924"},"modified":"2021-06-23T18:04:25","modified_gmt":"2021-06-23T23:04:25","slug":"homenajearan-al-maestro-gerardo-moscoso-en-la-uadec-unidad-torreon","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/06\/23\/homenajearan-al-maestro-gerardo-moscoso-en-la-uadec-unidad-torreon\/","title":{"rendered":"Homenajear\u00e1n al Maestro Gerardo Moscoso en la UAdeC Unidad Torre\u00f3n."},"content":{"rendered":"\n<p>TORRE\u00d3N, Coahuila. 23 de junio de 2021.- La Coordinaci\u00f3n de Unidad Torre\u00f3n<br>de la Universidad Aut\u00f3noma de Coahuila a trav\u00e9s del Departamento de Difusi\u00f3n<br>Cultural, rendir\u00e1 homenaje p\u00f3stumo al maestro y doctor Gerardo Moscoso<br>Caama\u00f1o, este viernes 25 de junio a las 13:00 horas, por medio del Facebook<br>Live: Cultura UAdeC Torre\u00f3n.<\/p>\n\n\n\n<p>Gerardo Moscoso fue maestro, actor, cantante, productor y director de Teatro,<br>nacido en la Ciudad de M\u00e9xico en 1945, estudi\u00f3 Medicina en la Universidad de<br>Santiago de Compostela, carrera de la que egres\u00f3 en 1970, para posteriormente,<br>dedicarse al mundo de la actuaci\u00f3n a comienzos de1977.<\/p>\n\n\n\n<p>Despu\u00e9s de una larga y fruct\u00edfera trayectoria en el \u00e1mbito del cine y el teatro<br>nacionales en donde tuvo la oportunidad de trabajar con los mejores actores de su<br>generaci\u00f3n y con directores como Ludwick Margulles, Ra\u00fal Quintanilla y Luis de<br>Tavira, entre muchos otros, decidi\u00f3, a finales de los a\u00f1os 90, instalar su residencia<br>en Torre\u00f3n, Coahuila.<\/p>\n\n\n\n<p>Fue en esa ciudad donde puso al servicio de la cultura y las artes de la regi\u00f3n un<br>enorme bagaje y c\u00famulo de experiencias que vinieron a trastocar este \u00e1mbito de<br>manera relevante y que lo llev\u00f3 a ser director de la Compa\u00f1\u00eda Coahuilense de<br>Teatro La Gaviota, del Centro Cultural Comunitario Pilar Rioja y del Teatro<br>Salvador Novo en Torre\u00f3n, adem\u00e1s fue articulista en diversos peri\u00f3dicos.<\/p>\n\n\n\n<p>Moscoso Caama\u00f1o, falleci\u00f3 el pasado 23 de mayo y se desempe\u00f1aba como<br>director de la Escuela de Artes Esc\u00e9nicas de la Unidad Torre\u00f3n. El homenaje es<br>este viernes 25 de junio a las 13:00 horas, por medio de la transmisi\u00f3n en vivo en:<br><a href=\"https:\/\/www.facebook.com\/difcultuadec.unidadtorreon\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/difcultuadec.unidadtorreon, <\/a>se contar\u00e1 con la presencia<a href=\"https:\/\/www.facebook.com\/difcultuadec.unidadtorreon\" target=\"_blank\" rel=\"noreferrer noopener\"><br><\/a>del rector de la m\u00e1xima casa de estudios, Salvador Hern\u00e1ndez V\u00e9lez.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n sobre esta y m\u00e1s actividades, visita el Facebook del<br>Departamento de Difusi\u00f3n Cultural: \u201cCultura UAdeC Torre\u00f3n\u201d, o la p\u00e1gina de la<br>Coordinaci\u00f3n de Unidad Torre\u00f3n: <a href=\"https:\/\/www.facebook.com\/UAdeCUT,\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/UAdeCUT,<\/a> o<br>comun\u00edcate a los tel\u00e9fonos: (871) 871 729 32 05, (871) 729 32 00, (871) 729 32<br>01.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORRE\u00d3N, Coahuila. 23 de junio de 2021.- La Coordinaci\u00f3n de Unidad Torre\u00f3nde la Universidad Aut\u00f3noma de Coahuila a trav\u00e9s del Departamento de Difusi\u00f3nCultural, rendir\u00e1 homenaje p\u00f3stumo al maestro y doctor Gerardo MoscosoCaama\u00f1o, este viernes 25 de junio a las 13:00 horas, por medio del FacebookLive: Cultura UAdeC Torre\u00f3n. Gerardo Moscoso fue maestro, actor, cantante, productor y director de Teatro,nacido en la Ciudad de M\u00e9xico en 1945, estudi\u00f3 Medicina en la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,2],"tags":[],"class_list":["post-2924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-uadec","wpcat-12-id","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=2924"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2924\/revisions"}],"predecessor-version":[{"id":2926,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2924\/revisions\/2926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/2925"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=2924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=2924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=2924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}