{"id":29837,"date":"2025-12-26T08:40:39","date_gmt":"2025-12-26T14:40:39","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=29837"},"modified":"2025-12-26T08:40:39","modified_gmt":"2025-12-26T14:40:39","slug":"feliz-navidad-coahuila-familia-jimenez-rodriguez","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2025\/12\/26\/feliz-navidad-coahuila-familia-jimenez-rodriguez\/","title":{"rendered":"FELIZ NAVIDAD COAHUILA: FAMILIA JIM\u00c9NEZ RODR\u00cdGUEZ."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; 24 de diciembre de 2025.- El gobernador&nbsp;&nbsp;Manolo Jim\u00e9nez Salinas, su esposa Paola Rodr\u00edguez L\u00f3pez y sus hijos Manolo, Santiago, Catalina y Cordelia, desean&nbsp;&nbsp;a todas las familias coahuilenses una Navidad llena de paz, unidad y salud.&nbsp;<\/p>\n\n\n\n<p>El mandatario estatal expres\u00f3 que estas fechas representan una oportunidad para fortalecer los valores de la uni\u00f3n, la solidaridad y la esperanza, as\u00ed como para reflexionar sobre lo alcanzado y renovar el compromiso de seguir trabajando por el bienestar de la entidad.<\/p>\n\n\n\n<p>\u201cEn esta Navidad, mi familia y yo deseamos que en cada hogar de Coahuila haya paz, salud y momentos de convivencia. Son d\u00edas para agradecer y para recordar que, cuando trabajamos unidos, somos m\u00e1s fuertes\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Asimismo, Manolo Jim\u00e9nez reiter\u00f3 su compromiso de continuar impulsando acciones y pol\u00edticas p\u00fablicas que permitan mantener a Coahuila como uno de los mejores estados para vivir en M\u00e9xico, priorizando la seguridad, el desarrollo econ\u00f3mico y la calidad de vida de las y los coahuilenses.<\/p>\n\n\n\n<p>Finalmente, el Gobernador dese\u00f3 que el pr\u00f3ximo a\u00f1o est\u00e9 lleno de nuevas oportunidades y desarrollo para todas las familias del estado.<\/p>\n\n\n\n<p>Comparte Paola v\u00edspera de Noche Buena con pacientes del Hospital General y Materno Infantil de Saltillo<\/p>\n\n\n\n<p>La presidenta honoraria de Inspira Coahuila, Paola Rodr\u00edguez L\u00f3pez, visit\u00f3 en la V\u00edspera de Noche Buena a las familias de pacientes que se encuentran internados en el Hospital General y el Materno Infantil de Saltillo, con quienes convivi\u00f3 y entreg\u00f3 cenas navide\u00f1as, llevando un mensaje de esperanza y unidad.&nbsp;<\/p>\n\n\n\n<p>La esposa del gobernador Manolo Jim\u00e9nez record\u00f3 que, desde la oficina Inspira, se trabaja de manera coordinada con las diversas secretar\u00edas del estado para atender las necesidades m\u00e1s sensibles de las y los coahuilenses, refrendando su compromiso de continuar siendo un punto de encuentro entre el gobierno estatal, la sociedad civil y las familias coahuilenses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; 24 de diciembre de 2025.- El gobernador&nbsp;&nbsp;Manolo Jim\u00e9nez Salinas, su esposa Paola Rodr\u00edguez L\u00f3pez y sus hijos Manolo, Santiago, Catalina y Cordelia, desean&nbsp;&nbsp;a todas las familias coahuilenses una Navidad llena de paz, unidad y salud.&nbsp; El mandatario estatal expres\u00f3 que estas fechas representan una oportunidad para fortalecer los valores de la uni\u00f3n, la solidaridad y la esperanza, as\u00ed como para reflexionar sobre lo alcanzado y renovar&#8230;<\/p>\n","protected":false},"author":1,"featured_media":29838,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","wpcat-1-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/29837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=29837"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/29837\/revisions"}],"predecessor-version":[{"id":29839,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/29837\/revisions\/29839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/29838"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=29837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=29837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=29837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}