{"id":3012,"date":"2021-06-27T19:04:28","date_gmt":"2021-06-28T00:04:28","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=3012"},"modified":"2021-06-27T19:04:29","modified_gmt":"2021-06-28T00:04:29","slug":"cuenta-coahuila-con-medicamento-innovador-para-tratamiento-de-cancer","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/06\/27\/cuenta-coahuila-con-medicamento-innovador-para-tratamiento-de-cancer\/","title":{"rendered":"CUENTA COAHUILA CON MEDICAMENTO INNOVADOR PARA TRATAMIENTO DE C\u00c1NCER."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 27 de Junio de 2021.-\u00a0 La Secretar\u00eda de Salud del Estado (SS) dio a conocer que, gracias a las gestiones del gobernador Miguel \u00c1ngel Riquelme Sol\u00eds, Coahuila cuenta con\u00a0 medicamentos oncol\u00f3gicos innovadores y de alta eficacia, mediante una inversi\u00f3n de 200 millones de pesos, que ser\u00e1n empleados en los Hospitales Generales de la entidad.<\/p>\n\n\n\n<p>Roberto Bernal G\u00f3mez, Secretario de Salud, explic\u00f3 que estos medicamentos oncol\u00f3gicos que utilizaremos son indicados por gu\u00edas nacionales e internacionales, por lo que poseen la certificaci\u00f3n correspondiente.<\/p>\n\n\n\n<p>Bernal G\u00f3mez record\u00f3 que al inicio de este a\u00f1o, la presente Administraci\u00f3n de Miguel Riquelme entreg\u00f3 85 millones de pesos en medicamentos oncol\u00f3gicos para atender a ni\u00f1as y ni\u00f1os con c\u00e1ncer, que son supervisados por la asociaci\u00f3n \u201cCasa Feliz\u201d, de Torre\u00f3n.<\/p>\n\n\n\n<p>Mencion\u00f3 que la entrega de dicho medicamento tiene un reglamento que privilegia a los menores que m\u00e1s lo necesitan, con apoyo del Sistema DIF Coahuila y la participaci\u00f3n del sector empresarial.<\/p>\n\n\n\n<p>Indic\u00f3 que en el estado se integr\u00f3 un Consejo Plural de Onc\u00f3logos, miembros de la sociedad civil, empresarios y autoridades sanitarias que definen el uso correcto y transparencia de este tipo de apoyos.<\/p>\n\n\n\n<p>Inform\u00f3 que adicionalmente a las quimioterapias que se emplean para tratar c\u00e1ncer de col\u00f3n, c\u00e9rvico \u2013 uterino y mama, se cuenta con inmunoterapia, un tipo de tratamiento que ayuda al sistema inmunitario para pacientes con c\u00e1ncer de pulm\u00f3n, de vejiga, renal y melanoma.<\/p>\n\n\n\n<p>El funcionario agreg\u00f3 que se ofrecer\u00e1n terapias dirigidas a pacientes con ciertas mutaciones de tumores malignos, especialmente de c\u00e1ncer de mama y ovario.<\/p>\n\n\n\n<p>Por parte su, Eva Willars, onc\u00f3loga especialista de la dependencia, destac\u00f3 que el Sector Salud coahuilense cuenta con tratamientos para c\u00e1ncer de mama met\u00e1stasico, que han podido salvar la vida de pacientes en las 8 Jurisdicciones Sanitarias.<\/p>\n\n\n\n<p>\u201cAdicionalmente hemos emprendido con el apoyo del programa estatal \u2018Cambiando Vidas\u2019, una intensa cruzada de detecciones de c\u00e1ncer de pulm\u00f3n, mama, col\u00f3n y pr\u00f3stata en cada Hospital General, donde podr\u00e1n acudir los interesados\u201d, dijo.<\/p>\n\n\n\n<p>Enfatiz\u00f3 que se mantiene comunicaci\u00f3n permanente con el Instituto de Salud para el Bienestar (INSABI) para obtener mayores recursos para la atenci\u00f3n de pacientes con c\u00e1ncer: \u201cRequerimos del apoyo federal para poder ampliar nuestro programa de beneficiarios\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 27 de Junio de 2021.-\u00a0 La Secretar\u00eda de Salud del Estado (SS) dio a conocer que, gracias a las gestiones del gobernador Miguel \u00c1ngel Riquelme Sol\u00eds, Coahuila cuenta con\u00a0 medicamentos oncol\u00f3gicos innovadores y de alta eficacia, mediante una inversi\u00f3n de 200 millones de pesos, que ser\u00e1n empleados en los Hospitales Generales de la entidad. Roberto Bernal G\u00f3mez, Secretario de Salud, explic\u00f3 que estos medicamentos oncol\u00f3gicos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,14],"tags":[],"class_list":["post-3012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-salud","wpcat-5-id","wpcat-15-id","wpcat-14-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=3012"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3012\/revisions"}],"predecessor-version":[{"id":3014,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3012\/revisions\/3014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/3013"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=3012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=3012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=3012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}