{"id":30471,"date":"2026-02-11T21:18:49","date_gmt":"2026-02-12T03:18:49","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=30471"},"modified":"2026-02-11T21:18:49","modified_gmt":"2026-02-12T03:18:49","slug":"arrancan-grandes-obras-en-coahuila-por-3-mil-mdp","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2026\/02\/11\/arrancan-grandes-obras-en-coahuila-por-3-mil-mdp\/","title":{"rendered":"ARRANCAN GRANDES OBRAS EN COAHUILA POR 3 MIL MDP."},"content":{"rendered":"\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<em>En la regi\u00f3n Sureste se construir\u00e1 el puente vehicular en la colonia Loma Linda en Saltillo<\/em><\/p>\n\n\n\n<p>Piedras Negras, Coahuila de Zaragoza; a 11 de febrero de 2026.- Con el arranque de la ampliaci\u00f3n del bulevar Fausto Z. Mart\u00ednez (Ruta Fiscal) en Piedras Negras, donde se invertir\u00e1n cien millones de pesos en su primera etapa, el gobernador Manolo Jim\u00e9nez Salinas deton\u00f3 el proyecto de grandes obras para Coahuila, en el cual se aplicar\u00e1n tres mil millones de pesos en acciones de infraestructura prioritaria en todas las regiones de la entidad.<\/p>\n\n\n\n<p>&#8220;Con el arranque de la ampliaci\u00f3n del bulevar Fausto Z. Mart\u00ednez, que forma parte del gran proyecto de la Ruta Fiscal, desde Piedras Negras detonamos las Grandes Obras para todas las regiones de Coahuila, en las que invertiremos 3 mil millones de pesos. Con esta Ruta Fiscal se mejorar\u00e1 la movilidad, dinamizar\u00e1 el comercio y consolidar\u00e1 el desarrollo de esta gran frontera de M\u00e9xico. Este es resultado del trabajo en equipo, la planeaci\u00f3n responsable y la cercan\u00eda con nuestra gente. En Coahuila cumplimos compromisos y avanzamos&#8221;, destac\u00f3 el gobernador.<\/p>\n\n\n\n<p>La ampliaci\u00f3n de la Ruta Fiscal se llevar\u00e1 a cabo en cinco etapas, con una inversi\u00f3n global de m\u00e1s de 500 millones de pesos.<\/p>\n\n\n\n<p>Jim\u00e9nez Salinas destac\u00f3 que en las pr\u00f3ximas semanas presentar\u00e1n el gran proyecto de mega obras para Coahuila, muchas de las cuales tienen que ver con la ampliaci\u00f3n, rehabilitaci\u00f3n y mejoramiento de la carretera 57.<\/p>\n\n\n\n<p>Mencion\u00f3 que la ampliaci\u00f3n de esta Ruta Fiscal tiene que ver con la ampliaci\u00f3n del Puente Internacional II, proyecto prioritario estatal que se lleva a cabo en coordinaci\u00f3n con el Gobierno Federal y con el gobierno de Eagle Pass, Texas.<\/p>\n\n\n\n<p>A\u00f1adi\u00f3 que se estar\u00e1 ampliando a cuatro carriles la carretera 57 en su tramo Saltillo \u2013 Monclova, y que, adem\u00e1s, se van a construir, rehabilitar y mejorar carreteras y libramientos para darle m\u00e1s competitividad y mejorar la conectividad y seguridad carretera de nuestro estado.<\/p>\n\n\n\n<p>\u201cCon todas estas obras, autom\u00e1ticamente Coahuila y Piedras Negras se volver\u00e1n mucho m\u00e1s atractivas para el comercio; todo esto se traduce en competitividad, en desarrollo, en inversiones; se traduce en m\u00e1s y mejores empleos para nuestra gente\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez coment\u00f3 que con este gran proyecto, que se espera est\u00e9 terminado antes de concluir su administraci\u00f3n, se podr\u00e1 atraer entre un 10 y un 15 por ciento del comercio que cruza por otras fronteras de la regi\u00f3n, con lo que se generar\u00e1 un \u201cboom\u201d econ\u00f3mico para Coahuila y para Eagle Pass.<\/p>\n\n\n\n<p>Mencion\u00f3 que en la parte de desarrollo econ\u00f3mico, todas las inversiones en infraestructura generan competitividad.<\/p>\n\n\n\n<p>Agradeci\u00f3 a los empresarios de la regi\u00f3n y al alcalde de Piedras Negras, Jacobo Rodr\u00edguez, por la coordinaci\u00f3n con su gobierno para poder llevar a cabo este gran proyecto en su regi\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Jim\u00e9nez Salinas reconoci\u00f3 que las condiciones de seguridad, desarrollo econ\u00f3mico y calidad de vida que hoy se tienen en Coahuila, es gracias al trabajo en equipo entre ciudadanos, sociedad civil organizada, iniciativa privada y los tres \u00f3rdenes de gobierno, \u201cy eso lo tenemos que seguir cuidando entre todas y todos\u201d.<\/p>\n\n\n\n<p>\u201cEn el tema de seguridad, hoy reiteramos nuestro compromiso con las y los coahuilenses; vamos a seguir invirtiendo y, gracias a las y los diputados, este a\u00f1o estaremos invirtiendo m\u00e1s de cuatro mil millones de pesos para blindar a nuestro estado\u201d, destac\u00f3.<\/p>\n\n\n\n<p>Record\u00f3 que gracias a este gran trabajo en seguridad, Coahuila tiene tres de las diez ciudades m\u00e1s seguras de M\u00e9xico: Piedras Negras, la frontera m\u00e1s segura del pa\u00eds; Saltillo, la capital m\u00e1s segura de M\u00e9xico; y Torre\u00f3n, la s\u00e9ptima ciudad m\u00e1s segura de la Rep\u00fablica, y la m\u00e1s segura de La Laguna.<\/p>\n\n\n\n<p>\u201cNuestro gobierno no va ni para al izquierda ni para la derecha; nuestro gobierno va puro pa\u00b4delante\u201d, puntualiz\u00f3 el gobernador Manolo Jim\u00e9nez al agregar que su administraci\u00f3n no divide, no grilla, no polariza, sino que trabaja, planea, tiene rumbo y da buenos resultados.<\/p>\n\n\n\n<p>Miguel \u00c1ngel Algara Acosta secretario de Infraestructura, Desarrollo Urbano y Movilidad inform\u00f3 que el proyecto de la ampliaci\u00f3n y modernizaci\u00f3n de la Ruta Fiscal consta de cinco etapas y una meta final de casi ocho kil\u00f3metros.<\/p>\n\n\n\n<p>Reiter\u00f3 con esta primera etapa se aplicar\u00e1n cien millones de pesos con una meta de 1.2 kil\u00f3metros, con ampliaciones a cinco y ocho carriles en algunos tramos.<\/p>\n\n\n\n<p>\u201cEl objetivo primordial de esta obra es el de contar con infraestructura vial necesaria para garantizar un tr\u00e1nsito \u00e1gil y optimizar la movilidad para el comercio internacional de Coahuila y del noreste de M\u00e9xico que cruzan diariamente hacia los Estados Unidos\u201d, expres\u00f3 Algara Acosta.<\/p>\n\n\n\n<p>Jacobo Rodr\u00edguez Gonz\u00e1lez, alcalde de Piedras Negras, en su intervenci\u00f3n mencion\u00f3 que invertir en Piedras Negras es fortalecer a Coahuila y es contribuir al desarrollo econ\u00f3mico de M\u00e9xico.<\/p>\n\n\n\n<p>Coment\u00f3 que esta obra de la ampliaci\u00f3n de la Ruta Fiscal es estrat\u00e9gica para la competitividad y el orden urbano de esta frontera, y refrend\u00f3 que la coordinaci\u00f3n estado y municipio es clave para que los proyectos se ejecuten buscando el mayor bienestar social para las y los coahuilenses.<\/p>\n\n\n\n<p>\u201cReconozco el apoyo y respaldo del gobernador Manolo Jime\u00e9nz Salinas cuya visi\u00f3n es impulsar obras que detonen el desarrollo econ\u00f3mico con responsabilidad social\u201d, se\u00f1al\u00f3 el alcalde.<\/p>\n\n\n\n<p>Por su parte Isidro de los Santos Villarreal, director de Prossesa SA de CV y beneficiario de este proyecto, se\u00f1al\u00f3 que esta inversi\u00f3n representa mayor competitividad, mayor tr\u00e1nsito de mercanc\u00edas y productos, m\u00e1s turismo y dinamismo comercial, fortaleciendo la econom\u00eda de Piedras Negras y generando m\u00e1s empleos para la gente y para toda la regi\u00f3n del norte.<\/p>\n\n\n\n<p>En el arranque de esta obra acompa\u00f1aron al gobernador, adem\u00e1s, Aaron Vald\u00e9s Aripe, Mayor de Eagle Pass; Guillermo Ruiz Guerra, diputado local; Gabriel Elizondo P\u00e9rez, coordinador general de Mejora Coahuila Sonia Villarreal P\u00e9rez, subsecretaria de Gobierno en la regi\u00f3n Norte Sa\u00fal Baldomero Rodr\u00edguez Moyeda, gerente general de Transportes Baldomero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;En la regi\u00f3n Sureste se construir\u00e1 el puente vehicular en la colonia Loma Linda en Saltillo Piedras Negras, Coahuila de Zaragoza; a 11 de febrero de 2026.- Con el arranque de la ampliaci\u00f3n del bulevar Fausto Z. Mart\u00ednez (Ruta Fiscal) en Piedras Negras, donde se invertir\u00e1n cien millones de pesos en su primera etapa, el gobernador Manolo Jim\u00e9nez Salinas deton\u00f3 el proyecto de grandes obras para Coahuila, en el cual&#8230;<\/p>\n","protected":false},"author":1,"featured_media":30472,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,75],"tags":[],"class_list":["post-30471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-obra","wpcat-5-id","wpcat-15-id","wpcat-75-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/30471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=30471"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/30471\/revisions"}],"predecessor-version":[{"id":30473,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/30471\/revisions\/30473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/30472"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=30471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=30471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=30471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}