{"id":31700,"date":"2026-05-06T19:02:20","date_gmt":"2026-05-07T01:02:20","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=31700"},"modified":"2026-05-06T21:45:51","modified_gmt":"2026-05-07T03:45:51","slug":"trabajando-en-equipo-cuidamos-nuestros-bosques-y-recursos-naturales","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2026\/05\/06\/trabajando-en-equipo-cuidamos-nuestros-bosques-y-recursos-naturales\/","title":{"rendered":"TRABAJANDO EN EQUIPO CUIDAMOS NUESTROS BOSQUES Y RECURSOS NATURALES."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 06 de mayo de 2026.- El gobernador Manolo Jim\u00e9nez Salinas presidi\u00f3 la sesi\u00f3n del Consejo Ciudadano para el Combate de Incendios Forestales, mesa de trabajo en la que se destacaron los avances en la&nbsp;&nbsp;materia.<\/p>\n\n\n\n<p>&#8220;\u00a1Cuidar nuestros bosques y nuestras sierras es cuidar el presente y el futuro de Coahuila! En Saltillo con el director nacional de la CONAFOR como invitado especial, llevamos a cabo la Segunda Sesi\u00f3n del Consejo Ciudadano para la Prevenci\u00f3n y Combate de Incendios Forestales; donde nos reunimos para revisar, afinar y seguir mejorando nuestra estrategia para proteger nuestros recursos naturales. El trabajo en equipo siempre da mejores resultados.<\/p>\n\n\n\n<p>Si detectas un incendio forestal, rep\u00f3rtalo de inmediato al 911. Tu llamada puede hacer la diferencia&#8221;, puntualiz\u00f3 el gobernador.<\/p>\n\n\n\n<p>En esta misma sesi\u00f3n, adem\u00e1s, se presentaron los avances preliminares y objetivos de la temporada de incendios forestales.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez puntualiz\u00f3 que lo que se ha invertido en Coahuila en materia de combate a incendios forestales es algo hist\u00f3rico gracias a la suma de esfuerzos de los municipios y la iniciativa privada.<\/p>\n\n\n\n<p>Coment\u00f3 que, sin duda, lo que se ha hecho en conjunto en estos dos a\u00f1os en esta materia, se ha pasado al siguiente nivel.<\/p>\n\n\n\n<p>Expres\u00f3 su agradecimiento por la gran participaci\u00f3n ciudadana y por la coordinaci\u00f3n y gran apoyo del Ej\u00e9rcito y de la Guardia Nacional.<\/p>\n\n\n\n<p>\u201cEn Coahuila cerramos filas y trabajamos en equipo en los temas importantes y prioritarios; aqu\u00ed estamos muy por encima de los temas pol\u00edtico-partidistas\u201d, indic\u00f3.<\/p>\n\n\n\n<p>Agreg\u00f3 que como Gobierno siempre buscan llamar a la unidad, ser punto de encuentro entre todas y todos quienes quieren hacer cosas buenas por Coahuila.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez record\u00f3 que para el arranque de la temporada de incendios forestales, hace unas semanas, se entreg\u00f3 a las y los brigadistas equipo, herramientas, veh\u00edculos, drones, equipo de radiocomunicaci\u00f3n, pilas colapsables; se inform\u00f3 que se cuenta con tres helic\u00f3pteros a disposici\u00f3n y, lo m\u00e1s importante, con 445 brigadistas listos para atender cualquier situaci\u00f3n.<\/p>\n\n\n\n<p>\u201cLo que se ve aqu\u00ed en este consejo, es parte de c\u00f3mo hacemos las cosas en Coahuila, porque todas las adversidades que se nos presentan en nuestro estado las enfrentamos trabajando en equipo; y este consejo es una muestra patente de esa f\u00f3rmula m\u00e1gica que nos permite dar buenos resultados en Coahuila\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>Jim\u00e9nez Salinas explic\u00f3 que en este consejo est\u00e1 presente la sociedad civil organizada, la iniciativa privada, la academia y los tres \u00f3rdenes de gobierno; todos jalando para un mismo lado, en sinton\u00eda, con un plan y con una estrategia.<\/p>\n\n\n\n<p>En esta sesi\u00f3n estuvo presente Sergio Humberto Graf Montero, director general de la Comisi\u00f3n Nacional Forestal (Conafor), quien agradeci\u00f3 y reconoci\u00f3 el compromiso que el estado de Coahuila ha tenido para el combate a incendios forestales.<\/p>\n\n\n\n<p>\u201cCoahuila es uno de los estados con mayor compromiso que tenemos en el pa\u00eds, y se lo reconocemos y agradecemos enormemente\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>Coment\u00f3 que las condiciones de sequ\u00eda y el aumento de temperatura est\u00e1n haciendo que los incendios forestales sean cada vez m\u00e1s explosivos, por lo que se necesita siempre una articulaci\u00f3n y una capacitaci\u00f3n de los tres \u00f3rdenes de gobierno, de los propietarios, de la sociedad civil organizada y de la academia.<\/p>\n\n\n\n<p>\u00d3scar Pimentel Gonz\u00e1lez, secretario de Gobierno mencion\u00f3 que la preservaci\u00f3n de nuestros recursos naturales, especialmente de las \u00e1reas boscosas, es un tema de la mayor relevancia.<\/p>\n\n\n\n<p>\u201cLa definici\u00f3n que se ha hecho para reducir al m\u00ednimo posible los incendios forestales y para combatirlos en forma inmediata y eficaz cuando se presentan, no es solamente una decisi\u00f3n voluntarista, es una pol\u00edtica de gobierno\u201d, dijo.<\/p>\n\n\n\n<p>Ren\u00e9 Medina Morales, subsecretario de Incendios Forestales de la Secretar\u00eda de Medio Ambiente inform\u00f3 que en lo que va de la administraci\u00f3n estatal se ha consolidado una inversi\u00f3n hist\u00f3rica para fortalecer, como nunca antes, la prevenci\u00f3n y el combate a incendios forestales en Coahuila.<\/p>\n\n\n\n<p>\u201cCon esta inversi\u00f3n se ha fortalecido el estado de fuerza operativo mediante la entrega de m\u00e1s de tres mil 300 unidades de equipo de protecci\u00f3n personal, y m\u00e1s de dos mil herramientas especializadas destinadas ha mejorar la seguridad y la capacidad de respuesta de nuestras brigadas\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Inform\u00f3 que hoy se cuenta con 47 veh\u00edculos terrestres disponibles y el apoyo a\u00e9reo de tres aeronaves estrat\u00e9gicamente ubicadas en el estado.<\/p>\n\n\n\n<p>Estuvieron presentes en esta sesi\u00f3n, adem\u00e1s, General Brigadier E.M. Francisco Acu\u00f1a Diaz, coordinador estatal de la Guardia Nacional; General de Brigada E.M. Juan Carlos Quiroz Mu\u00f1oz, comandante de la 6ta. Zona Militar; Miguel Felipe Mery Ayup, magistrado presidente de la Tribunal Superior de Justicia; Beatriz Fraustro D\u00e1vila, diputada local; Federico Fern\u00e1ndez Monta\u00f1ez, fiscal general del Estado; Javier D\u00edaz Gonz\u00e1lez, presidente municipal de Saltillo; Diana Susana Estens de la Garza, secretaria de Medio Ambiente; y David Valladares, de Amigos de la Sierra AC.<\/p>\n\n\n\n<p>As\u00ed como alcaldes y alcaldesas de diversos municipios; empresarios, representantes de universidades p\u00fablicas y privadas; integrantes de la sociedad civil organizada, funcionarios de los tres \u00f3rdenes de gobierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 06 de mayo de 2026.- El gobernador Manolo Jim\u00e9nez Salinas presidi\u00f3 la sesi\u00f3n del Consejo Ciudadano para el Combate de Incendios Forestales, mesa de trabajo en la que se destacaron los avances en la&nbsp;&nbsp;materia. &#8220;\u00a1Cuidar nuestros bosques y nuestras sierras es cuidar el presente y el futuro de Coahuila! En Saltillo con el director nacional de la CONAFOR como invitado especial, llevamos a cabo la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":31701,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,50,15],"tags":[],"class_list":["post-31700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-ecologia","category-gobierno-de-coahuila","wpcat-5-id","wpcat-50-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=31700"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31700\/revisions"}],"predecessor-version":[{"id":31702,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31700\/revisions\/31702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/31701"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=31700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=31700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=31700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}