{"id":31703,"date":"2026-05-07T18:26:00","date_gmt":"2026-05-08T00:26:00","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=31703"},"modified":"2026-05-07T18:26:00","modified_gmt":"2026-05-08T00:26:00","slug":"anuncia-fcc-de-la-uadec-su-semana-de-la-comunicacion-2026-y-open-house-nido-del-perico","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2026\/05\/07\/anuncia-fcc-de-la-uadec-su-semana-de-la-comunicacion-2026-y-open-house-nido-del-perico\/","title":{"rendered":"Anuncia FCC de la UAdeC su Semana de la Comunicaci\u00f3n 2026 y Open House \u201cNido del Perico\u201d."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 7 de mayo de 2026. La Facultad de Ciencias de la<br>Comunicaci\u00f3n de la Universidad Aut\u00f3noma de Coahuila dio a conocer los<br>pormenores de la Semana de la Comunicaci\u00f3n 2026 \u201cClick: Voz y mensaje\u201d, as\u00ed<br>como del Open House \u201cNido del Perico\u201d, actividades que buscan fortalecer la<br>formaci\u00f3n acad\u00e9mica y la vinculaci\u00f3n profesional de sus estudiantes.<\/p>\n\n\n\n<p>En conferencia de prensa realizada en el Foro de Grupos y Talleres de la UAdeC, el<br>responsable del Departamento de Relaciones P\u00fablicas del plantel, Iv\u00e1n Mora \u00c1vila,<br>acompa\u00f1ado por los alumnos Andrea Amaro, organizadora de la Semana de la<br>Comunicaci\u00f3n y Gael Cuello, organizador del Open House, se\u00f1alaron que este<br>evento se consolida como un espacio estrat\u00e9gico de an\u00e1lisis, actualizaci\u00f3n y<br>formaci\u00f3n pr\u00e1ctica para la comunidad universitaria.<\/p>\n\n\n\n<p>La edici\u00f3n 2026 contempla un simposio que reunir\u00e1 a profesionales, investigadores y<br>estudiantes para reflexionar sobre las tendencias actuales del ecosistema medi\u00e1tico<br>mediante conferencias, talleres y cursos especializados.<\/p>\n\n\n\n<p>El programa iniciar\u00e1 el 11 de mayo a las 11:00 horas, con la conferencia magistral del<br>periodista Jorge Carrasco, director de la Revista Proceso, medio que celebra su 50<br>aniversario; asimismo, participar\u00e1n los acad\u00e9micos y periodistas Gabriel P\u00e9rez<br>Salazar, Carlos Arredondo Sibaja y Christian Orta, quienes abordar\u00e1n temas como la<br>inteligencia artificial, los retos del periodismo contempor\u00e1neo y la inserci\u00f3n laboral en<br>el campo de la comunicaci\u00f3n.<\/p>\n\n\n\n<p>Como parte de la oferta formativa, se impartir\u00e1n talleres profesionalizantes en \u00e1reas<br>como Direcci\u00f3n de Actores, Periodismo en Redes Sociales, Mercadotecnia y<br>Emprendimiento, Lenguaje Inclusivo en Medios, Producci\u00f3n de Audio y Maquillaje<br>para Fotograf\u00eda, entre otros, con el objetivo de fortalecer habilidades clave en<br>comunicaci\u00f3n organizacional y producci\u00f3n de medios.<\/p>\n\n\n\n<p>Todas las actividades se desarrollar\u00e1n en las instalaciones de la Facultad, ubicadas<br>en Carretera a Zacatecas Km. 3, Colonia Villas de San Lorenzo en Saltillo; la entrada<br>ser\u00e1 gratuita para alumnos de la Facultad, para estudiantes de la UAdeC tendr\u00e1 un<br>costo de $80 pesos y para p\u00fablico externo de $100 pesos.<\/p>\n\n\n\n<p>En el mismo encuentro, la Facultad extendi\u00f3 la invitaci\u00f3n al Open House \u201cNido del<br>Perico\u201d, dirigido a estudiantes de bachillerato y personas interesadas en cursar la<br>Licenciatura en Ciencias de la Comunicaci\u00f3n, el cual se llevar\u00e1 a cabo este 7 de<br>mayo, de 10:00 a 13:00 horas en las instalaciones del plantel.<\/p>\n\n\n\n<p>El acceso al Open House ser\u00e1 gratuito para todos los interesados, quienes podr\u00e1n<br>conocer de primera mano la oferta acad\u00e9mica, recorrer las instalaciones y<br>experimentar el uso del equipo en laboratorios especializados.<\/p>\n\n\n\n<p>Adem\u00e1s, durante la jornada, los asistentes podr\u00e1n participar en clases muestra de<br>fotograf\u00eda, periodismo y relaciones p\u00fablicas, adem\u00e1s de integrarse al ambiente<br>cultural y emprendedor de la Facultad mediante un \u201cmercadito\u201d y exposiciones<br>fotogr\u00e1ficas y audiovisuales organizadas por estudiantes.<\/p>\n\n\n\n<p>Ambas actividades son coordinadas por alumnos de quinto semestre, lo que les<br>permite aplicar estrategias de publicidad y relaciones p\u00fablicas en un contexto real; se<br>espera la asistencia de m\u00e1s de 170 j\u00f3venes provenientes de escuelas de nivel medio<br>superior de la UAdeC y de diversas instituciones del sur de Saltillo, fortaleciendo as\u00ed<br>la orientaci\u00f3n vocacional y el v\u00ednculo con la comunidad.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n, sobre la Semana de la Comunicaci\u00f3n 2026 y el Open House<br>comunicarse a la Facultad de Ciencias de la Comunicaci\u00f3n a los tel\u00e9fonos (844) 417<br>97 17 y (844) 417 00 92, o visitar la p\u00e1gina de Facebook<br><a href=\"https:\/\/www.facebook.com\/facultad.comunicacion.oficial\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/facultad.comunicacion.oficial<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 7 de mayo de 2026. La Facultad de Ciencias de laComunicaci\u00f3n de la Universidad Aut\u00f3noma de Coahuila dio a conocer lospormenores de la Semana de la Comunicaci\u00f3n 2026 \u201cClick: Voz y mensaje\u201d, as\u00edcomo del Open House \u201cNido del Perico\u201d, actividades que buscan fortalecer laformaci\u00f3n acad\u00e9mica y la vinculaci\u00f3n profesional de sus estudiantes. En conferencia de prensa realizada en el Foro de Grupos y Talleres de la UAdeC, elresponsable&#8230;<\/p>\n","protected":false},"author":1,"featured_media":31704,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-31703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=31703"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31703\/revisions"}],"predecessor-version":[{"id":31705,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31703\/revisions\/31705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/31704"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=31703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=31703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=31703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}