{"id":31719,"date":"2026-05-08T13:13:03","date_gmt":"2026-05-08T19:13:03","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=31719"},"modified":"2026-05-08T13:13:03","modified_gmt":"2026-05-08T19:13:03","slug":"coahuila-aplica-ajustes-al-calendario-escolar-2025-2026-por-disposicion-de-la-autoridad-educativa-federal","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2026\/05\/08\/coahuila-aplica-ajustes-al-calendario-escolar-2025-2026-por-disposicion-de-la-autoridad-educativa-federal\/","title":{"rendered":"COAHUILA APLICA AJUSTES AL CALENDARIO ESCOLAR 2025-2026 POR DISPOSICI\u00d3N DE LA AUTORIDAD EDUCATIVA FEDERAL."},"content":{"rendered":"\n<p>Saltillo, Coahuila; 7 de mayo de 2026.- La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza informa que, por indicaciones de la Secretar\u00eda de Educaci\u00f3n P\u00fablica Federal, se realizar\u00e1n ajustes al calendario escolar 2025-2026, para escuelas de Educaci\u00f3n B\u00e1sica y Media Superior en la entidad.<\/p>\n\n\n\n<p>Las modificaciones responden principalmente a las condiciones clim\u00e1ticas provocadas por las altas temperaturas registradas en distintas regiones del pa\u00eds, priorizando en todo momento el bienestar y la seguridad de las comunidades escolares.<\/p>\n\n\n\n<p>Los ajustes que se realizar\u00e1n en el calendario de educaci\u00f3n b\u00e1sica son:<\/p>\n\n\n\n<p>\u2022 El ciclo escolar concluir\u00e1 el pr\u00f3ximo 5 de junio.<\/p>\n\n\n\n<p>\u2022 Las actividades administrativas de cierre finalizar\u00e1n el 12 de junio.<\/p>\n\n\n\n<p>\u2022 La sesi\u00f3n de Consejo T\u00e9cnico Escolar (CTE), prevista originalmente para el 29 de mayo, se llevar\u00e1 a cabo el 8 de junio.<\/p>\n\n\n\n<p>\u2022 El personal educativo retomar\u00e1 actividades a partir del 10 de agosto, para participar en la fase intensiva de Consejo T\u00e9cnico Escolar y preparar el arranque del siguiente ciclo lectivo.<\/p>\n\n\n\n<p>\u2022 El personal educativo recibir\u00e1 a sus alumnos del 17 al 28 de agosto con el objetivo de reforzar conocimientos y atender las necesidades acad\u00e9micas.<\/p>\n\n\n\n<p>\u2022 El inicio formal del ciclo escolar 2026-2027 ser\u00e1 el 31 de agosto, en todas las escuelas incorporadas al Sistema Educativo Nacional.<\/p>\n\n\n\n<p>Las escuelas particulares tendr\u00e1n la libertad de decisi\u00f3n con la finalidad de salvaguardar las necesidades del servicio educativo que ofertan y en concordancia a la infraestructura de sus planteles educativos, adem\u00e1s de las condiciones clim\u00e1ticas, lo anterior con la finalidad de proteger la integridad y desarrollo educativo de sus alumnos.<\/p>\n\n\n\n<p>Una vez que la autoridad educativa federal emita el acuerdo por el cual modifica el calendario escolar, aplicable para las escuelas de educaci\u00f3n b\u00e1sica, as\u00ed como al calendario de educaci\u00f3n media superior,&nbsp;&nbsp;la Secretar\u00eda de Educaci\u00f3n del Estado, emitir\u00e1 los lineamientos correspondientes, con la finalidad de normar las situaciones no previstas y atendiendo en todo momento al inter\u00e9s superior de la ni\u00f1ez y juventud coahuilense.<\/p>\n\n\n\n<p>La dependencia estatal reconoce el compromiso de maestras, maestros, directivos, supervisores, personal administrativo y de apoyo, as\u00ed como el acompa\u00f1amiento permanente de madres, padres de familia y tutores, quienes contribuyen diariamente al fortalecimiento de la educaci\u00f3n en Coahuila.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila; 7 de mayo de 2026.- La Secretar\u00eda de Educaci\u00f3n del Estado de Coahuila de Zaragoza informa que, por indicaciones de la Secretar\u00eda de Educaci\u00f3n P\u00fablica Federal, se realizar\u00e1n ajustes al calendario escolar 2025-2026, para escuelas de Educaci\u00f3n B\u00e1sica y Media Superior en la entidad. Las modificaciones responden principalmente a las condiciones clim\u00e1ticas provocadas por las altas temperaturas registradas en distintas regiones del pa\u00eds, priorizando en todo momento el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,9,15],"tags":[],"class_list":["post-31719","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-educacion","category-gobierno-de-coahuila","wpcat-5-id","wpcat-9-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=31719"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31719\/revisions"}],"predecessor-version":[{"id":31720,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31719\/revisions\/31720"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=31719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=31719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=31719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}