{"id":31721,"date":"2026-05-08T17:47:52","date_gmt":"2026-05-08T23:47:52","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=31721"},"modified":"2026-05-08T17:47:52","modified_gmt":"2026-05-08T23:47:52","slug":"rinde-su-tercer-informe-de-actividades-la-directora-de-la-escuela-de-sistemas-de-la-uadec-carolina-melendez-gurrola","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2026\/05\/08\/rinde-su-tercer-informe-de-actividades-la-directora-de-la-escuela-de-sistemas-de-la-uadec-carolina-melendez-gurrola\/","title":{"rendered":"Rinde su Tercer Informe de Actividades la Directora de la Escuela de Sistemas de la UAdeC, Carolina Mel\u00e9ndez Gurrola."},"content":{"rendered":"\n<p>TORRE\u00d3N, Coahuila. 8 de mayo de 2026. Ante el Consejo Directivo de la Escuela<br>de Sistemas Unidad Laguna de la Universidad Aut\u00f3noma de Coahuila, rindi\u00f3 su<br>tercer Informe de Actividades la directora Carolina Mel\u00e9ndez Gurrola,<br>correspondiente al periodo 2025-2026.<\/p>\n\n\n\n<p>En el Aula Magna \u201cManuel Sea\u00f1ez\u201d del plantel, asisti\u00f3 el coordinador de Unidad<br>Laguna, Omar Rojas Zapata; el secretario ex oficio del Consejo Directivo, Jes\u00fas<br>Daniel Hern\u00e1ndez Villegas; el secretario administrativo de la Escuela de Sistemas,<br>Ariel Gonz\u00e1lez L\u00f3pez; as\u00ed como directivos de Dependencias, Escuelas y Facultades<br>de la Unidad Laguna.<\/p>\n\n\n\n<p>En su mensaje, el coordinador de Unidad Laguna, Omar Rojas Zapata, reconoci\u00f3 el<br>trabajo realizado por la directora Carolina Mel\u00e9ndez en materia administrativa,<br>transparencia y mejora de infraestructura, as\u00ed como por el fortalecimiento de<br>laboratorios, aulas activas y espacios acad\u00e9micos que contribuyen directamente a la<br>calidad educativa de la Escuela de Sistemas.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que actualmente la Escuela de Sistemas se proyecta como una instituci\u00f3n<br>con visi\u00f3n de futuro, comprometida con la innovaci\u00f3n, la investigaci\u00f3n, la<br>transformaci\u00f3n digital y la formaci\u00f3n integral de profesionistas altamente<br>competitivos.<\/p>\n\n\n\n<p>\u201cA nombre de la Coordinaci\u00f3n Unidad Laguna, reconocemos el compromiso,<br>liderazgo y trabajo realizado por la maestra Ana Carolina Mel\u00e9ndez Gurrola, por su<br>equipo de trabajo y por toda la comunidad de la Escuela de Sistemas durante este<br>periodo de gesti\u00f3n\u201d, expres\u00f3.<\/p>\n\n\n\n<p>En su informe, la directora Mel\u00e9ndez Gurrola se\u00f1al\u00f3 que el periodo 2023-2026 ha<br>representado una etapa de consolidaci\u00f3n acad\u00e9mica, crecimiento institucional y<br>fortalecimiento integral de la comunidad universitaria, trabajando bajo cinco ejes<br>estrat\u00e9gicos: calidad educativa, fortalecimiento docente, vinculaci\u00f3n e infraestructura,<br>transparencia institucional y formaci\u00f3n integral estudiantil.<\/p>\n\n\n\n<p>A\u00f1adi\u00f3 que, uno de los principales compromisos fue apoyar la permanencia y el<br>egreso oportuno de los estudiantes, por lo que 264 alumnos participaron en cursos<br>de verano y regularizaci\u00f3n acad\u00e9mica, lo que permiti\u00f3 disminuir rezagos y fortalecer<br>la eficiencia terminal.<\/p>\n\n\n\n<p>En materia de apoyos estudiantiles, destac\u00f3 el beneficio otorgado a m\u00e1s de 300<br>estudiantes mediante becas de excelencia acad\u00e9mica, inclusi\u00f3n, apoyos deportivos y<br>condonaciones de cuota interna, promoviendo la equidad y la permanencia escolar.<\/p>\n\n\n\n<p>Asimismo, impuls\u00f3 una estrategia de promoci\u00f3n institucional mediante visitas a m\u00e1s<br>de 30 instituciones de educaci\u00f3n media superior, el fortalecimiento de las redes<br>sociales institucionales y el desarrollo de eventos como \u201cCasa Abierta\u201d.<\/p>\n\n\n\n<p>En el \u00e1mbito acad\u00e9mico y tecnol\u00f3gico, la Escuela de Sistemas fortaleci\u00f3 su<br>presencia regional mediante la organizaci\u00f3n de la Semana Acad\u00e9mica y<br>posteriormente del evento \u201cData Week\u201d, consolid\u00e1ndose como un espacio de<br>innovaci\u00f3n en inteligencia artificial, programaci\u00f3n, ciencia y tecnolog\u00eda; estos eventos<br>integraron conferencias, talleres, concursos acad\u00e9micos, as\u00ed como actividades<br>deportivas y culturales, con la participaci\u00f3n de universidades de toda la regi\u00f3n.<\/p>\n\n\n\n<p>En cuanto a la investigaci\u00f3n y fortalecimiento acad\u00e9mico, destac\u00f3 el crecimiento de<br>la planta docente y la consolidaci\u00f3n de cuerpos acad\u00e9micos reconocidos por el<br>Programa para el Desarrollo Profesional Docente (PRODEP); actualmente, la<br>Escuela cuenta con 16 profesores de tiempo completo, de los cuales nueve poseen<br>reconocimiento PRODEP, adem\u00e1s de tres cuerpos acad\u00e9micos en consolidaci\u00f3n y<br>formaci\u00f3n, que impulsan proyectos cient\u00edficos, publicaciones y convocatorias<br>nacionales en temas de inteligencia artificial, transformaci\u00f3n digital, sostenibilidad y<br>tecnolog\u00eda aplicada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORRE\u00d3N, Coahuila. 8 de mayo de 2026. Ante el Consejo Directivo de la Escuelade Sistemas Unidad Laguna de la Universidad Aut\u00f3noma de Coahuila, rindi\u00f3 sutercer Informe de Actividades la directora Carolina Mel\u00e9ndez Gurrola,correspondiente al periodo 2025-2026. En el Aula Magna \u201cManuel Sea\u00f1ez\u201d del plantel, asisti\u00f3 el coordinador de UnidadLaguna, Omar Rojas Zapata; el secretario ex oficio del Consejo Directivo, Jes\u00fasDaniel Hern\u00e1ndez Villegas; el secretario administrativo de la Escuela de Sistemas,Ariel&#8230;<\/p>\n","protected":false},"author":1,"featured_media":31722,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-31721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-torreon","category-uadec","wpcat-7-id","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=31721"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31721\/revisions"}],"predecessor-version":[{"id":31723,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/31721\/revisions\/31723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/31722"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=31721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=31721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=31721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}