{"id":3344,"date":"2021-07-15T17:35:48","date_gmt":"2021-07-15T22:35:48","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=3344"},"modified":"2021-07-15T17:35:49","modified_gmt":"2021-07-15T22:35:49","slug":"educacion-coahuila-pone-a-disposicion-via-web-los-certificados-de-primaria-y-secundaria","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/07\/15\/educacion-coahuila-pone-a-disposicion-via-web-los-certificados-de-primaria-y-secundaria\/","title":{"rendered":"EDUCACI\u00d3N COAHUILA PONE A DISPOSICI\u00d3N V\u00cdA WEB LOS CERTIFICADOS DE PRIMARIA Y SECUNDARIA."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>\u00a0Facilita el tr\u00e1mite y es gratuito<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 15 de Julio 2021.- A fin de reducir tr\u00e1mites y tiempos en la emisi\u00f3n de certificados del nivel B\u00e1sico, la Secretar\u00eda de Educaci\u00f3n del Estado pone a disposici\u00f3n desde ya el portal donde los interesados podr\u00e1n consultar e imprimir el diploma de conclusi\u00f3n de estudios de alumnos de 6\u00ba de Primaria y 3\u00ba de Secundaria del presente ciclo escolar.<\/p>\n\n\n\n<p>El Subsecretario de Educaci\u00f3n B\u00e1sica, Jorge Salcido Portillo, inform\u00f3 que el certificado se expide bajo los mismos principios legales con los que trabaja la Secretar\u00eda de Educaci\u00f3n de manera tradicional, que tambi\u00e9n puede ser expedido en los centros escolares y reimprimirlo sin costo las veces que lo requieran para sus tr\u00e1mites.<\/p>\n\n\n\n<p>Aclar\u00f3 que para las escuelas particulares dicho tr\u00e1mite estar\u00e1 disponible a partir del d\u00eda 16 de este mes.<\/p>\n\n\n\n<p>En estos tiempos de contingencia la certificaci\u00f3n digital tiene varias ventajas, como facilitar el acceso desde cualquier computadora con acceso a internet, tener una versi\u00f3n electr\u00f3nica con la misma validez que la impresa, por lo que hace posible la portabilidad del documento en medios como el correo electr\u00f3nico o internet.<\/p>\n\n\n\n<p>Con el certificado digital se evitan errores con el firmado aut\u00f3grafo por parte de los directores, reduce los tr\u00e1mites como los tiempos y es completamente seguro y gratuito.<\/p>\n\n\n\n<p>Salcido Portillo dijo que el portal<\/p>\n\n\n\n<p><a href=\"https:\/\/siecec.seducoahuila.gob.mx\/expediente\/index.php\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/siecec.seducoahuila.gob.mx\/expediente\/index.php<\/a>&nbsp;se encuentra disponible y ante cualquier duda al respecto pueden acudir a la Secretar\u00eda de Educaci\u00f3n con la CURP.&nbsp;<\/p>\n\n\n\n<p>Para certificados anteriores al Ciclo 2001-2002 se tendr\u00e1 que hacer el tr\u00e1mite de manera convencional en las oficinas de la Secretar\u00eda de Educaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Facilita el tr\u00e1mite y es gratuito Saltillo, Coahuila de Zaragoza; a 15 de Julio 2021.- A fin de reducir tr\u00e1mites y tiempos en la emisi\u00f3n de certificados del nivel B\u00e1sico, la Secretar\u00eda de Educaci\u00f3n del Estado pone a disposici\u00f3n desde ya el portal donde los interesados podr\u00e1n consultar e imprimir el diploma de conclusi\u00f3n de estudios de alumnos de 6\u00ba de Primaria y 3\u00ba de Secundaria del presente ciclo escolar&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":3345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,9,15],"tags":[],"class_list":["post-3344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-educacion","category-gobierno-de-coahuila","wpcat-5-id","wpcat-9-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=3344"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3344\/revisions"}],"predecessor-version":[{"id":3346,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3344\/revisions\/3346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/3345"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=3344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=3344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=3344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}