{"id":3377,"date":"2021-07-18T19:19:13","date_gmt":"2021-07-19T00:19:13","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=3377"},"modified":"2021-07-18T19:19:13","modified_gmt":"2021-07-19T00:19:13","slug":"dinosaurios-en-la-monsivais-unete-a-este-divertido-curso-de-verano-que-ofrece-coahuila","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/07\/18\/dinosaurios-en-la-monsivais-unete-a-este-divertido-curso-de-verano-que-ofrece-coahuila\/","title":{"rendered":"\u00a1DINOSAURIOS EN LA MONSIV\u00c1IS! \u00daNETE A ESTE DIVERTIDO CURSO DE VERANO QUE OFRECE COAHUILA."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 18 de Julio de 2021.- Este verano los dinosaurios invadir\u00e1n tu pantalla y te ense\u00f1ar\u00e1n todo sobre ellos: Qu\u00e9 com\u00edan, cu\u00e1nto med\u00edan y descubrir\u00e1s que muchos eran coahuilenses, como t\u00fa.<\/p>\n\n\n\n<p>Esto y m\u00e1s lo aprender\u00e1s en el Curso de Verano que la Librer\u00eda del Fondo de Cultura Econ\u00f3mica \u201cCarlos Monsiv\u00e1is\u201d ya tiene listo para ni\u00f1os y ni\u00f1as de 6 a\u00f1os en adelante.<\/p>\n\n\n\n<p>As\u00ed lo inform\u00f3 la Coordinaci\u00f3n General de Bibliotecas, Publicaciones y Librer\u00edas del Estado, al se\u00f1alar que el curso ser\u00e1 transmitido por la plataforma Zoom del 26 al 30 de julio, en un horario de las 14:00 a las 16:00 horas.<\/p>\n\n\n\n<p>\u201cCada a\u00f1o la Librer\u00eda prepara un curso de verano para los peque\u00f1os del hogar, y este a\u00f1o exploraremos todo lo relacionado con los dinosaurios a trav\u00e9s de narraciones, juegos y un concierto musical\u201d, se\u00f1al\u00f3 la dependencia.<\/p>\n\n\n\n<p>Las inscripciones se realizan por mensaje \u2013inbox- al Facebook Librer\u00eda del Fondo Carlos Monsiv\u00e1is, con el nombre del participante y un n\u00famero telef\u00f3nico, es totalmente gratuito y los materiales que se utilizar\u00e1n son muy f\u00e1ciles de conseguir en casa.<\/p>\n\n\n\n<p>Adri\u00e1n Villar, reconocido tallerista de la Ciudad de M\u00e9xico, se encargar\u00e1 de dirigir este Curso de Verano Virtual.<\/p>\n\n\n\n<p>\u201cEn cada sesi\u00f3n haremos din\u00e1micas manuales, gimnasia cerebral, les mostraremos c\u00e1psulas informativas de cada dinosaurio para que vean c\u00f3mo viv\u00edan, qu\u00e9 caracter\u00edsticas ten\u00edan y cu\u00e1les eran sus habilidades\u201d, detall\u00f3.<\/p>\n\n\n\n<p>Agreg\u00f3 que contar\u00e1n con la participaci\u00f3n de un narrador infantil y, para finalizar, los ni\u00f1os disfrutar\u00e1n de un concierto musical con un artista invitado.<\/p>\n\n\n\n<p>\u201cEstamos muy entusiasmados con este curso porque sabemos lo populares que son los dinosaurios entre los ni\u00f1os, y cuando descubran que esta regi\u00f3n estaba llena de ellos, se pondr\u00e1n muy contentos y aprender\u00e1n m\u00e1s\u201d, expres\u00f3.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 18 de Julio de 2021.- Este verano los dinosaurios invadir\u00e1n tu pantalla y te ense\u00f1ar\u00e1n todo sobre ellos: Qu\u00e9 com\u00edan, cu\u00e1nto med\u00edan y descubrir\u00e1s que muchos eran coahuilenses, como t\u00fa. Esto y m\u00e1s lo aprender\u00e1s en el Curso de Verano que la Librer\u00eda del Fondo de Cultura Econ\u00f3mica \u201cCarlos Monsiv\u00e1is\u201d ya tiene listo para ni\u00f1os y ni\u00f1as de 6 a\u00f1os en adelante. As\u00ed lo inform\u00f3&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,9,15],"tags":[],"class_list":["post-3377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-educacion","category-gobierno-de-coahuila","wpcat-5-id","wpcat-9-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=3377"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3377\/revisions"}],"predecessor-version":[{"id":3379,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3377\/revisions\/3379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/3378"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=3377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=3377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=3377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}