{"id":360,"date":"2021-02-14T19:55:48","date_gmt":"2021-02-15T01:55:48","guid":{"rendered":"http:\/\/34.69.167.107\/?p=360"},"modified":"2021-02-14T19:55:48","modified_gmt":"2021-02-15T01:55:48","slug":"aqui-laguna-5","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/02\/14\/aqui-laguna-5\/","title":{"rendered":"Aqu\u00ed Laguna."},"content":{"rendered":"\n<p>\u00a1Nadie es profeta en su tierra! Pero resulta que el Ingeniero Salvador Hern\u00e1ndez Velez, s\u00ed lo es. Los fr\u00edos n\u00fameros que arroj\u00f3 el c\u00f3mputo final del proceso de elecci\u00f3n interna de la Universidad Aut\u00f3noma de Coahuila, as\u00ed lo indican. Ah\u00ed est\u00e1n, para que cada quien los lea, los interprete pues, desde la perspectiva que les permita la ubicaci\u00f3n de su inter\u00e9s, pero la reelecci\u00f3n del lagunero, es un hecho ya inamovible.<br><br>Cabe se\u00f1alar que en este proceso de elecci\u00f3n, en medio del impacto que genera la pandemia y que oblig\u00f3 a que tal proceso se verificara de manera presencial y remota entre por lo menos poco mas de 42 mil convocados, entre docentes y estudiantes, afectados todos por la virtual inacci\u00f3n socializante que se ha impuesto en esta y el resto de actividades comunes a lo largo ya de un a\u00f1o que imprimieron sin duda, y mostr\u00f3 de paso su impacto entre la comunidad universitaria, que no es ajena ahora nada a la misma, y llamado al que acudi\u00f3, contra todo pronostico, poco mas del 70% de sus integrantes seg\u00fan suma oficial, se contaron y sumaron poco mas de 32 mil votos, cifra nada despreciable de legitimidad y sostenibilidad al hoy Rector electo para un segundo periodo al frente de la m\u00e1xima Casa de Estudios en Coahuila.<br><br>Bien tambi\u00e9n por aquellos que votaron en contra, pues el disenso en cualquier democracia es indispensable, en especial entre una comunidad integrada por j\u00f3venes que en M\u00e9xico, por desgracia no se significan por tal participaci\u00f3n y se resignan a ser parte de una masa acr\u00edtica debido a muy diversos factores.<br><br>Por ahora, el Ingeniero Hern\u00e1ndez Velez, es el primer lagunero que alcanza el puesto m\u00e1ximo de direcci\u00f3n en la Universidad estatal y hay que decirlo, es en la Unidad Saltillo donde se gener\u00f3 el mayor n\u00famero de votos en su contra, de resistencias, no as\u00ed en el resto de la Unidad Norte y la Unidad Torre\u00f3n. Sin duda, con inter\u00e9s se escuchar\u00e1 el mensaje que en la pr\u00f3xima toma de posesi\u00f3n de su cargo, el lagunero Hernandez Velez dirija a la comunidad universitaria y al resto de los coahuilenses, y se\u00f1ale prioridades en lo que ser\u00e1 su segundo mandato y en el que sin duda incluir\u00e1 con peso especifico significativo, una de las tareas fundamentales de cualquier universidad en el mundo; la generaci\u00f3n de nuevos conocimientos, que solo se logran con la investigaci\u00f3n pura y aplicada.<br><br>Esta elecci\u00f3n universitaria in\u00e9dita por el contexto que le toco esperar, tambi\u00e9n ser\u00e1 se\u00f1alada, debido a que el candidato registr\u00f3 durante la mismas, afectaci\u00f3n del virus que azota al mundo y, lo super\u00f3. \u00a1Felicidades!<br><br><br>En tanto, para este mismo lunes a primera hora, el Presidente Andr\u00e9s Manuel L\u00f3pez Obrador y su gobierno estar\u00e1 iniciando la vacunaci\u00f3n contra Covid-19 a adultos mayores, inscritos previamente a trav\u00e9s de la plataforma digital correspondiente, pero solo en 33 municipios del pa\u00eds, y a mexicanos que tengan 80 a\u00f1os o mas, una vez que dicen, estar\u00e1n llegando al pa\u00eds, 870 mil dosis de vacuna Astra Zeneca, procedentes de Mumbai, India. Para que esto suceda en Coahuila todav\u00eda falta, primero el anuncio, y luego que este sea cierto, pues no hay informaci\u00f3n oficial, al menos hasta hoy domingo en el que se haga del conocimiento de los interesados, los sitios a donde podr\u00e1 acudir para recibir el ant\u00edgeno. Ya veremos y diremos.<br><br><br>Efem\u00e9rides, si bien &#8220;los males, fueron del tiempo, no de Espa\u00f1a&#8221; como dicen y que en ello se incluyen algunas de nuestras verg\u00fcenzas, como lo es la famosa matanza de Chinos ocurrida un Torre\u00f3n en el aciago 16 de mayo de 1911, cuando al menos 330 miembros de la comunidad china en Torre\u00f3n fueron vejados y asesinados por las fuerzas revolucionarias que hac\u00edan de la ciudad, constante cuartel, zona de trasiego que impuso la Revoluci\u00f3n en nuestra tierra. Recodar tal episodio a 110 a\u00f1os de su registro y que alguna raz\u00f3n, el presidente L\u00f3pez Obrador ha decidido inclu\u00edrlo en el programa de celebraciones o recordatorios a realizar este a\u00f1o y en cuyo marco, se anticipa M\u00e9xico ofrecer\u00e1 una disculpa la gran pueblo chino por tal agravio, pero, mejor estar\u00eda que AMLO, mas que homenajes recordatorios a tantos y tantos a\u00f1os de distancia, fuera mas efectivo y su gobierno, con todo y lo austero que dice ser, pagar la indemnizaci\u00f3n que nuestro pa\u00eds que adeuda a tales v\u00edctimas -ahora a sus descendientes-, no solo de por su extinci\u00f3n como seres humanos, sino de sus patrimonios, que se llev\u00f3 la revoluci\u00f3n y que un organismo internacional sentenci\u00f3 a pagarles y aun, a 110 a\u00f1os no ha cumplido.<br><br><br>El Licenciado Marcelo Torres Cofi\u00f1o, pre-candidato por el Partido Acci\u00f3n Nacional, a la alcald\u00eda de Torre\u00f3n, ya defini\u00f3 los ejes centrales de su discurso pol\u00edtico que habr\u00e1 de agotar a partir del 4 de abril pr\u00f3ximo ante el potencial electorado de este municipio y que construye en torno a agotado tema de la megadeuda que tan pocos resultados pol\u00edtico-electorales les ha generado a los panistas en Coahuila, y al que ahora agrega el tema del Metrobus.<br><br>Sin duda ambos son relevantes, en especial el de la megadeuda en el que el panismo ha montado todas sus campa\u00f1as electorales y agotado, sin lograr mayores resultados, no solo porque no encuentran el eco esperado entre la poblaci\u00f3n sino tambi\u00e9n por incompetencia para agotar caminos judiciales, que los hay, tortuosos si se quiere, pero existen, y el otro, el Metrob\u00fas, obra realizada en Torre\u00f3n con recursos federales extraordinarios, y que en efecto, merece que se llame ya el lentob\u00fas, que ha registrado todo tipo de retrasos para su total operaci\u00f3n, si bien la obra, en principio esta concluida, si bien la obra con todo lo que signific\u00f3 en t\u00e9rminos t\u00e9cnicos realizarla sobre un bulevar en uso y por el que transita el mayor aforo de unidades en la ciudad, pero ha resultado mas dif\u00edcil aun generar el modelo de negocio que satisfaga a los concesionarios involucrados en el sistema troncal, que son la mayor\u00eda y que se resisten a dejar el esquema de &#8220;hombre-cami\u00f3n&#8221;, que tantos beneficios les ha proporcionado a lo largo de toda su vida, ello agregado a la pandemia que ha hecho bajar el aforo de usuarios a expresiones m\u00ednimas.<br><br>En ambos temas, se espera que Torres Cofi\u00f1o, aporte algunas sugerencias para superarlos.<br><br><br>Desatado, anda por Torre\u00f3n el alcalde Jorge Zerme\u00f1o Infante en inaugurar obras, as\u00ed sean estas obra hormigas o de relumbr\u00f3n pues se le agota el tiempo previo a que presente licencia por tres meses a su cargo, para irse en pos de Do\u00f1a Blanca.<br><br><br>Y con todo y que baja un tanto la presencia del coronavirus en Coahuila, se requiere que sigamos acatando las recomendaciones sanitarias en su contra &#8220;nuestra vida y la de los dem\u00e1s va en ello&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Nadie es profeta en su tierra! Pero resulta que el Ingeniero Salvador Hern\u00e1ndez Velez, s\u00ed lo es. Los fr\u00edos n\u00fameros que arroj\u00f3 el c\u00f3mputo final del proceso de elecci\u00f3n interna de la Universidad Aut\u00f3noma de Coahuila, as\u00ed lo indican. Ah\u00ed est\u00e1n, para que cada quien los lea, los interprete pues, desde la perspectiva que les permita la ubicaci\u00f3n de su inter\u00e9s, pero la reelecci\u00f3n del lagunero, es un hecho ya&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-360","post","type-post","status-publish","format-standard","hentry","category-aqui-laguna","wpcat-8-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=360"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/360\/revisions"}],"predecessor-version":[{"id":361,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/360\/revisions\/361"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}