{"id":3862,"date":"2021-08-11T20:41:23","date_gmt":"2021-08-12T01:41:23","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=3862"},"modified":"2021-08-11T20:41:23","modified_gmt":"2021-08-12T01:41:23","slug":"aqui-laguna-55","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/08\/11\/aqui-laguna-55\/","title":{"rendered":"Aqu\u00ed Laguna."},"content":{"rendered":"\n<p>\u00a1De nueva cuenta! Se anuncia la presencia de Andr\u00e9s Manuel L\u00f3pez Obrador,\u00a0 en La Laguna, si bien no se sabe con certeza\u00a0 la agenda a que habr\u00e1 de ce\u00f1irse tan importante presencia,\u00a0 se anticipa que el tema dominante ser\u00e1\u00a0 el de \u00a0 profundizar en el conocimiento\u00a0 general de la poblaci\u00f3n\u00a0 en torno al Proyecto &#8220;Agua Saludable para La Laguna&#8221;, \u00a0 que hasta hoy solo\u00a0 es del conocimiento integro\u00a0de algunos, no as\u00ed la opini\u00f3n p\u00fablica,\u00a0 que conoce solo \u00a0 elementos parciales del conjunto\u00a0 del mismo, lo que siembra incertidumbre, curiosidad\u00a0 y recelos.<\/p>\n\n\n\n<p>A la fecha, y al parecer solo la Comisi\u00f3n Nacional del Agua, que regentea\u00a0 tal\u00a0 tema \u00a0 lo\u00a0 conoce a fondo, y\u00a0 quiz\u00e1s\u00a0 \u00a0 la Secretar\u00eda de\u00a0 Agricultura \u00a0 luego que sus titulares V\u00edctor Villalobos y Germ\u00e1n Mart\u00ednez, mas a fuerza que de ganas tuvieron que enfrentarse en reuni\u00f3n privada dicen, a los titulares de los M\u00f3dulos\u00a0 que integran el Distrito de\u00a0 Riego Numero 17,\u00a0 del que forman parte -por ahora, ya solo en papel-,\u00a0 todos y cada uno de los campesinos que en 1936 fueron dotados de las aguas\u00a0 de las presas del Nazas en un n\u00famero de 44 mil usuarios que inclu\u00edan no solo a los campesinos y\u00a0 en ese momento\u00a0 ejidatarios dotados tambi\u00e9n de tierras, al igual\u00a0 que peque\u00f1os propietarios\u00a0 con derecho a tales aguas en proporci\u00f3n directa a las tierras que se les respetaron tras liquidar L\u00e1zaro C\u00e1rdenas el sistema feudal\u00a0 que prevaleci\u00f3\u00a0 en este pa\u00eds, hasta ese famoso a\u00f1o de 1936\u00a0.<\/p>\n\n\n\n<p>Eso lo conoce al dedillo\u00a0la CONAGUA, con precisi\u00f3n\u00a0 como\u00a0 han transitado tales dotaciones a manos de peque\u00f1os propietarios\u00a0 una vez que tal derecho o concesi\u00f3n\u00a0 se convirti\u00f3 en mercanc\u00eda, y siguiendo\u00a0 las leyes del mercado, acabaron siendo moneda de cambio al extinguirse, por Decreto Presidencial el sistema ejidal, por decisi\u00f3n de\u00a0 Carlos Salinas de Gortari,  de ah\u00ed que informar &#8220;a los campesinos&#8221; en la citada reuni\u00f3n celebrada en Ciudad Lerdo, esta misma semana es un decir,\u00a0 en tanto el resto de la poblaci\u00f3n toda sigue\u00a0 pr\u00e1cticamente en la ignorancia.<\/p>\n\n\n\n<p>En estos tiempos que corren de absoluto pragmatismo, con todo y la izquierda que representa MORENA en el poder\u00a0 \u00a0 luego de &#8220;la muerte de las ideolog\u00edas&#8221; generada al t\u00e9rmino de la guerra fr\u00eda, el escenario publico donde gestar\u00a0 \u00a0 dialogo, discusi\u00f3n alguna sobre el tema del agua, que no es asunto \u00a0 de entidades gubernamentales, sino que es tema de todos, los que habitamos esta tierra, estas tierras\u00a0 en especial. Si bien y en principio nadie duda de la bondad del objetivo que \u00a0 se\u00f1ala el Proyecto &#8220;Agua Saludable para La Laguna&#8221;, es decir, proporcionar al margen de la fuente, agua\u00a0 para\u00a0 consumo humano en cantidades y calidad suficiente, el tema, cuya soluci\u00f3n dicen se encuentra en la extracci\u00f3n y potabilizaci\u00f3n de las aguas contenidas en las presas laguneras,\u00a0 cuyos caudales\u00a0 se alimentan con las lluvias que registre la Cuenca Alta del Nazas,  sin duda es\u00a0 positiva, solo que\u00a0 se deja de lado, cuidadosamente\u00a0 que el origen del abatimiento de los mantos acu\u00edferos sobre el que se\u00a0 ha venido sustentando la regi\u00f3n para tal uso, resulta que esta sobreexplotado, considerando seg\u00fan CONAGUA,\u00a0 que tales aguas solo aseguran\u00a0 ya viabilidad\u00a0 \u00a0 por no mas de 30 a\u00f1os, claro de seguir\u00a0 adelante con el modelito\u00a0 econ\u00f3mico sobre el que se sustenta la viabilidad y operaci\u00f3n de la cuenca lechera, quiz\u00e1s la mas numerosa\u00a0 e importante de todo el pa\u00eds.<\/p>\n\n\n\n<p>Silencio sepulcral de parte de los representantes y voceros del sector privado del ramo agropecuario, detentadores y sostenedores de tal modelo \u00a0 cuyo personero mas  importante, a veces\u00a0 visible es\u00a0 el Ingeniero Eduardo Tricio Haro, \u00a0 que ha comprometido\u00a0 a nombre del sector\u00a0 la entrega de 59 millones de metros c\u00fabicos de agua, de los 169 mil\u00a0 que dice CONAGUA\u00a0 involucra la demanda anual para tal proyecto. Obvio, tal \u00a0 aportaci\u00f3n no toca para nada, \u00a0 una gota de agua subterr\u00e1nea alguna, que es el quid del problema,\u00a0 sino de los vol\u00famenes\u00a0 adquiridos de las aguas de gravedad\u00a0 procedentes de las presas, cuyos derechos\u00a0 o est\u00e1n rentados o comprados definitivamente a los integrantes del sector rural, transici\u00f3n realizada\u00a0 a lo largo de los \u00faltimos \u00a0 20 a\u00f1os, y de los cuales, seg\u00fan \u00e9l mismo, solo tienen por ahora y para tal aportaci\u00f3n 20 millones de  metros c\u00fabicos&#8230;<\/p>\n\n\n\n<p>Y diremos que\u00a0&#8220;lo que no es parejo, es chipotudo&#8221;,\u00a0 en ello se disimule\u00a0 discusi\u00f3n\u00a0 publica de tal tema, que\u00a0 por ahora tiene muchas aristas, en especial, la capacidad financiera de los organismos operadores de agua en cada uno de los 9 municipios que resultaron beneficiados en el proyecto mencionado, pues los costos,\u00a0 seg\u00fan trasciende, estar\u00e1n\u00a0 a cargo\u00a0 de los ingresos municipales derivados de los cobros del servicio de agua potable y saneamiento que en su mayor\u00eda y hay que decirlo,\u00a0 est\u00e1n algo mas que en quiebra, bien porque los usuarios no\u00a0 han generado cultura de pago por tal servicio a lo largo de muchos a\u00f1os, o bien, porque\u00a0 hay laxitud en el cobro de tan importante servicio bajo lo mas diversos motivos.<\/p>\n\n\n\n<p>Al proceso\u00a0 pol\u00edtico del tema, falta pues mucho, y  con el agravante que los mas entusiastas\u00a0 con \u00e9ste\u00a0proyecto son los alcaldes que terminar\u00e1n\u00a0 sus periodos el d\u00eda 31 de diciembre del a\u00f1o en curso,\u00a0 pues ser\u00e1 a los que inicien su gesti\u00f3n \u00a0 quienes toque\u00a0 encarar tal tema, que como se ve &#8220;tiene mas picos que una custodia&#8221;.<\/p>\n\n\n\n<p>Y el virus\u00a0 del Covid sigue su tr\u00e1nsito caprichoso, indescifrable a veces.\u00a0 M\u00e9xico registr\u00f3 este d\u00eda\u00a0 22,711 nuevos contagios, \u00a0 la mas alta cantidad que se registra\u00a0 \u00a0 de manera oficial desde\u00a0 el\u00a0 inicio\u00a0 de esta pandemia. De tal cifra,\u00a0 468 corresponden a contagios en Coahuila\u00a0 a la que acompa\u00f1an 9 decesos,\u00a0 siendo Saltillo capital\u00a0 la mas afectada por ahora,\u00a0 esta oleada siembra la incertidumbre, sobre certeza alguna\u00a0 en torno al reinicio de\u00a0 actividades escolares en \u00e9ste ciclo, reto que por ahora, solo han asumido en el caso de nuestra entidad,\u00a0 algunas escuelas y facultades de la Universidad Aut\u00f3noma de Coahuila, al tiempo que al menos se acelera el proceso de vacunaci\u00f3n entre la poblaci\u00f3n \u00a0 cuyas edades est\u00e9n comprendidas entre los 18 y los 29 a\u00f1os, \u00a0 acci\u00f3n que ha tenido por suerte,\u00a0 respuesta por dem\u00e1s adecuada entre\u00a0 nuestros j\u00f3venes, al tiempo que da esperanzas de que pronto, muy pronto, se conozca vacuna alguna\u00a0 para la poblaci\u00f3n infantil&#8230;<\/p>\n\n\n\n<p> Y la vida sigue, de ah\u00ed que hay que anotar que result\u00f3 todo un \u00e9xito la Expo Tlaqueparte, realizada en las instalaciones de la Expo Feria de Torre\u00f3n, \u00a0 y cuya convocatoria y recepci\u00f3n organizativa corri\u00f3 a cargo de la Oficina de Convenciones y Visitantes de Torre\u00f3n\u00a0 al mando de\u00a0 Elias Habib\u00a0 Rodr\u00edguez Perez, quien por cierto este d\u00eda, celebro Sesi\u00f3n de sus \u00a0 miembros,\u00a0 misma que fue presidida por la titular de la Secretaria de Turismo y Pueblos M\u00e1gicos de Coahuila, Licenciada Azucena Ramos, si bien, la ausencia, de la subsecretaria Maria Eugenia Villarreal Abusaid result\u00f3 notable&#8230;<\/p>\n\n\n\n<p>Y en este mismo marco, diremos que el se\u00f1or Guillermo Mart\u00ednez Avalos, l\u00edder\u00a0 de la CANIRAC-Torre\u00f3n, inaugur\u00f3\u00a0 el pasado martes, \u00a0 una\u00a0 nueva instalaci\u00f3n gastron\u00f3mica \u00a0 \u00a0 que forma parte del Grupo Pinabete, del cual es\u00a0 su\u00a0 Presidente, esta vez en la cabecera\u00a0 del municipio de Matamoros,\u00a0 apostando \u00a0 capital y recursos humano en tal tarea, esperando verse favorecido con el \u00e9xito&#8230;<\/p>\n\n\n\n<p>Y en este tema, sin duda,\u00a0 y como lo\u00a0 calific\u00f3 el Gobernador Riquelme Solis,\u00a0 la ampliaci\u00f3n de la empresa metalmec\u00e1nica FYMSA,\u00a0 abre sin duda, la esperada\u00a0 ventana de oportunidad\u00a0 para la Laguna, \u00a0 \u00a0 que extiende\u00a0 actividades\u00a0 en\u00a0 la operaci\u00f3n de aluminio y que con innovaciones \u00a0 hacen llegar ya su producci\u00f3n elaborada en\u00a0 su planta local,\u00a0 a diversas partes del pa\u00eds y del mundo, y por ahora \u00a0 dirigir\u00e1 sus esfuerzos de innovaci\u00f3n a procesar aluminio l\u00edquido, para abastecer la naciente manufactura de autom\u00f3viles el\u00e9ctricos.<\/p>\n\n\n\n<p>Bien por los \u00a0 emprendedores\u00a0 miembros de la familia Ch\u00e1vez, que aportan\u00a0 no solo el capital, sino\u00a0 los talentos y la organizaci\u00f3n necesaria para\u00a0 alcanzar tales metas&#8230;<\/p>\n\n\n\n<p>Y no se puede dar tregua alguna al Covid y sus mutaciones,\u00a0 cuando solo se nos solicita\u00a0 utilizar cubrebocas, guardar la sana distancia y lavar a manos\u00a0 intensivamente. Aportemos lo que nos corresponde, hay que atajar\u00a0 la proliferaci\u00f3n de la pandemia\u00a0 de manera voluntaria,\u00a0 pues\u00a0 pagar\u00a0 mas de ochocientos pesos de multa por tal falta, resultar\u00e1 una\u00a0 cara lecci\u00f3n para\u00a0 quien \u00a0 insista en ser omiso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1De nueva cuenta! Se anuncia la presencia de Andr\u00e9s Manuel L\u00f3pez Obrador,\u00a0 en La Laguna, si bien no se sabe con certeza\u00a0 la agenda a que habr\u00e1 de ce\u00f1irse tan importante presencia,\u00a0 se anticipa que el tema dominante ser\u00e1\u00a0 el de \u00a0 profundizar en el conocimiento\u00a0 general de la poblaci\u00f3n\u00a0 en torno al Proyecto &#8220;Agua Saludable para La Laguna&#8221;, \u00a0 que hasta hoy solo\u00a0 es del conocimiento integro\u00a0de algunos, no&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-3862","post","type-post","status-publish","format-standard","hentry","category-aqui-laguna","wpcat-8-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=3862"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3862\/revisions"}],"predecessor-version":[{"id":3863,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/3862\/revisions\/3863"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=3862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=3862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=3862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}