{"id":4567,"date":"2021-09-21T19:03:12","date_gmt":"2021-09-22T00:03:12","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=4567"},"modified":"2021-09-21T19:03:12","modified_gmt":"2021-09-22T00:03:12","slug":"llega-a-coahuila-el-primer-frente-frio-de-la-temporada","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/09\/21\/llega-a-coahuila-el-primer-frente-frio-de-la-temporada\/","title":{"rendered":"LLEGA A COAHUILA EL PRIMER FRENTE FR\u00cdO DE LA TEMPORADA."},"content":{"rendered":"\n<p>\u00b7\u00a0<strong><em>Originar\u00e1 lluvias fuertes, descargas el\u00e9ctricas y posible ca\u00edda de granizo, rachas de viento fuertes con probabilidad para la formaci\u00f3n de torbellinos.<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 21 de Septiembre de 2021.- La Subsecretar\u00eda de Protecci\u00f3n Civil del Estado (PC) inform\u00f3 que este d\u00eda, el ingreso del primer frente fr\u00edo de la temporada sobre el norte y noreste de M\u00e9xico, interaccionar\u00e1 con un canal de baja presi\u00f3n en el noreste y oriente del territorio nacional, originando lluvias fuertes a puntuales muy fuertes, descargas el\u00e9ctricas y posible ca\u00edda de granizo, adem\u00e1s de rachas de viento fuertes con probabilidad para la formaci\u00f3n de torbellinos en Coahuila.<\/p>\n\n\n\n<p>Para el d\u00eda de hoy se espera un ambiente fresco por la ma\u00f1ana y temperaturas fr\u00edas en zonas monta\u00f1osas, as\u00ed como ambiente c\u00e1lido por la tarde, con temperaturas calurosas.<\/p>\n\n\n\n<p>Adem\u00e1s de pronostican lluvias fuertes con puntuales muy fuertes (50 a 75 mm), mismas que podr\u00edan acompa\u00f1arse de descargas el\u00e9ctricas, vientos fuertes y ca\u00edda de granizo que podr\u00edan generar deslaves e inundaciones.<\/p>\n\n\n\n<p>El Servicio Meteorol\u00f3gico Nacional se\u00f1al\u00f3 que se espera viento con rachas de 60 a 70 km\/h con posible formaci\u00f3n de torbellinos en la Regi\u00f3n Norte del estado.<\/p>\n\n\n\n<p>Ante el pron\u00f3stico, Protecci\u00f3n Civil del Estado, en coordinaci\u00f3n con las Unidades Municipales de Protecci\u00f3n Civil, se encuentran en vigilancia meteorol\u00f3gica por las lluvias que se pudieran tener durante los pr\u00f3ximos d\u00edas, por lo que se exhorta a la poblaci\u00f3n a tomar precauciones y estar atentos a los avisos que emita el Servicio Meteorol\u00f3gico Nacional (SMN).<\/p>\n\n\n\n<p>PC emiti\u00f3 las siguientes recomendaciones:<\/p>\n\n\n\n<p><strong>EN TU VIVIENDA<\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Cierra y asegura puertas, ventanas o toldos.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Retira todos aquellos objetos que puedan caer a la calle y provocar un accidente.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Si los vidrios de las ventanas no son tan fuertes, coloca cinta adhesiva transparente en la parte interior para evitar que al romperse los vidrios provoquen da\u00f1os.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Evita salir de casa si no es necesario.<\/p>\n\n\n\n<p><strong>EN LA CALLE O EL CAMPO<\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Al\u00e9jate de cornisas, muros o \u00e1rboles que puedan llegar a desprenderse.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Toma precauciones delante de edificaciones en construcci\u00f3n o en mal estado.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Abstente de subir andamios sin las adecuadas medidas de protecci\u00f3n.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;No te protejas del viento en zonas pr\u00f3ximas a muros, \u00e1rboles o edificios en mal estado o en construcci\u00f3n.<\/p>\n\n\n\n<p><strong>SI EST\u00c1S CONDUCIENDO<\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ten precauci\u00f3n, ya que son frecuentes los cortes en v\u00edas por ca\u00edda de \u00e1rboles y cables el\u00e9ctricos.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Conduce con precauci\u00f3n debido a la posibilidad de la formaci\u00f3n de nubes de polvo.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Si tu auto se ve afectado por la fuerza que el viento ejerce sobre \u00e9l, evita los rebases y ten precauci\u00f3n en los cruces y puentes.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Conduce con el m\u00e1ximo de precauci\u00f3n, disminuyendo la velocidad y con las luces de cruce y ordinarias encendidas si la visibilidad es escasa.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ten precauci\u00f3n al momento de cruzar con otros veh\u00edculos, rebasar, pasar por puentes, baches u otros hundimientos, ya que la fuerza que ejerce el viento en el veh\u00edculo se ve alterada.<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Al conducir, presta atenci\u00f3n al momento de rebasar un veh\u00edculo de carga pesada, ya que puede hacer alg\u00fan movimiento imprevisto.<\/p>\n\n\n\n<p>Mant\u00e9ngase informado por los medios oficiales de comunicaci\u00f3n y atento a los avisos que emita el Servicio Meteorol\u00f3gico Nacional y la Subsecretar\u00eda de Protecci\u00f3n Civil de Coahuila.<\/p>\n\n\n\n<p>Ante cualquier emergencia, la ciudadan\u00eda puede llamar al 911.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0Originar\u00e1 lluvias fuertes, descargas el\u00e9ctricas y posible ca\u00edda de granizo, rachas de viento fuertes con probabilidad para la formaci\u00f3n de torbellinos. Saltillo, Coahuila de Zaragoza; a 21 de Septiembre de 2021.- La Subsecretar\u00eda de Protecci\u00f3n Civil del Estado (PC) inform\u00f3 que este d\u00eda, el ingreso del primer frente fr\u00edo de la temporada sobre el norte y noreste de M\u00e9xico, interaccionar\u00e1 con un canal de baja presi\u00f3n en el noreste y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4568,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,5,54],"tags":[],"class_list":["post-4567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clima","category-coahuila","category-proteccion-civil","wpcat-27-id","wpcat-5-id","wpcat-54-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=4567"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4567\/revisions"}],"predecessor-version":[{"id":4569,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4567\/revisions\/4569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/4568"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=4567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=4567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=4567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}