{"id":4646,"date":"2021-09-26T20:26:58","date_gmt":"2021-09-27T01:26:58","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=4646"},"modified":"2021-09-26T20:26:58","modified_gmt":"2021-09-27T01:26:58","slug":"aqui-laguna-67","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/09\/26\/aqui-laguna-67\/","title":{"rendered":"Aqu\u00ed Laguna."},"content":{"rendered":"\n<p>\u00a17 a\u00f1os!\u00a0 S\u00ed, son ya siete a\u00f1os que hoy se alcanzan\u00a0 \u00e9ste d\u00eda, en la que\u00a0 las familias de\u00a0al menos 40 j\u00f3venes estudiantes de la escuela Normal Rural de Ayotzinapa, Guerrero, pues a la fecha, solo tres de los integrantes de este desafortunado grupo de estudiantes, han podido ser identificados,\u00a0 de manera oficial por las muy diversas autoridades que han tenido a su cargo y encargo, dar con su paradero, alcanzar su identificaci\u00f3n plena, se\u00f1alar y detener a los posibles responsables y mas aun, detenerlos y presentarlos ante la justicia, as\u00ed como poder dar la cristiana sepultura\u00a0 a su restos, o tambi\u00e9n, de  ser\u00a0 posible una utop\u00eda, encontrarlos vivos, como exigen en sus mantas de protesta\u00a0 sus familias. En este prolongado \u00ednter, el caso\u00a0 ha servido para desmontar la p\u00edrrica realidad que exhibe\u00a0 nuestro precario sistema de\u00a0 impartici\u00f3n de justicia, si bien no en todas las entidades del pa\u00eds,\u00a0 s\u00ed en su mayor\u00eda,\u00a0 en las que se muestra no solo la\u00a0 fragilidad del mismo, la impericia,\u00a0 adem\u00e1s de los intereses involucrados en que est\u00e1 la verdad, cuyo misterio\u00a0 ha envenenado y envenena al pa\u00eds, por dura de digerir que sea, salga a flote, pues al parecer se\u00a0 ha\u00a0 constitu\u00eddo en un aut\u00e9ntico\u00a0 fruto podrido, cuya putrefacci\u00f3n amenaza seguir afectando al cuerpo vivo de la naci\u00f3n, que incluso ante el cambio de un r\u00e9gimen no logra\u00a0 ser visible del todo \u00a0 y con ello se haga susceptible de ser extirpado. De ah\u00ed que ante tales hechos y los casi nulos avances en la investigaci\u00f3n a cargo de la Comisi\u00f3n de la Verdad\u00a0 que para el caso fuera creada por Andr\u00e9s Manuel L\u00f3pez Obrador, sus resultados sean hoy por hoy tan exiguos, y que su titular Alejandro Encinas\u00a0 se encuentra ya tanto o mas cansado que el hoy exprocurador\u00a0 Jes\u00fas Murillo Karam, el primer responsable de la investigaci\u00f3n federal que obligadamente tuvo que\u00a0 enfrentar el r\u00e9gimen de Enrique Pe\u00f1a Nieto y que seg\u00fan expertos, caso con el cual \u00a0 inicia el principio del fin\u00a0 de\u00a0 los reg\u00edmenes\u00a0 neoliberales\u00a0 en especial, el del ultimo\u00a0 a cargo del priista Pe\u00f1a Nieto\u00a0 y que hoy por hoy ante los magros resultados obtenidos por\u00a0 el presente, mas all\u00e1 de que se eche a bajo\u00a0 la versi\u00f3n de &#8220;la verdad hist\u00f3rica&#8221; laboriosamente construida\u00a0 para\u00a0 enterrar parece, literal y figuradamente\u00a0 la verdadera g\u00e9nesis\u00a0 de\u00a0 esta tragedia\u00a0 \u00a0 y con ella se desvanezca \u00a0 para los deudos la posibilidad\u00a0 de alcanzar justicia, as\u00ed como la paz que ya merecen sus conciencias.<\/p>\n\n\n\n<p>Hoy \u00e9ste d\u00eda calles y plazas de diversas ciudades del pa\u00eds, ser\u00e1n el escenario que agotan las familias de los desaparecidos, que imbatibles, cargan sobre sus hombros y sus vidas, la inconmensurable p\u00e9rdida de sus hijos, as\u00ed\u00a0 sea que en ello\u00a0 vaya la duda, la sospecha sobre cuanto tiene que ver con ello, no solo las autoridades y elementos\u00a0 de las fuerzas\u00a0 de polic\u00eda el nivel municipal, o federal, o estatal, sino de elementos corruptos y corrompidos\u00a0 que \u00a0 hubieran formado parte de las H. Fuerzas militares ah\u00ed destacamentadas,\u00a0 en el \u00e1rea de Guerrero donde su ubica la ciudad de Iguala, Cocula y sus alrededores.<\/p>\n\n\n\n<p>La duda, como se ha expuesto ya a lo largo de este doloroso recorrido de las familias que buscan a sus seres queridos, se ha externado ya, resta pues\u00a0 conocer de la respuesta que el Estado mexicano aporte sobre ello, deslindando\u00a0 injerencia alguna, si as\u00ed lo es, en tal\u00a0 caso&#8230;<\/p>\n\n\n\n<p>Toda una experiencia de orden intelectual\u00a0 y emocional\u00a0 result\u00f3\u00a0 ser, para\u00a0 quienes hayan asistido a la ceremonia celebrada el pasado s\u00e1bado, al\u00a0 Auditorio del Centro Cultural\u00a0 Braulio\u00a0 Fern\u00e1ndez Aguirre\u00a0 ubicado en la Ciudad\u00a0 Universitaria\u00a0 de la UAdeC, en Torre\u00f3n habilitado como Recinto desde el cual, la comunidad universitaria, testific\u00f3 la designaci\u00f3n que como M\u00e1ster Ad Vitam, al ingeniero Adolfo Orive Bellinger,\u00a0 el mas alto grado y honor acad\u00e9mico que\u00a0 la M\u00e1xima Casa de Estudios de Coahuila\u00a0 concede a quienes\u00a0 \u00a0 han sido relevantes por sus aportaciones a la academia\u00a0 o al servicio\u00a0 de la sociedad\u00a0 como es el caso de quien es considerado\u00a0 por sus pares, \u00a0 a nivel nacional, como uno de las mas destacados promotores organizador \u00a0 y\u00a0 orientador de\u00a0 organizaciones sociales\u00a0 campesinas, sindicatos y\u00a0 colonos en este pa\u00eds, \u00a0 y cuyo testimonio de entrega\u00a0 queda plasmado en la memoria\u00a0 de quienes a su lado, dieron la lucha por conformar \u00a0 m\u00e9todos de participaci\u00f3n comunal &#8220;desde abajo&#8221; no en las c\u00fapulas\u00a0 pol\u00edticas o econ\u00f3micas, \u00a0 en especial en la d\u00e9cada de los a\u00f1os 70&#8217;s,\u00a0 y mas adelante como legislador\u00a0 \u00a0 en sus aportaciones a diversos art\u00edculos contenidos y vigentes hoy\u00a0 en nuestros leyes laborales\u00a0 y la propia\u00a0 constituci\u00f3n de las leyes laborales todo ello sin demerito de haber alcanzado una solida formaci\u00f3n intelectual y acad\u00e9mica\u00a0 por demas destacable, pues suma en su trayectoria vital,\u00a0 tres Doctorados, uno de las Universidad de Par\u00eds, otro de la Universidad de Cambridge, mas la publicaci\u00f3n de innumerables libros y ensayos \u00a0 donde deja\u00a0 huella de su solido conocimiento de la teor\u00eda marxista, sin que por ello amerite\u00a0 explicaci\u00f3n o justificaci\u00f3n alguna,\u00a0 y finca en ello el\u00a0 conocimiento de las teor\u00edas que aportara a la ciencia social y al mundo \u00a0 el marxismo, y que hoy\u00a0 con 81 a\u00f1os a cuestas, lo hace \u00a0 predecir\u00a0 que la utop\u00eda de la 4 Transformaci\u00f3n, ser solo eso, pues afirma que la misma\u00a0 no tiene futuro mas all\u00e1 del 2024, bajo el argumento y su experiencia personal de que a la fecha,\u00a0 en ninguna \u00e9poca, en ning\u00fan pa\u00eds, en ninguna civilizaci\u00f3n,\u00a0 la obra de transformaci\u00f3n social ha sido posible por la acci\u00f3n de un solo hombre, como es la pretensi\u00f3n de nuestro Presidente\u00a0 Andr\u00e9s Manuel L\u00f3pez Obrador, pues en tanto que el individuo no sea\u00a0 el sujeto de\u00a0 su historia y de la historia nacional, eso no ser\u00e1 posible.<\/p>\n\n\n\n<p>&#8220;No puedo aceptar&#8221;, dice, &#8220;que una sola persona por mas que sea Presidente de la Rep\u00fablica y por mas que tenga buenas intenciones, no hay manera, la historia nos los dice que no hay manera de que una sola persona pueda transformar la realidad de toda una naci\u00f3n. Eso es imposible, no se ha hecho jam\u00e1s en la historia&#8221;. Tal opini\u00f3n\u00a0 de tan calificado intelectual, acad\u00e9mico y organizador social, como es el caso del PHD Adolfo Orive, pesa.<\/p>\n\n\n\n<p>En\u00a0 este evento, imposible no recordar aquello de que &#8220;honrar, honra&#8221; y esto alcanza sin duda a los afanes que en \u00a0 materia del plus que da\u00a0 la\u00a0 UAdeC\u00a0 \u00a0 y su Rector\u00a0 Salvador Hern\u00e1ndez V\u00e9lez \u00a0 con este acto&#8230;<\/p>\n\n\n\n<p>Alica\u00eddos,\u00a0 pensativos se encuentran dos que tres de quienes dicen aspiran a ser considerados por el\u00a0 alcalde electo\u00a0 Rom\u00e1n Alberto Cepeda, como titulares de la Tesorer\u00eda Municipal a partir del primero de enero del a\u00f1o pr\u00f3ximo. Con todo y que administrar\u00a0 poco mas de tres mil millones de pesos, ingresos estimados \u00a0 como recaudaci\u00f3n en este municipio capital de la Laguna, parecen ser suma mas que interesante, no dejan de recordar los destinos que\u00a0 registran\u00a0 en las administraciones priistas, sus dos \u00faltimos ocupantes en tal cargo, es decir, Pablo Ch\u00e1vez Rosique, que con todo y que constituy\u00f3 un vendaval, verdadera\u00a0 ave de tempestades, es fecha aun que no logra finiquitar\u00a0 el proceso judicial que se\u00a0 se\u00a0 instruy\u00f3 a ra\u00edz de\u00a0 las diferencias registradas por el cobro del famoso Impuesto Sobre Traslados de Dominio, una vez que para\u00a0 \u00a0 cobrarlos una omisi\u00f3n\u00a0 de una firma en el Decreto que los autoriz\u00f3 \u00a0 por parte del Congreso del Estado, que \u00a0 hicieran valer y \u00a0 hacer atajo\u00a0 por parte de algunos Notarios P\u00fablicos de la localidad\u00a0 \u00a0 gestaron el inicio del proceso judicial que aun no concluye y que le finc\u00f3 la judicatura federal, en tanto que al Contador Publico Enrique Leonardo Mota Barrag\u00e1n, contra lo esperado al t\u00e9rmino de su gesti\u00f3n, regres\u00f3 a sus actividades profesionales privadas y no mas, de ah\u00ed que se especule, por los especuladores que hoy\u00a0 por\u00a0 hoy con todo y pandemia\u00a0 abundan, en que tal encargo pudiera quedar en manos, bien de Javier Lechuga o tambi\u00e9n de Javier Herrera Arroyo profesionales de la contadur\u00eda altamente\u00a0 considerados en la actual administraci\u00f3n estatal y es precisamente por ello que se afirma, pudieran no tener posibilidades\u00a0 de retornar a Torre\u00f3n con tal encargo&#8230;<\/p>\n\n\n\n<p>Y en tanto y mientras llega el 3 de octubre pr\u00f3ximo, en la regi\u00f3n siguen con altibajos en los\u00a0 procesos de vacunaci\u00f3n masiva contra el Covid, esper\u00e1ndose con expectaci\u00f3n la que corresponda la aplicaci\u00f3n del ant\u00edgeno a menores de\u00a0 18 a\u00f1os, de ah\u00ed que el resto de la poblaci\u00f3n deber\u00e1 seguir al pie de la letra las medidas de pevenci\u00f3n vigentes&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a17 a\u00f1os!\u00a0 S\u00ed, son ya siete a\u00f1os que hoy se alcanzan\u00a0 \u00e9ste d\u00eda, en la que\u00a0 las familias de\u00a0al menos 40 j\u00f3venes estudiantes de la escuela Normal Rural de Ayotzinapa, Guerrero, pues a la fecha, solo tres de los integrantes de este desafortunado grupo de estudiantes, han podido ser identificados,\u00a0 de manera oficial por las muy diversas autoridades que han tenido a su cargo y encargo, dar con su paradero,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-4646","post","type-post","status-publish","format-standard","hentry","category-aqui-laguna","wpcat-8-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=4646"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4646\/revisions"}],"predecessor-version":[{"id":4647,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4646\/revisions\/4647"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=4646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=4646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=4646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}