{"id":4807,"date":"2021-10-04T18:40:42","date_gmt":"2021-10-04T23:40:42","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=4807"},"modified":"2021-10-04T18:40:43","modified_gmt":"2021-10-04T23:40:43","slug":"reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-179","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/10\/04\/reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-179\/","title":{"rendered":"REPORTE COAHUILA DEL PLAN ESTATAL DE PREVENCI\u00d3N Y CONTROL COVID-19."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 4 de Octubre del 2021.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa:<\/p>\n\n\n\n<p>1.- Al d\u00eda de hoy se registran 57 nuevos casos en Coahuila, incluidas 3 defunciones.<\/p>\n\n\n\n<p>DEFUNCIONES<\/p>\n\n\n\n<p>M\u00daZQUIZ<\/p>\n\n\n\n<p>Hombre de 62 a\u00f1os (caso ya reportado)<\/p>\n\n\n\n<p>SALTILLO<\/p>\n\n\n\n<p>Mujer de 65 a\u00f1os (caso ya reportado)<\/p>\n\n\n\n<p>TORRE\u00d3N<\/p>\n\n\n\n<p>Mujer de 74 a\u00f1os (caso ya reportado)<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE NUEVOS CASOS<\/p>\n\n\n\n<p>24 SALTILLO<\/p>\n\n\n\n<p>16 TORRE\u00d3N<\/p>\n\n\n\n<p>4 SAN PEDRO<\/p>\n\n\n\n<p>3 MONCLOVA<\/p>\n\n\n\n<p>2 MATAMOROS&nbsp;<\/p>\n\n\n\n<p>1 ACU\u00d1A<\/p>\n\n\n\n<p>1 CUATRO CI\u00c9NEGAS<\/p>\n\n\n\n<p>1 FRANCISCO I. MADERO<\/p>\n\n\n\n<p>1 FRONTERA<\/p>\n\n\n\n<p>1 RAMOS ARIZPE<\/p>\n\n\n\n<p>1 SABINAS<\/p>\n\n\n\n<p>1 SAN BUENAVENTURA<\/p>\n\n\n\n<p>1 VIESCA<\/p>\n\n\n\n<p>2.- Existen AHORA en Coahuila 1,591 casos activos de COVID &#8211; 19.<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE CASOS ACTIVOS<\/p>\n\n\n\n<p>-Saltillo 504<\/p>\n\n\n\n<p>-Torre\u00f3n 327<\/p>\n\n\n\n<p>-Monclova 88<\/p>\n\n\n\n<p>-San Pedro 76<\/p>\n\n\n\n<p>-M\u00fazquiz 69<\/p>\n\n\n\n<p>-Francisco I. Madero 57<\/p>\n\n\n\n<p>-Sabinas 56<\/p>\n\n\n\n<p>-Parras de la Fuente 49<\/p>\n\n\n\n<p>-Ramos Arizpe 48<\/p>\n\n\n\n<p>-Piedras Negras 48<\/p>\n\n\n\n<p>-Frontera 42<\/p>\n\n\n\n<p>-Cuatro Ci\u00e9negas 41<\/p>\n\n\n\n<p>-Matamoros 37<\/p>\n\n\n\n<p>-Acu\u00f1a 34<\/p>\n\n\n\n<p>-San Juan de Sabinas 29<\/p>\n\n\n\n<p>-Arteaga 23<\/p>\n\n\n\n<p>-San Buenaventura 18<\/p>\n\n\n\n<p>-Casta\u00f1os 13<\/p>\n\n\n\n<p>-Nava 8<\/p>\n\n\n\n<p>-Villa Uni\u00f3n 6<\/p>\n\n\n\n<p>-Allende 3<\/p>\n\n\n\n<p>-Viesca 3<\/p>\n\n\n\n<p>-Nadadores 2<\/p>\n\n\n\n<p>-General Cepeda 2<\/p>\n\n\n\n<p>-Sacramento 2<\/p>\n\n\n\n<p>-Lamadrid 2<\/p>\n\n\n\n<p>-Guerrero 1<\/p>\n\n\n\n<p>-Ocampo 1<\/p>\n\n\n\n<p>-Jim\u00e9nez 1<\/p>\n\n\n\n<p>-Morelos 1<\/p>\n\n\n\n<p>-Hidalgo 0<\/p>\n\n\n\n<p>-Progreso 0<\/p>\n\n\n\n<p>-Escobedo 0<\/p>\n\n\n\n<p>-Zaragoza 0<\/p>\n\n\n\n<p>-Ju\u00e1rez 0<\/p>\n\n\n\n<p>-Candela 0<\/p>\n\n\n\n<p>-Abasolo 0<\/p>\n\n\n\n<p>-Sierra Mojada 0<\/p>\n\n\n\n<p>3.- Al d\u00eda de hoy, se contabilizan en Coahuila EN TOTAL 91,516 casos, incluidos 7,166 decesos.<\/p>\n\n\n\n<p>4.- HOSPITALIZADOS: 184 (Se incluyen casos sospechosos y confirmados)<\/p>\n\n\n\n<p>Saltillo 80<\/p>\n\n\n\n<p>Torre\u00f3n 58<\/p>\n\n\n\n<p>Monclova 16<\/p>\n\n\n\n<p>San Juan de Sabinas 11<\/p>\n\n\n\n<p>Acu\u00f1a 10<\/p>\n\n\n\n<p>Piedras Negras 9<\/p>\n\n\n\n<p>5.- TOTAL DE RECUPERADOS: 82,759<\/p>\n\n\n\n<p>21,088 SALTILLO<\/p>\n\n\n\n<p>18,034 TORRE\u00d3N<\/p>\n\n\n\n<p>7,806 MONCLOVA<\/p>\n\n\n\n<p>7,419 PIEDRAS NEGRAS<\/p>\n\n\n\n<p>3,938 ACU\u00d1A<\/p>\n\n\n\n<p>2,567 SAN PEDRO<\/p>\n\n\n\n<p>2,576 SABINAS<\/p>\n\n\n\n<p>2,180 M\u00daZQUIZ<\/p>\n\n\n\n<p>2,001 SAN JUAN DE SABINAS<\/p>\n\n\n\n<p>1,939 FRANCISCO I. MADERO<\/p>\n\n\n\n<p>1,851 FRONTERA<\/p>\n\n\n\n<p>1,803 PARRAS DE LA FUENTE<\/p>\n\n\n\n<p>1,622 RAMOS ARIZPE<\/p>\n\n\n\n<p>1,454 MATAMOROS&nbsp;<\/p>\n\n\n\n<p>1,031 CUATRO CI\u00c9NEGAS<\/p>\n\n\n\n<p>977 ALLENDE<\/p>\n\n\n\n<p>849 NAVA<\/p>\n\n\n\n<p>540 CASTA\u00d1OS<\/p>\n\n\n\n<p>485 SAN BUENAVENTURA<\/p>\n\n\n\n<p>435 ZARAGOZA&nbsp;<\/p>\n\n\n\n<p>346 VILLA UNI\u00d3N<\/p>\n\n\n\n<p>239 MORELOS<\/p>\n\n\n\n<p>222 SACRAMENTO<\/p>\n\n\n\n<p>211 OCAMPO<\/p>\n\n\n\n<p>244 ARTEAGA<\/p>\n\n\n\n<p>153 LAMADRID<\/p>\n\n\n\n<p>166 GENERAL CEPEDA<\/p>\n\n\n\n<p>138 NADADORES<\/p>\n\n\n\n<p>106 VIESCA<\/p>\n\n\n\n<p>74 SIERRA MOJADA<\/p>\n\n\n\n<p>71 JIM\u00c9NEZ<\/p>\n\n\n\n<p>44 PROGRESO<\/p>\n\n\n\n<p>41 CANDELA&nbsp;<\/p>\n\n\n\n<p>28 ESCOBEDO<\/p>\n\n\n\n<p>28 GUERRERO<\/p>\n\n\n\n<p>23 JU\u00c1REZ<\/p>\n\n\n\n<p>21 HIDALGO&nbsp;<\/p>\n\n\n\n<p>9 ABASOLO<\/p>\n\n\n\n<p>6.- El Gobierno de Coahuila recomienda a las familias evitar salir a lugares de alta concurrencia.&nbsp; Si es necesario, acudir a aquellos ubicados al aire libre.<\/p>\n\n\n\n<p>Privilegiar aquellos que cumplen con los protocolos establecidos por los Subcomit\u00e9s Regionales de Salud.<\/p>\n\n\n\n<p>7.- Se exhorta a aquellos (as) ciudadanos (as) que tengan que salir a la calle USAR CUBREBOCAS.<\/p>\n\n\n\n<p>Su uso es OBLIGATORIO.<\/p>\n\n\n\n<p>8.- Con la finalidad de fortalecer el sistema inmunol\u00f3gico se sugiere a las familias llevar una alimentaci\u00f3n balanceada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 4 de Octubre del 2021.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa: 1.- Al d\u00eda de hoy se registran 57 nuevos casos en Coahuila, incluidas 3 defunciones. DEFUNCIONES M\u00daZQUIZ Hombre de 62 a\u00f1os (caso ya reportado) SALTILLO Mujer de 65 a\u00f1os (caso ya reportado)&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-4807","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-covid","wpcat-5-id","wpcat-4-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=4807"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4807\/revisions"}],"predecessor-version":[{"id":4808,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4807\/revisions\/4808"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=4807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=4807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=4807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}