{"id":4854,"date":"2021-10-06T18:28:11","date_gmt":"2021-10-06T23:28:11","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=4854"},"modified":"2021-10-06T18:28:12","modified_gmt":"2021-10-06T23:28:12","slug":"coahuila-reconocido-por-sus-vinos-a-nivel-nacional-listo-el-cuarto-festival-del-vino-gastronomia-y-arte","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/10\/06\/coahuila-reconocido-por-sus-vinos-a-nivel-nacional-listo-el-cuarto-festival-del-vino-gastronomia-y-arte\/","title":{"rendered":"COAHUILA, RECONOCIDO POR SUS VINOS A NIVEL NACIONAL: LISTO EL CUARTO FESTIVAL DEL VINO, GASTRONOM\u00cdA Y ARTE."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>\u00a0Invitan Vin\u00edcola Cuatro \u00c1ngeles y Turismo Estatal al evento que se llevar\u00e1 a cabo 12 y 13 de Noviembre, a partir de las 19:00 horas en el Centro de Convenciones de Torre\u00f3n<\/em><\/strong><\/p>\n\n\n\n<p>Torre\u00f3n, Coahuila de Zaragoza; a 6 de Octubre de 2021.- El Gobierno de Coahuila, a trav\u00e9s de la Secretar\u00eda de Turismo y Desarrollo de Pueblos M\u00e1gicos, se une a la convocatoria que hace la Vin\u00edcola Cuatro \u00c1ngeles para participar en el 4to. Festival del Vino, la Gastronom\u00eda y el Arte.<\/p>\n\n\n\n<p>Azucena Ramos Ramos, Secretaria de Turismo y Desarrollo de Pueblos M\u00e1gicos, reconoci\u00f3 a nombre del gobernador Miguel \u00c1ngel Riquelme Sol\u00eds el esfuerzo que cada sector ha realizado para seguir avanzando.<\/p>\n\n\n\n<p>Destac\u00f3 que Coahuila es reconocida por tener m\u00e1s de 1,200 medallas en reconocimientos por sus vinos, lo que representa m\u00e1s del 40 por ciento a nivel nacional.<\/p>\n\n\n\n<p>Esta vin\u00edcola, sostuvo que pronto se integrar\u00e1 a la Ruta de Vinos &amp; Dinos, por lo que es un honor sumarse a la cuarta edici\u00f3n de este evento que conjuga el \u201cvino, la gastronom\u00eda y el arte\u201d.<\/p>\n\n\n\n<p>Reconoci\u00f3 que desde hace m\u00e1s de 400 a\u00f1os el vino es una generosa tradici\u00f3n en el estado, y en los \u00faltimos a\u00f1os su producci\u00f3n se ha ido posicionado fuertemente en el mercado nacional e internacional.<\/p>\n\n\n\n<p>\u201cEl Turismo Enol\u00f3gico se ha convertido en un s\u00edmbolo de identidad, y para varios municipios representa una valiosa oportunidad de desarrollo\u201d.<\/p>\n\n\n\n<p>Ramos Ramos coment\u00f3 que no ha sido tarea f\u00e1cil recuperar la actividad tur\u00edstica, apenas ayer termin\u00f3 la Feria de Torre\u00f3n, evento que se llev\u00f3 a cabo con todos los protocolos sanitarios y que demostr\u00f3 que s\u00ed se pueden celebrar eventos seguros.<\/p>\n\n\n\n<p>Por lo que espera que pronto se regrese a Sem\u00e1foro Verde en la entidad: \u201cPara continuar con m\u00e1s eventos que nos permitan vivir mejores experiencias y disfrutar de lo mejor de nuestra gastronom\u00eda y cultura\u201d.<\/p>\n\n\n\n<p>Por su parte, el Director General de Vin\u00edcola Cuatro \u00c1ngeles, \u00c1ngel Morales, agradeci\u00f3 al Gobierno de Coahuila: \u201cNos ha hecho sentir que estamos muy cobijados y quiero mandar un saludo a nuestro amigo el gobernador Miguel \u00c1ngel Riquelme Sol\u00eds\u201d.<\/p>\n\n\n\n<p>El exhorto, con este evento, es para que la poblaci\u00f3n se una al Concurso de Talento Lagunero en baile, canto, actos de magia, acrobacia, malabares, comedia, instrumentos musicales y m\u00e1s, donde el invitado especial como jurado ser\u00e1 Fernando Sujo, ganador de la Voz M\u00e9xico 2020.<\/p>\n\n\n\n<p>El prop\u00f3sito es estimular a los nuevos valores de la Comarca Lagunera, aunque no est\u00e1 limitado a s\u00f3lo personas del estado, sino que pueden participar de otras partes del Pa\u00eds.<\/p>\n\n\n\n<p>El primer lugar se llevar\u00e1 10 mil pesos; el segundo 3 mil, y el tercer lugar 1 mil 500 pesos, adem\u00e1s de la posibilidad de ganarse un viaje a Mazatl\u00e1n.<\/p>\n\n\n\n<p>Recalc\u00f3 que en este programa se fusionan el vino, la gastronom\u00eda y el arte, mismo que ser\u00e1 los d\u00edas 12 y 13 de noviembre a partir de las 19:00 horas en el Centro de Convenciones de Torre\u00f3n.<\/p>\n\n\n\n<p>Aqu\u00ed, quienes gusten asistir podr\u00e1n disfrutar de muestras gastron\u00f3micas de los mejores restaurantes de la regi\u00f3n, \u201cde maridajes sin igual\u201d.<\/p>\n\n\n\n<p>La participaci\u00f3n en el concurso puede darse de forma individual o en grupo, no hay l\u00edmite de edad ni tem\u00e1tica en espec\u00edfico.<\/p>\n\n\n\n<p>Se valorar\u00e1 la originalidad, grado art\u00edstico e impacto de entretenimiento.<\/p>\n\n\n\n<p>La idea es que a partir de ya se env\u00ede un video con tu actuaci\u00f3n al 871 174 9071 o al correo:&nbsp;<a href=\"mailto:ventas.cuatroangeles@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">ventas.cuatroangeles@gmail.com<\/a>&nbsp;donde incluyas tu nombre, edad, domicilio y tel\u00e9fono.<\/p>\n\n\n\n<p>\u201cSi resultas seleccionado se te enviar\u00e1 una notificaci\u00f3n a los cinco d\u00edas h\u00e1biles despu\u00e9s de que enviaste tu material\u201d, detall\u00f3.<\/p>\n\n\n\n<p>Para acudir como espectador, los costos son: por persona 650 y por pareja 1,100 pesos.<\/p>\n\n\n\n<p>\u201cPara adquirir tu o tus boletos, puedes acudir a Vin\u00edcola Cuatro \u00c1ngeles ubicada en Due\u00f1ez Orozco #80, en la Cd. Industrial de Torre\u00f3n de 10:00 a 18:00 horas o bien comunicarte al tel\u00e9fono 871 750 5530\u201d.<\/p>\n\n\n\n<p>A la presentaci\u00f3n ante medios de comunicaci\u00f3n tambi\u00e9n acudieron El\u00edas Habib Rodr\u00edguez P\u00e9rez, presidente de la Oficina de Convenciones y Visitantes de Torre\u00f3n; Guillermo Mart\u00ednez \u00c1vila, presidente de la C\u00e1mara Nacional de la Industria de Restaurantes y Alimentos Condimentados; Omar Lozano Cant\u00fa, Rector de la UAL, y Fernando Sujo, como invitado especial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Invitan Vin\u00edcola Cuatro \u00c1ngeles y Turismo Estatal al evento que se llevar\u00e1 a cabo 12 y 13 de Noviembre, a partir de las 19:00 horas en el Centro de Convenciones de Torre\u00f3n Torre\u00f3n, Coahuila de Zaragoza; a 6 de Octubre de 2021.- El Gobierno de Coahuila, a trav\u00e9s de la Secretar\u00eda de Turismo y Desarrollo de Pueblos M\u00e1gicos, se une a la convocatoria que hace la Vin\u00edcola Cuatro \u00c1ngeles para&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,34],"tags":[],"class_list":["post-4854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-turismo","wpcat-5-id","wpcat-15-id","wpcat-34-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=4854"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4854\/revisions"}],"predecessor-version":[{"id":4856,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4854\/revisions\/4856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/4855"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=4854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=4854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=4854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}