{"id":4956,"date":"2021-10-12T19:13:27","date_gmt":"2021-10-13T00:13:27","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=4956"},"modified":"2021-10-12T19:13:28","modified_gmt":"2021-10-13T00:13:28","slug":"invierten-estado-y-municipio-75-mdp-en-la-linea-verde-de-saltillo","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/10\/12\/invierten-estado-y-municipio-75-mdp-en-la-linea-verde-de-saltillo\/","title":{"rendered":"INVIERTEN ESTADO Y MUNICIPIO 75 MDP EN LA \u2018L\u00cdNEA VERDE\u2019 DE SALTILLO."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>\u00a0El gobernador Miguel Riquelme, junto al alcalde Manolo Jim\u00e9nez,\u00a0 inauguran esta magna obra<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 12 de Octubre de 2021.- Con la finalidad de fortalecer el desarrollo de la comunidad y el tejido social, se inaugur\u00f3 este d\u00eda la \u201cL\u00ednea Verde\u201d de Saltillo, donde se invirtieron 75 millones de pesos y que beneficiar\u00e1 a 60 mil saltillenses de las colonias Miguel Hidalgo, Vicente Guerrero, Federico Berrueto Ram\u00f3n, y dem\u00e1s sectores del sur oriente de la Capital del Estado.<\/p>\n\n\n\n<p>El gobernador Miguel \u00c1ngel Riquelme Sol\u00eds realiz\u00f3 el corte de list\u00f3n, con lo que se inaugur\u00f3 de manera formal el parque lineal en esta zona de Saltillo, donde fue acompa\u00f1ado por el Alcalde de Saltillo, Manolo Jim\u00e9nez Salinas.<\/p>\n\n\n\n<p>Riquelme Sol\u00eds destac\u00f3 la sinergia y el trabajo en equipo entre la sociedad, el Poder Ejecutivo, Legislativo y Judicial, as\u00ed como el trabajo con el Municipio, la Iniciativa Privada y el Ej\u00e9rcito Mexicano, que permiten tener a Coahuila con muy buenos resultados.<\/p>\n\n\n\n<p>\u201cEl generar un ambiente positivo en un estado como el nuestro es tarea de todas y de todos, el generar sinergia, trabajo diario, resultados, no es el trabajo de un Gobierno, es un esfuerzo de toda una sociedad dispuesta a llegar diariamente a las metas que nos proponemos\u201d, puntualiz\u00f3.<\/p>\n\n\n\n<p>Dicho trabajo, continu\u00f3 Riquelme Sol\u00eds, es el que requiere nuestra entidad para generar empleos, para tener recursos para obras como la \u201cL\u00ednea Verde\u201d y, sobre todo, para tener estabilidad, que es lo que nos ha dado en los \u00faltimos a\u00f1os un equilibrio que permite generar inversi\u00f3n y empleo.<\/p>\n\n\n\n<p>Resalt\u00f3 el trabajo realizado durante la pandemia, y se\u00f1al\u00f3 que Coahuila lleva una reactivaci\u00f3n econ\u00f3mica del 90 por ciento, que se han recuperado los empleos perdidos y se tiene la llegada de nuevas inversiones.<\/p>\n\n\n\n<p>Adem\u00e1s, invit\u00f3 a los nuevos 38 alcaldes y alcaldesas, electos y reelectos, a trabajar por la entidad y crear 38 Mandos \u00danicos para mantener la paz y tranquilidad.<\/p>\n\n\n\n<p>\u201c\u00bfCu\u00e1l es la f\u00f3rmula para tener un Coahuila seguro, para tener a nuestra entidad generando empleos? La unidad y la confianza, y eso es lo que debemos mantener y garantizar, que el 1 de enero (2022) no haya cambio de pol\u00edticas p\u00fablicas; hay cambios de actores, pero tenemos que mejorar cada uno de los 38 municipios\u201d, concluy\u00f3.<\/p>\n\n\n\n<p><strong>MEJORAR LA VIDA DE LOS CIUDADANOS<\/strong><\/p>\n\n\n\n<p>En su intervenci\u00f3n el Alcalde de Saltillo, Manolo Jim\u00e9nez Salinas, record\u00f3 que uno de sus compromisos principales fue el de mejorar la calidad de vida de los saltillenses, lo que se ve reflejado en la \u201cL\u00ednea Verde\u201d, donde destaca la suma de esfuerzos del Gobierno del Estado, Municipio e Iniciativa Privada.<\/p>\n\n\n\n<p>Dio la explicaci\u00f3n t\u00e9cnica del proyecto e inform\u00f3 que una extensi\u00f3n de casi dos kil\u00f3metros transform\u00f3 el entorno y se mejor\u00f3 la calidad de vida de cerca de 60 mil ciudadanos de las colonias Miguel Hidalgo, Vicente Guerrero y Federico Berrueto Ram\u00f3n, la que se construy\u00f3 en cinco etapas.<\/p>\n\n\n\n<p>Expuso que esta obra consta de nueva carpeta asf\u00e1ltica para andadores y vita pista circuito 3.4 kil\u00f3metros; concreto estampado en plazoleta; pasto artificial y arbolado con sistema de riego; l\u00e1mparas LED, y un sistemas de c\u00e1maras de monitoreo.<\/p>\n\n\n\n<p>Adem\u00e1s que se crearon canchas de basquetbol y futbol con pasto artificial, gradas de concreto, pista de trote, pista de skate y bicicross; as\u00ed como obras de recarpeteo, alumbrado de calles aleda\u00f1as, juegos infantiles y gimnasios urbanos.<\/p>\n\n\n\n<p>Mar\u00eda del Rosario Escalante Torres, agradeci\u00f3 a nombre de las cerca de 60 mil familias beneficiadas por esta obra, y expuso que ahora este nuevo espacio es un lugar de provecho para pasear, hacer deporte y convivir con familia y amigos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0El gobernador Miguel Riquelme, junto al alcalde Manolo Jim\u00e9nez,\u00a0 inauguran esta magna obra Saltillo, Coahuila de Zaragoza; a 12 de Octubre de 2021.- Con la finalidad de fortalecer el desarrollo de la comunidad y el tejido social, se inaugur\u00f3 este d\u00eda la \u201cL\u00ednea Verde\u201d de Saltillo, donde se invirtieron 75 millones de pesos y que beneficiar\u00e1 a 60 mil saltillenses de las colonias Miguel Hidalgo, Vicente Guerrero, Federico Berrueto Ram\u00f3n,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,60],"tags":[],"class_list":["post-4956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-saltillo","wpcat-5-id","wpcat-15-id","wpcat-60-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=4956"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4956\/revisions"}],"predecessor-version":[{"id":4958,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/4956\/revisions\/4958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/4957"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=4956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=4956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=4956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}