{"id":571,"date":"2021-02-26T17:26:24","date_gmt":"2021-02-26T23:26:24","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=571"},"modified":"2021-02-26T17:26:24","modified_gmt":"2021-02-26T23:26:24","slug":"reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-22","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/02\/26\/reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-22\/","title":{"rendered":"REPORTE COAHUILA DEL PLAN ESTATAL DE PREVENCI\u00d3N Y CONTROL COVID-19."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 26 de Febrero del 2021.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa:<\/p>\n\n\n\n<p>1.- Al momento se registran 110 nuevos casos de COVID &#8211; 19 en la entidad, incluidas 5 defunciones:<\/p>\n\n\n\n<p>ALLENDE<\/p>\n\n\n\n<p>Mujer de 70 a\u00f1os (caso ya reportado)<\/p>\n\n\n\n<p>CASTA\u00d1OS<\/p>\n\n\n\n<p>Mujer de 60 a\u00f1os (caso ya reportado)<\/p>\n\n\n\n<p>FRONTERA<\/p>\n\n\n\n<p>Hombre de 65 a\u00f1os (caso ya reportado)<\/p>\n\n\n\n<p>MONCLOVA<\/p>\n\n\n\n<p>Mujer de 73 a\u00f1os (caso ya reportado)<\/p>\n\n\n\n<p>SALTILLO<\/p>\n\n\n\n<p>Mujer de 74 a\u00f1os (caso ya reportado)<br><\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE NUEVOS CASOS<\/p>\n\n\n\n<p>35 SALTILLO<\/p>\n\n\n\n<p>18 TORRE\u00d3N<\/p>\n\n\n\n<p>14 PIEDRAS NEGRAS<\/p>\n\n\n\n<p>6 MONCLOVA<\/p>\n\n\n\n<p>6 SAN PEDRO<\/p>\n\n\n\n<p>5 ACU\u00d1A<\/p>\n\n\n\n<p>5 FRANCISCO I. MADERO<\/p>\n\n\n\n<p>4 RAMOS ARIZPE<\/p>\n\n\n\n<p>3 FRONTERA<\/p>\n\n\n\n<p>3 MATAMOROS<\/p>\n\n\n\n<p>2 CASTA\u00d1OS<\/p>\n\n\n\n<p>2 M\u00daZQUIZ<\/p>\n\n\n\n<p>1 SAN JUAN DE SABINAS<\/p>\n\n\n\n<p>1 SACRAMENTO<\/p>\n\n\n\n<p>1 ALLENDE<\/p>\n\n\n\n<p>1 LAMADRID<\/p>\n\n\n\n<p>1 NAVA<\/p>\n\n\n\n<p>1 PARRAS DE LA FUENTE<\/p>\n\n\n\n<p>1 VILLA UNI\u00d3N<br><\/p>\n\n\n\n<p>2.- Existen AHORA en Coahuila 1,015 casos activos de COVID &#8211; 19.<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE CASOS ACTIVOS<\/p>\n\n\n\n<p>-Saltillo 221<\/p>\n\n\n\n<p>-Torre\u00f3n 163<\/p>\n\n\n\n<p>-Parras de la Fuente 101<\/p>\n\n\n\n<p>-Monclova 77<\/p>\n\n\n\n<p>-Piedras Negras 71<\/p>\n\n\n\n<p>-Allende 60<\/p>\n\n\n\n<p>-San Pedro 41<\/p>\n\n\n\n<p>-Francisco I. Madero 43<\/p>\n\n\n\n<p>-Acu\u00f1a 33<\/p>\n\n\n\n<p>-Ramos Arizpe 30<\/p>\n\n\n\n<p>-Matamoros 24<\/p>\n\n\n\n<p>-Cuatro Ci\u00e9negas 22<\/p>\n\n\n\n<p>-Frontera 15<\/p>\n\n\n\n<p>-Zaragoza 11<\/p>\n\n\n\n<p>-M\u00fazquiz 10<\/p>\n\n\n\n<p>-San Juan de Sabinas 10<\/p>\n\n\n\n<p>-Sabinas 9<\/p>\n\n\n\n<p>-Sierra Mojada 9<\/p>\n\n\n\n<p>-Jim\u00e9nez 8<\/p>\n\n\n\n<p>-Casta\u00f1os 8<\/p>\n\n\n\n<p>-San Buenaventura 6<\/p>\n\n\n\n<p>-Lamadrid 6<\/p>\n\n\n\n<p>-Arteaga 5<\/p>\n\n\n\n<p>-Nava 4<\/p>\n\n\n\n<p>-Escobedo 4<\/p>\n\n\n\n<p>-Ocampo 4<\/p>\n\n\n\n<p>-Candela 3<\/p>\n\n\n\n<p>-Sacramento 3<\/p>\n\n\n\n<p>-Morelos 2<\/p>\n\n\n\n<p>-Abasolo 2<\/p>\n\n\n\n<p>-Villa Uni\u00f3n 2<\/p>\n\n\n\n<p>-Viesca 2<\/p>\n\n\n\n<p>-General Cepeda 2<\/p>\n\n\n\n<p>-Progreso 2<\/p>\n\n\n\n<p>-Nadadores 2<\/p>\n\n\n\n<p>-Ju\u00e1rez 0<\/p>\n\n\n\n<p>-Hidalgo 0<\/p>\n\n\n\n<p>-Guerrero 0<\/p>\n\n\n\n<p>3.- Al d\u00eda de hoy, se contabilizan en Coahuila EN TOTAL 66,453 casos, incluidos 5,643 decesos.<\/p>\n\n\n\n<p>4.- HOSPITALIZADOS: 180 (Se incluyen casos sospechosos y confirmados)<\/p>\n\n\n\n<p>Torre\u00f3n 63<\/p>\n\n\n\n<p>Saltillo 57<\/p>\n\n\n\n<p>Monclova 21<\/p>\n\n\n\n<p>Piedras Negras 20<\/p>\n\n\n\n<p>Acu\u00f1a 11<\/p>\n\n\n\n<p>San Juan de Sabinas 8<br><\/p>\n\n\n\n<p>5.- TOTAL DE RECUPERADOS: 59,795<\/p>\n\n\n\n<p>14,520 TORRE\u00d3N<\/p>\n\n\n\n<p>12,310 SALTILLO<\/p>\n\n\n\n<p>6,433 MONCLOVA<\/p>\n\n\n\n<p>5,712 PIEDRAS NEGRAS<\/p>\n\n\n\n<p>2,934 ACU\u00d1A<\/p>\n\n\n\n<p>2,195 SAN PEDRO<\/p>\n\n\n\n<p>1,936 SABINAS<\/p>\n\n\n\n<p>1,746 SAN JUAN DE SABINAS<\/p>\n\n\n\n<p>1,642 FRANCISCO I. MADERO<\/p>\n\n\n\n<p>1,568 M\u00daZQUIZ<\/p>\n\n\n\n<p>1,359 FRONTERA<\/p>\n\n\n\n<p>1,132 MATAMOROS<\/p>\n\n\n\n<p>848 CUATRO CI\u00c9NEGAS<\/p>\n\n\n\n<p>802 PARRAS DE LA FUENTE<\/p>\n\n\n\n<p>833 ALLENDE<\/p>\n\n\n\n<p>674 NAVA<\/p>\n\n\n\n<p>589 RAMOS ARIZPE<\/p>\n\n\n\n<p>349 ZARAGOZA<\/p>\n\n\n\n<p>328 CASTA\u00d1OS<\/p>\n\n\n\n<p>290 SAN BUENAVENTURA<\/p>\n\n\n\n<p>286 VILLA UNI\u00d3N<\/p>\n\n\n\n<p>208 SACRAMENTO<\/p>\n\n\n\n<p>206 MORELOS<\/p>\n\n\n\n<p>178 OCAMPO<\/p>\n\n\n\n<p>133 LAMADRID<\/p>\n\n\n\n<p>104 ARTEAGA<\/p>\n\n\n\n<p>98 NADADORES<\/p>\n\n\n\n<p>80 VIESCA<\/p>\n\n\n\n<p>75 GENERAL CEPEDA<\/p>\n\n\n\n<p>63 SIERRA MOJADA<\/p>\n\n\n\n<p>45 JIM\u00c9NEZ<\/p>\n\n\n\n<p>22 PROGRESO<\/p>\n\n\n\n<p>21 ESCOBEDO<\/p>\n\n\n\n<p>20 JU\u00c1REZ<\/p>\n\n\n\n<p>19 GUERRERO<\/p>\n\n\n\n<p>18 HIDALGO&nbsp;&nbsp;<\/p>\n\n\n\n<p>15 CANDELA<\/p>\n\n\n\n<p>4 ABASOLO<br><\/p>\n\n\n\n<p>6.- El Gobierno de Coahuila recuerda a las familias la necesidad de resguardarse en casa.<\/p>\n\n\n\n<p>Es importante mantener actividades de recreo para los peque\u00f1os dentro del HOGAR.<\/p>\n\n\n\n<p>NO SALIR, solo si es estrictamente necesario (actividades esenciales).<\/p>\n\n\n\n<p>7.- Se exhorta a aquellos (as) ciudadanos (as) que &#8211; por situaciones de extrema urgencia o de car\u00e1cter laboral &#8211; tengan que salir a la calle USAR CUBREBOCAS.<\/p>\n\n\n\n<p>Su uso es OBLIGATORIO.<\/p>\n\n\n\n<p>8.- Con la finalidad de fortalecer el sistema inmunol\u00f3gico se sugiere a las familias llevar una alimentaci\u00f3n balanceada.<\/p>\n\n\n\n<p>9.- Si presentas alg\u00fan malestar respiratorio acude a la unidad de salud m\u00e1s cercana o marca al 911.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 26 de Febrero del 2021.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa: 1.- Al momento se registran 110 nuevos casos de COVID &#8211; 19 en la entidad, incluidas 5 defunciones: ALLENDE Mujer de 70 a\u00f1os (caso ya reportado) CASTA\u00d1OS Mujer de 60 a\u00f1os (caso&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-571","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-covid","wpcat-5-id","wpcat-4-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=571"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/571\/revisions"}],"predecessor-version":[{"id":572,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/571\/revisions\/572"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}