{"id":5983,"date":"2021-12-02T19:16:02","date_gmt":"2021-12-03T01:16:02","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=5983"},"modified":"2021-12-02T19:16:02","modified_gmt":"2021-12-03T01:16:02","slug":"buscan-empresario-mayor-participacion-en-consejo-de-simas-torreon","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/12\/02\/buscan-empresario-mayor-participacion-en-consejo-de-simas-torreon\/","title":{"rendered":"Buscan empresario mayor participaci\u00f3n en Consejo de SIMAS-Torre\u00f3n."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila.- En coordinaci\u00f3n con el Grupo Empresarial Lagunero -GEL-,\u00a0 los integrantes del Consejo C\u00edvico \u00a0 de las Instituciones,\u00a0 pretende que\u00a0 \u00a0 en la pr\u00f3xima administraci\u00f3n municipal, fortalecer\u00a0 su \u00a0 representaci\u00f3n  en el\u00a0 SIMAS-Torre\u00f3n con el objetivo de\u00a0 alcanzar\u00a0 el mejoramiento sustancial en la prestaci\u00f3n de este importante servicio publico, para que sus responsables\u00a0 lo\u00a0 hagan con transparencia y  rindan cuentas de su\u00a0 actuaci\u00f3n.<\/p>\n\n\n\n<p>En reuni\u00f3n sostenida con los Medios, el\u00a0 Grupo Empresarial Lagunero \u00a0 encabezado por su actual vocero, Jes\u00fas de la Garza Acosta\u00a0 y el titular del Consejo C\u00edvico de las Instituciones, por su titular, Licenciado Mario Zamarripa\u00a0 dieron a conocer\u00a0 lo anterior.<\/p>\n\n\n\n<p>Para ello, el se\u00f1or Jes\u00fas de la Garza Acosta, afirm\u00f3 que,\u00a0 &#8220;estamos pidiendo que las decisiones\u00a0 que se tomen\u00a0 al interior de los Consejos de Administraci\u00f3n no solo de Simas Torre\u00f3n sino tambi\u00e9n de todos  y cada uno de los organismos operadores de\u00a0 agua en la comarca lagunera, no sean decisiones unilaterales, sino que sean consensuadas\u00a0 por toda la comunidad, y para ello, deber\u00e1 de haber una apertura de todos los alcaldes&#8221;.<\/p>\n\n\n\n<p>&#8220;Si bien los Consejos de Administraci\u00f3n\u00a0 de \u00e9stas figuras\u00a0 son aut\u00f3nomos\u00a0 y s\u00ed existen\u00a0 pero al final del d\u00eda son los\u00a0 ciudadanos quienes exigen el nivel de servicios\u00a0 que ah\u00ed se prestan&#8221;.<\/p>\n\n\n\n<p>&#8220;Con ello tambi\u00e9n se pudiera velar por la salud financiera\u00a0 de tales organismos,\u00a0 y estamos tocando la puerta de los alcaldes\u00a0 en los municipios\u00a0 donde se tenga poca participaci\u00f3n\u00a0 ciudadana en sus Consejos\u00a0 y con ello dejen entrar a gentes que est\u00e1n preocupadas\u00a0 en el desarrollo de esos sistemas operadores de agua&#8221;.<\/p>\n\n\n\n<p>Reiter\u00f3 que, &#8220;es necesaria una mayor apertura, con todo y que en el Consejo de administraci\u00f3n de estas empresas paramunicipales,\u00a0 haya un regidor como representante popular, pues debe haber mayor apertura para no\u00a0 se tomen decisiones unilaterales y haya una exigencia realmente de todos los sectores&#8221;.<\/p>\n\n\n\n<p>&#8220;Nosotros\u00a0 en voz de los empresarios,  exigimos que sea visto como consulta ciudadana en el \u00e1mbito empresarial en cada uno de estos organismos. Vamos a hacer nuestra tarea&#8221;.<\/p>\n\n\n\n<p>Preguntado, dijo que en el caso de Simas-Torre\u00f3n, &#8220;hoy en d\u00eda se tiene un consejo con 73%\u00a0 de participaci\u00f3n ciudadana\u00a0 y ante estos, rinde informes su director general&#8221;.<\/p>\n\n\n\n<p>Queremos, afirm\u00f3, &#8220;tener participaci\u00f3n en la toma de decisiones. Vamos a estar velando\u00a0 por los intereses de nuestros agremiados&#8221;\u00a0\u00a0<\/p>\n\n\n\n<p>&#8220;La figura que estamos impulsando\u00a0 es una figura participativa, pero vamos a socializar acciones\u00a0 que sean \u00a0 en beneficio de todos los\u00a0 laguneros&#8221;.<\/p>\n\n\n\n<p>&#8220;Queremos ser participes\u00a0 en estos\u00a0 Consejos que dictan \u00a0 las directrices de los mismos y evaluar con indicadores muy estrechos al Ejecutor, en este caso a su Director general&#8221;. Concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila.- En coordinaci\u00f3n con el Grupo Empresarial Lagunero -GEL-,\u00a0 los integrantes del Consejo C\u00edvico \u00a0 de las Instituciones,\u00a0 pretende que\u00a0 \u00a0 en la pr\u00f3xima administraci\u00f3n municipal, fortalecer\u00a0 su \u00a0 representaci\u00f3n en el\u00a0 SIMAS-Torre\u00f3n con el objetivo de\u00a0 alcanzar\u00a0 el mejoramiento sustancial en la prestaci\u00f3n de este importante servicio publico, para que sus responsables\u00a0 lo\u00a0 hagan con transparencia y rindan cuentas de su\u00a0 actuaci\u00f3n. En reuni\u00f3n sostenida con los Medios,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-5983","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/5983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=5983"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/5983\/revisions"}],"predecessor-version":[{"id":5984,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/5983\/revisions\/5984"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=5983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=5983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=5983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}