{"id":6009,"date":"2021-12-05T18:47:37","date_gmt":"2021-12-06T00:47:37","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=6009"},"modified":"2021-12-05T18:47:37","modified_gmt":"2021-12-06T00:47:37","slug":"con-la-firma-del-acuerdo-de-voluntades-avanza-agua-saludable-para-la-laguna-jrat","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/12\/05\/con-la-firma-del-acuerdo-de-voluntades-avanza-agua-saludable-para-la-laguna-jrat\/","title":{"rendered":"CON LA FIRMA DEL ACUERDO DE VOLUNTADES AVANZA AGUA SALUDABLE PARA LA LAGUNA: JRAT."},"content":{"rendered":"\n<p>Comarca Lagunera, Dgo., Como parte del fortalecimiento al proceso de<br>socializaci\u00f3n del proyecto Agua Saludable para La Laguna, el gobernador del<br>estado de Durango, Jos\u00e9 Rosas Aispuro Torres; el senador con licencia, Gabriel<br>Garc\u00eda Hern\u00e1ndez, y el alcalde de Lerdo, Homero Mart\u00ednez Cabrera, firmaron un<br>Acuerdo de Voluntades con cinco de los seis ejidos inconformes del M\u00f3dulo de<br>Riego III \u201cSan Jacinto-Jerusalem\u201d y encabezaron una reuni\u00f3n con productores del<br>M\u00f3dulo de Riego V \u201cBrittingham\u201d, del Distrito de Riego 017;<br>Al respecto, Jos\u00e9 Rosas Aispuro Torres, gobernador de Durango, asegur\u00f3 que se<br>avanza con Agua Saludable para La Laguna y tiene confianza de que ser\u00e1<br>ben\u00e9fico para todos, gracias al di\u00e1logo y la apertura que se ha tenido con los<br>productores, en especial con los del M\u00f3dulo de Riego III que albergaran las obras<br>hidr\u00e1ulicas.<\/p>\n\n\n\n<p>Ayer se llev\u00f3 a cabo la firma de del Acuerdo de Voluntades ante Notario P\u00fablico,<br>por parte del Gobierno de M\u00e9xico, a trav\u00e9s de la Comisi\u00f3n Nacional del Agua y la<br>Secretar\u00eda de Gobernaci\u00f3n, con el gobierno del estado de Durango, el Municipio<br>de Lerdo y los representantes de Le\u00f3n Guzm\u00e1n, Sapioriz y Juan E. Garc\u00eda.<\/p>\n\n\n\n<p>Tras la lectura del documento, cada uno de los representantes de los productores<br>de las comunidades de San Jacinto, Le\u00f3n Guzm\u00e1n, Sapioriz, Juan E. Garc\u00eda, La<br>Goma y 21 de Marzo, expusieron sus puntos de vista y decidieron firmar tres de<br>los seis representantes el Acuerdo de Voluntades; por lo que hoy se realizaron<br>Asambleas Ejidales donde se analiz\u00f3 a detalle el contenido del mismo.<\/p>\n\n\n\n<p>En su gira de trabajo por la regi\u00f3n, el mandatario estatal acompa\u00f1\u00f3 al Senador<br>Gabriel Garc\u00eda Hern\u00e1ndez a las Asambleas en los ejidos 21 de Marzo y San<br>Jacinto en el Municipio de Lerdo, en d\u00f3nde atestigu\u00f3 la Firma del Acuerdo de<br>Voluntades para llevar a cabo el programa Agua Saludable para La Laguna.<\/p>\n\n\n\n<p>Al hacer un balance del proceso de socializaci\u00f3n del proyecto, Gabriel Garc\u00eda<br>Hern\u00e1ndez indic\u00f3 que se continuar\u00e1 con el di\u00e1logo abierto en las diferentes<br>comunidades. Reiter\u00f3 que todo deber\u00e1 ser con el consenso de todas y todos, y<br>que se dar\u00e1 claridad a los productores sociales.<\/p>\n\n\n\n<p>En su mensaje el mandatario estatal manifest\u00f3 que este proyecto busca garantizar<br>la salud de los laguneros y tecnificar el campo para hacerlo m\u00e1s productivo.<br>Record\u00f3 que Agua Saludable para La Laguna significa una inversi\u00f3n cercana a los<br>11 mil millones de pesos, de los cuales dos mil ser\u00e1n para la tecnificaci\u00f3n del<br>campo \u201cesta es la inversi\u00f3n m\u00e1s grande del norte del pa\u00eds en materia h\u00eddrica del<br>Gobierno de M\u00e9xico\u201d enfatiz\u00f3.<\/p>\n\n\n\n<p>Entre los puntos principales del Acuerdo destacan: Acciones integrales para<br>atender las demandas de los seis ejidos inconformes; la entrega, en el punto de<br>control del M\u00f3dulo de Riego III \u201cSan Jacinto- Jerusalem\u201d, un total de 71.22<br>millones de metros c\u00fabicos; programa de monitoreo del caudal; los ejidos<br>firmantes manifiestan su conformidad y buena voluntad con el Acuerdo que sienta<br>las bases en la implementaci\u00f3n de Agua Saludable para La Laguna; los<br>participantes se comprometen a dirimir diferencias y controversias jur\u00eddicas en las<br>mesas de di\u00e1logo y a cumplir con la normatividad aplicable vigente en la materia.<br>Por otra parte, Jos\u00e9 Rosas Aispuro Torres tambi\u00e9n se reuni\u00f3 con los productores<br>del M\u00f3dulo V \u201cBrittingham\u201d, del Distrito de Riego 017; a quienes invit\u00f3 a<br>aprovechar esta oportunidad hist\u00f3rica que se tiene con un proyecto de tal<br>envergadura y la apertura que del Gobierno de M\u00e9xico para transparentar todo el<br>proceso y otorgar los apoyos necesarios para que el campo de la Laguna sea m\u00e1s<br>productivo.<\/p>\n\n\n\n<p>En tanto, los productores expusieron ante el gobernador de Durango, Jos\u00e9 Rosas<br>Aispuro Torres; el Senador con licencia, Gabriel Garc\u00eda Hern\u00e1ndez y funcionarios<br>federales, sus inquietudes en torno al proyecto y solicitaron acciones conjuntas<br>para crear un centro de acopio para las cosechas, tecnificaci\u00f3n del campo y<br>resolver el problema de la sobreexplotaci\u00f3n del acu\u00edfero Principal de la Comarca<br>Lagunera de Coahuila y Durango. Al t\u00e9rmino de la reuni\u00f3n refrendaron su decisi\u00f3n<br>para continuar con las mesas de di\u00e1logo a fin de lograr los consensos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comarca Lagunera, Dgo., Como parte del fortalecimiento al proceso desocializaci\u00f3n del proyecto Agua Saludable para La Laguna, el gobernador delestado de Durango, Jos\u00e9 Rosas Aispuro Torres; el senador con licencia, GabrielGarc\u00eda Hern\u00e1ndez, y el alcalde de Lerdo, Homero Mart\u00ednez Cabrera, firmaron unAcuerdo de Voluntades con cinco de los seis ejidos inconformes del M\u00f3dulo deRiego III \u201cSan Jacinto-Jerusalem\u201d y encabezaron una reuni\u00f3n con productores delM\u00f3dulo de Riego V \u201cBrittingham\u201d, del Distrito&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6010,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,40,64,31],"tags":[],"class_list":["post-6009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agua","category-durango","category-gobierno-de-durango","category-gobierno-federal","wpcat-32-id","wpcat-40-id","wpcat-64-id","wpcat-31-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=6009"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6009\/revisions"}],"predecessor-version":[{"id":6011,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6009\/revisions\/6011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/6010"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=6009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=6009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=6009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}