{"id":6120,"date":"2021-12-12T19:48:00","date_gmt":"2021-12-13T01:48:00","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=6120"},"modified":"2021-12-12T19:48:01","modified_gmt":"2021-12-13T01:48:01","slug":"reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-228","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/12\/12\/reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-228\/","title":{"rendered":"REPORTE COAHUILA DEL PLAN ESTATAL DE PREVENCI\u00d3N Y CONTROL COVID-19."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 12 de Diciembre del 2021.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa:<\/p>\n\n\n\n<p>1.- Al d\u00eda de hoy se registran 41 nuevos casos en Coahuila, sin presentarse defunciones.<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE NUEVOS CASOS<\/p>\n\n\n\n<p>14 TORRE\u00d3N<\/p>\n\n\n\n<p>6 FRONTERA<\/p>\n\n\n\n<p>6 MONCLOVA<\/p>\n\n\n\n<p>4 SAN PEDRO<\/p>\n\n\n\n<p>3 FRANCISCO I. MADERO<\/p>\n\n\n\n<p>2 CASTA\u00d1OS<\/p>\n\n\n\n<p>2 SALTILLO<\/p>\n\n\n\n<p>2 MATAMOROS<\/p>\n\n\n\n<p>1 SABINAS<\/p>\n\n\n\n<p>1 SAN BUENAVENTURA<\/p>\n\n\n\n<p>2.- Existen AHORA en Coahuila 1,405 casos activos de COVID &#8211; 19.<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE CASOS ACTIVOS<\/p>\n\n\n\n<p>-Torre\u00f3n 353<\/p>\n\n\n\n<p>-Saltillo 165<\/p>\n\n\n\n<p>-Monclova 156<\/p>\n\n\n\n<p>-Frontera 80<\/p>\n\n\n\n<p>-San Pedro 79<\/p>\n\n\n\n<p>-Sabinas 77<\/p>\n\n\n\n<p>-Piedras Negras 73<\/p>\n\n\n\n<p>-Cuatro Ci\u00e9negas 65<\/p>\n\n\n\n<p>-Francisco I. Madero 60<\/p>\n\n\n\n<p>-San Juan de Sabinas 56<\/p>\n\n\n\n<p>-M\u00fazquiz 44<\/p>\n\n\n\n<p>-Matamoros 39<\/p>\n\n\n\n<p>-Ramos Arizpe 30<\/p>\n\n\n\n<p>-San Buenaventura 26<\/p>\n\n\n\n<p>-Casta\u00f1os 23<\/p>\n\n\n\n<p>-Acu\u00f1a 22<\/p>\n\n\n\n<p>-Parras de la Fuente 12<\/p>\n\n\n\n<p>-Nava 11<\/p>\n\n\n\n<p>-Nadadores 8<\/p>\n\n\n\n<p>-General Cepeda 7<\/p>\n\n\n\n<p>-Villa Uni\u00f3n 6<\/p>\n\n\n\n<p>-Viesca 2<\/p>\n\n\n\n<p>-Ocampo 2<\/p>\n\n\n\n<p>-Allende 2<\/p>\n\n\n\n<p>-Arteaga 2<\/p>\n\n\n\n<p>-Zaragoza 1<\/p>\n\n\n\n<p>-Candela 1<\/p>\n\n\n\n<p>-Sacramento 1<\/p>\n\n\n\n<p>-Progreso 1<\/p>\n\n\n\n<p>-Ju\u00e1rez 1<\/p>\n\n\n\n<p>-Abasolo 0<\/p>\n\n\n\n<p>-Morelos 0<\/p>\n\n\n\n<p>-Guerrero 0<\/p>\n\n\n\n<p>-Lamadrid 0<\/p>\n\n\n\n<p>-Hidalgo 0<\/p>\n\n\n\n<p>-Escobedo 0<\/p>\n\n\n\n<p>-Jim\u00e9nez 0<\/p>\n\n\n\n<p>-Sierra Mojada 0<\/p>\n\n\n\n<p>3.- Al d\u00eda de hoy, se contabilizan en Coahuila EN TOTAL 101,749 casos, incluidos 7,688 decesos.<\/p>\n\n\n\n<p>4.- HOSPITALIZADOS: 162 (Se incluyen casos sospechosos y confirmados)<\/p>\n\n\n\n<p>Torre\u00f3n 77<\/p>\n\n\n\n<p>Saltillo 36<\/p>\n\n\n\n<p>Monclova 30<\/p>\n\n\n\n<p>Piedras Negras 10<\/p>\n\n\n\n<p>San Juan de Sabinas 7<\/p>\n\n\n\n<p>Acu\u00f1a 2<\/p>\n\n\n\n<p>5.- TOTAL DE RECUPERADOS: 92,656<\/p>\n\n\n\n<p>23,950 SALTILLO<\/p>\n\n\n\n<p>20,105 TORRE\u00d3N<\/p>\n\n\n\n<p>8,586 MONCLOVA<\/p>\n\n\n\n<p>8,034 PIEDRAS NEGRAS<\/p>\n\n\n\n<p>4,093 ACU\u00d1A<\/p>\n\n\n\n<p>3,128 SABINAS<\/p>\n\n\n\n<p>2,915 SAN PEDRO<\/p>\n\n\n\n<p>2,543 M\u00daZQUIZ<\/p>\n\n\n\n<p>2,273 SAN JUAN DE SABINAS<\/p>\n\n\n\n<p>2,254 FRANCISCO I. MADERO<\/p>\n\n\n\n<p>2,151 FRONTERA<\/p>\n\n\n\n<p>1,969 PARRAS DE LA FUENTE<\/p>\n\n\n\n<p>1,867 RAMOS ARIZPE<\/p>\n\n\n\n<p>1,680 MATAMOROS<\/p>\n\n\n\n<p>1,248 CUATRO CI\u00c9NEGAS<\/p>\n\n\n\n<p>994 ALLENDE<\/p>\n\n\n\n<p>911 NAVA<\/p>\n\n\n\n<p>610 CASTA\u00d1OS<\/p>\n\n\n\n<p>558 SAN BUENAVENTURA<\/p>\n\n\n\n<p>447 ZARAGOZA<\/p>\n\n\n\n<p>364 VILLA UNI\u00d3N<\/p>\n\n\n\n<p>300 ARTEAGA<\/p>\n\n\n\n<p>246 MORELOS<\/p>\n\n\n\n<p>229 SACRAMENTO<\/p>\n\n\n\n<p>219 OCAMPO<\/p>\n\n\n\n<p>185 GENERAL CEPEDA<\/p>\n\n\n\n<p>158 NADADORES<\/p>\n\n\n\n<p>156 LAMADRID<\/p>\n\n\n\n<p>124 VIESCA<\/p>\n\n\n\n<p>74 SIERRA MOJADA<\/p>\n\n\n\n<p>71 JIM\u00c9NEZ<\/p>\n\n\n\n<p>47 PROGRESO<\/p>\n\n\n\n<p>44 CANDELA<\/p>\n\n\n\n<p>30 ESCOBEDO<\/p>\n\n\n\n<p>30 GUERRERO<\/p>\n\n\n\n<p>26 JU\u00c1REZ<\/p>\n\n\n\n<p>22 HIDALGO<\/p>\n\n\n\n<p>15 ABASOLO<\/p>\n\n\n\n<p>6.- El Gobierno de Coahuila recomienda a las familias evitar salir a lugares de alta concurrencia.&nbsp; Si es necesario, acudir a aquellos ubicados al aire libre.<\/p>\n\n\n\n<p>Privilegiar aquellos que cumplen con los protocolos establecidos por los Subcomit\u00e9s Regionales de Salud.<\/p>\n\n\n\n<p>7.- Se exhorta a aquellos (as) ciudadanos (as) que tengan que salir a la calle USAR CUBREBOCAS.<\/p>\n\n\n\n<p>Su uso es OBLIGATORIO.<\/p>\n\n\n\n<p>8.- Con la finalidad de fortalecer el sistema inmunol\u00f3gico se sugiere a las familias llevar una alimentaci\u00f3n balanceada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 12 de Diciembre del 2021.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa: 1.- Al d\u00eda de hoy se registran 41 nuevos casos en Coahuila, sin presentarse defunciones. DISTRIBUCI\u00d3N DE NUEVOS CASOS 14 TORRE\u00d3N 6 FRONTERA 6 MONCLOVA 4 SAN PEDRO 3 FRANCISCO I. MADERO&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-6120","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-covid","wpcat-5-id","wpcat-4-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=6120"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6120\/revisions"}],"predecessor-version":[{"id":6121,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6120\/revisions\/6121"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=6120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=6120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=6120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}