{"id":6777,"date":"2022-01-21T19:00:41","date_gmt":"2022-01-22T01:00:41","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=6777"},"modified":"2022-01-21T19:00:42","modified_gmt":"2022-01-22T01:00:42","slug":"se-registra-incremento-de-afectaciones-respiratorias-ssd","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/01\/21\/se-registra-incremento-de-afectaciones-respiratorias-ssd\/","title":{"rendered":"SE REGISTRA INCREMENTO DE AFECTACIONES RESPIRATORIAS: SSD."},"content":{"rendered":"\n<p>Comarca Lagunera, Dgo.- La Secretar\u00eda de Salud del Estado de Durango,<br>informa que en \u00e9poca invernal se registra un incremento en las atenciones por<br>enfermedades respiratorias agudas, mismas que actualmente se tienen que<br>diagnosticar adecuadamente, para as\u00ed descartar probables casos de Covid-19.<br>Durante todo el a\u00f1o las atenciones han sido constantes y permanentes debido a la<br>contingencia.<\/p>\n\n\n\n<p>En lo que corresponde a Enfermedades Respiratorias, a la semana 1 del a\u00f1o 2021<br>se registr\u00f3 un total de acumulados de 3, 668 cerrando con un total de 181, 547<br>casos; en comparativo a la semana 1 del a\u00f1o en curso se registra un acumulado<br>de 6, 806. Con una variaci\u00f3n del 85 por ciento.<\/p>\n\n\n\n<p>Es por ello que toda persona que presente s\u00edntomas no debe auto medicarse y<br>mejor acudir a instancias espec\u00edficas de atenci\u00f3n para en caso de ser necesario<br>realizarse una prueba de covid y definir el tratamiento oportuno que deber\u00e1 seguir.<\/p>\n\n\n\n<p>Las recomendaciones para prevenir enfermedades respiratorias son: Abrigarse<br>bien, evitar cambios bruscos de temperatura, el uso del cubrebocas, el lavado<br>constante de manos y el uso de gel antibacterial. As\u00ed mismo, se pide reforzar el<br>sistema inmunol\u00f3gico con el consumo de productos ricos en Vitamina C, ya sean<br>naturales o mediante suplementos alimenticios, es conveniente la aplicaci\u00f3n de la<br>vacuna contra la influenza, mayormente en la poblaci\u00f3n vulnerable, para que, de<br>esta manera, se encuentren m\u00e1s protegidos.<\/p>\n\n\n\n<p>Se hace un llamado a la poblaci\u00f3n, de no acudir a lugares concurridos y evitar<br>reuniones, para prevenir la transmisi\u00f3n de cualquiera de las dos enfermedades;<br>tanto influenza como covid, es necesario disminuir la movilidad y exponerse lo<br>menos posible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comarca Lagunera, Dgo.- La Secretar\u00eda de Salud del Estado de Durango,informa que en \u00e9poca invernal se registra un incremento en las atenciones porenfermedades respiratorias agudas, mismas que actualmente se tienen quediagnosticar adecuadamente, para as\u00ed descartar probables casos de Covid-19.Durante todo el a\u00f1o las atenciones han sido constantes y permanentes debido a lacontingencia. En lo que corresponde a Enfermedades Respiratorias, a la semana 1 del a\u00f1o 2021se registr\u00f3 un total de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,64,14],"tags":[],"class_list":["post-6777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango","category-gobierno-de-durango","category-salud","wpcat-40-id","wpcat-64-id","wpcat-14-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=6777"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6777\/revisions"}],"predecessor-version":[{"id":6779,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6777\/revisions\/6779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/6778"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=6777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=6777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=6777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}