{"id":6873,"date":"2022-01-27T17:31:09","date_gmt":"2022-01-27T23:31:09","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=6873"},"modified":"2022-01-27T17:31:10","modified_gmt":"2022-01-27T23:31:10","slug":"convoca-investigacion-y-posgrado-de-la-uadec-a-la-conferencia-ciencia-para-todos","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/01\/27\/convoca-investigacion-y-posgrado-de-la-uadec-a-la-conferencia-ciencia-para-todos\/","title":{"rendered":"Convoca Investigaci\u00f3n y Posgrado de la UAdeC a la Conferencia \u201cCiencia para Todos\u201d."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 27 de enero de 2022.- Para promover las vocaciones<br>cient\u00edficas en los j\u00f3venes de bachillerato, la Universidad Aut\u00f3noma de Coahuila a<br>trav\u00e9s de la Direcci\u00f3n de Investigaci\u00f3n y Posgrado y su Centro de Innovaci\u00f3n<br>Cient\u00edfica y Tecnol\u00f3gica (CICYT-UAdeC), convocan a la conferencia &#8220;Ciencia para<br>todos&#8221;, el lunes 31 de enero a las 13:00 horas por medio de Microsoft Teams y<br>Facebook Live @investigacionyposgradoUAdeC.<\/p>\n\n\n\n<p>La actividad se desarrolla dentro del Programa \u201cVocaciones Cient\u00edficas para<br>Bachillerato\u201d del CICYT-UAdeC, para promover la generaci\u00f3n y difusi\u00f3n del<br>conocimiento cient\u00edfico, adem\u00e1s de impulsar la superaci\u00f3n personal de los<br>estudiantes a trav\u00e9s del desarrollo acad\u00e9mico.<\/p>\n\n\n\n<p>&#8220;Ciencia para todos&#8221; ser\u00e1 impartida por el cient\u00edfico y emprendedor mexicano,<br>Ricardo G\u00f3mez Garc\u00eda, Ingeniero Qu\u00edmico egresado de la m\u00e1xima casa de<br>estudios y quien forma parte del Grupo de Investigaci\u00f3n en Biotecnolog\u00eda y<br>Qu\u00edmica Fina de la Universidad Cat\u00f3lica Portuguesa (UCP), adem\u00e1s de ser<br>miembro del equipo de trabajo de la empresa europea AgroGrIN Tech.<\/p>\n\n\n\n<p>G\u00f3mez Garc\u00eda, comenz\u00f3 su carrera cient\u00edfica en 2012, con el desarrollo de nuevas<br>tecnolog\u00edas extractivas para la explotaci\u00f3n de residuos agroalimentarios y con ello,<br>elaborar productos de valor agregado, asimismo, particip\u00f3 en diferentes pr\u00e1cticas<br>de alta capacitaci\u00f3n en diferentes pa\u00edses como Argentina, Francia, Italia e India.<\/p>\n\n\n\n<p>Actualmente, es candidato a Doctor en Biotecnolog\u00eda por la UCP, su trabajo de<br>tesis pretende desarrollar tecnolog\u00edas innovadoras y sostenibles en el contexto del<br>enfoque de cero residuos y econom\u00eda circular para la extracci\u00f3n e identificaci\u00f3n de<br>compuestos bioactivos funcionales de inter\u00e9s para varias industrias, empleando<br>subproductos de frutas para su valorizaci\u00f3n y reincorporaci\u00f3n.<\/p>\n\n\n\n<p>El registro a la charla est\u00e1 disponible en el formulario: <a href=\"https:\/\/tinyurl.com\/VCB-by- Ricardo-Gomez\" data-type=\"URL\" data-id=\"https:\/\/tinyurl.com\/VCB-by- Ricardo-Gomez\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/tinyurl.com\/VCB-by-<br>Ricardo-Gomez<\/a> donde se deben escribir datos como nombre completo, direcci\u00f3n<br>de correo electr\u00f3nico y Unidad Acad\u00e9mica de la UAdeC a la que se pertenece;<br>posteriormente, se proporciona el enlace de acceso a Microsoft Teams.<br>Para m\u00e1s informaci\u00f3n sobre esta y m\u00e1s actividades, visita las p\u00e1ginas de<br>Facebook de la Direcci\u00f3n de Investigaci\u00f3n y Posgrado:<br><a href=\"https:\/\/www.facebook.com\/investigacionyposgradoUAdeC\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/investigacionyposgradoUAdeC<\/a> y del CICYT-UAdeC:<br>https<a href=\"https:\/\/www.facebook.com\/cicytuadec\/\" data-type=\"URL\" data-id=\"https:\/\/www.facebook.com\/cicytuadec\/\" target=\"_blank\" rel=\"noreferrer noopener\">:\/\/www.facebook.com\/cicytuadec\/<\/a> .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 27 de enero de 2022.- Para promover las vocacionescient\u00edficas en los j\u00f3venes de bachillerato, la Universidad Aut\u00f3noma de Coahuila atrav\u00e9s de la Direcci\u00f3n de Investigaci\u00f3n y Posgrado y su Centro de Innovaci\u00f3nCient\u00edfica y Tecnol\u00f3gica (CICYT-UAdeC), convocan a la conferencia &#8220;Ciencia paratodos&#8221;, el lunes 31 de enero a las 13:00 horas por medio de Microsoft Teams yFacebook Live @investigacionyposgradoUAdeC. La actividad se desarrolla dentro del Programa \u201cVocaciones Cient\u00edficas paraBachillerato\u201d&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=6873"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6873\/revisions"}],"predecessor-version":[{"id":6875,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6873\/revisions\/6875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/6874"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=6873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=6873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=6873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}