{"id":6927,"date":"2022-01-31T19:12:37","date_gmt":"2022-02-01T01:12:37","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=6927"},"modified":"2022-01-31T19:12:37","modified_gmt":"2022-02-01T01:12:37","slug":"ponen-en-marcha-programa-municipal-anticorrupcion-ni-tu-ni-yo","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/01\/31\/ponen-en-marcha-programa-municipal-anticorrupcion-ni-tu-ni-yo\/","title":{"rendered":"Ponen en marcha programa municipal anticorrupci\u00f3n \u201cNi t\u00fa, ni yo\u201d."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 31 de enero de 2022.<\/p>\n\n\n\n<p>La Administraci\u00f3n P\u00fablica Municipal que preside el alcalde Rom\u00e1n Alberto<br>Cepeda, puso en marcha esta ma\u00f1ana el programa anticorrupci\u00f3n denominado \u201cNi<br>t\u00fa, ni yo\u201d el cual busca prevenir y erradicar todo acto de corrupci\u00f3n al interior del<br>gobierno de Torre\u00f3n.<\/p>\n\n\n\n<p>En su mensaje el alcalde de Torre\u00f3n Rom\u00e1n Alberto Cepeda mencion\u00f3 que un<br>buen gobierno se entiende como la forma de ejercicio del poder p\u00fablico con<br>rasgos como la eficiencia, la transparencia, la rendici\u00f3n de cuentas, la<br>participaci\u00f3n de la sociedad y la correcta aplicaci\u00f3n del estado de derecho.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que todo buen gobierno debe poner especial atenci\u00f3n en prevenir la<br>corrupci\u00f3n y en inspirar siempre el buen actuar de los servidores p\u00fablicos, porque<br>este problema perjudica la prosperidad econ\u00f3mica y afecta directamente la<br>confianza que tienen los ciudadanos ante sus autoridades.<\/p>\n\n\n\n<p>Dijo tambi\u00e9n que es urgente una estrategia que permita erradicar la corrupci\u00f3n,<br>por lo que el d\u00eda de hoy se pone en marcha uno de los proyectos m\u00e1s importantes<br>de su Administraci\u00f3n, el programa anticorrupci\u00f3n denominado \u201cNi t\u00fa, ni yo\u201d<br>mediante el cual se trabajar\u00e1 en la prevenci\u00f3n y sanci\u00f3n de esta problem\u00e1tica,<br>para reafirmar el correcto desempe\u00f1o de los servidores p\u00fablicos en todos los<br>niveles.<\/p>\n\n\n\n<p>Inform\u00f3 que se conforma el Consejo Municipal Anticorrupci\u00f3n, con la participaci\u00f3n<br>del gobierno municipal, estatal, universidades, organismos de la sociedad civil,<br>representantes de c\u00e1maras y organismos empresariales, bajo la supervisi\u00f3n de la<br>Contralor\u00eda Ciudadana.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que el compromiso es con la transparencia y la rendici\u00f3n de cuentas y que<br>todos y cada uno de los servidores p\u00fablicos se comprometen a seguir<br>puntualmente el modelo integridad municipal, orientado por los valores de<br>honestidad, responsabilidad, vocaci\u00f3n de servicio, compromiso, empat\u00eda, respeto,<br>eficiencia y confianza.<\/p>\n\n\n\n<p>Dijo que la lucha contra la corrupci\u00f3n es un tema de corresponsabilidad, por lo que<br>parte importante para el \u00e9xito del programa es la participaci\u00f3n ciudadana,<br>mencion\u00f3 que \u201cla ciudadan\u00eda es parte vital para el buen desempe\u00f1o de esta<br>iniciativa, el esp\u00edritu de este programa es que ni t\u00fa ciudadano ofreces sobornos, ni yo ciudadano los acepto y de igual forma los servidores p\u00fablicos, ni t\u00fa vas a pedir ni el ciudadano te va a dar\u201d.<\/p>\n\n\n\n<p>Finalmente coment\u00f3 que se van a poner a disposici\u00f3n de la ciudadan\u00eda<br>mecanismos para que pueda denunciar cualquier tipo de acto de corrupci\u00f3n.<br>Por su parte la Secretaria del Ayuntamiento, Natalia Fern\u00e1ndez Mart\u00ednez dio a<br>conocer que el Consejo Municipal deber\u00e1 sesionar una vez cada cuatro meses<br>para dar seguimiento a los lineamientos del programa anticorrupci\u00f3n.<\/p>\n\n\n\n<p>El Gobernador del Estado, Miguel \u00c1ngel Riquelme Sol\u00eds, se\u00f1al\u00f3 que tan<br>importante es implementar un programa de obras, servicios y mantenimiento en un<br>municipio como Torre\u00f3n, como lo es fomentar las bases de un programa local<br>anticorrupci\u00f3n.<\/p>\n\n\n\n<p>Dijo que es importante trabajar unidos para erradicar toda forma de corrupci\u00f3n, y<br>mencion\u00f3 que el hecho de que una Administraci\u00f3n inicie con programas muy<br>directos para combatirla es un mensaje muy claro.<\/p>\n\n\n\n<p>En el acto el Gobernador de Coahuila tom\u00f3 protesta y reconoci\u00f3 a los integrantes<br>del Consejo Municipal Anticorrupci\u00f3n, destac\u00f3 que la participaci\u00f3n ciudadana se<br>debe fomentar y trabajar de fondo para obtener buenos resultados, en tiempos<br>dif\u00edciles que han puesto a prueba la fortaleza de las instituciones.<\/p>\n\n\n\n<p>Mencion\u00f3 que, con la prevenci\u00f3n y el combate a la corrupci\u00f3n dentro de todo el<br>quehacer gubernamental, se consolida el estado de derecho, el entorno de<br>legalidad, lo que hace propicio el dinamismo econ\u00f3mico y el desarrollo de<br>inversiones.<\/p>\n\n\n\n<p>El programa anticorrupci\u00f3n \u201cNi t\u00fa, ni yo\u201d es una iniciativa del gobierno de Torre\u00f3n<br>para fomentar la cultura de la legalidad, el orden y la armon\u00eda para llevar al<br>municipio a vivir un pleno estado de derecho mediante la prevenci\u00f3n de actos de<br>corrupci\u00f3n dentro de la Administraci\u00f3n P\u00fablica Municipal.<\/p>\n\n\n\n<p>Busca promover la participaci\u00f3n ciudadana para inhibir los actos il\u00edcitos y el abuso<br>de autoridad por parte de los servidores p\u00fablicos municipales, as\u00ed como crear<br>consciencia en ellos promoviendo el desempe\u00f1o \u00e9tico de sus funciones.<\/p>\n\n\n\n<p>Dentro de las acciones del programa \u201cNi t\u00fa, ni yo\u201d se encuentran: implementar la<br>Pol\u00edtica Anticorrupci\u00f3n en el Municipio con base en las recomendaciones de la<br>Pol\u00edtica Estatal Anticorrupci\u00f3n de Coahuila y presentar la campa\u00f1a \u201cNi t\u00fa, ni yo\u201d la<br>cual busca concientizar a la sociedad, sobre la dualidad de los actos de corrupci\u00f3n<br>y sus consecuencias.<\/p>\n\n\n\n<p>El evento de presentaci\u00f3n del programa anticorrupci\u00f3n fue presidido por el<br>Gobernador del Estado, Miguel \u00c1ngel Riquelme Sol\u00eds; acompa\u00f1ado por el alcalde<br>de Torre\u00f3n, Rom\u00e1n Alberto Cepeda; el Presidente de la Junta de Gobierno del<br>Congreso del Estado, Eduardo Olmos Castro, el Magistrado Presidente del<br>Tribunal Superior de Justicia del Estado, Miguel Mery Ayup; la Secretaria de<br>Fiscalizaci\u00f3n y Rendici\u00f3n de Cuentas, Teresa Guajardo Berlanga; la Secretaria del<\/p>\n\n\n\n<p>Ayuntamiento de Torre\u00f3n, Natalia Fern\u00e1ndez Mart\u00ednez y como representante de<br>los servidores p\u00fablicos municipales, la comandante Nancy L\u00f3pez Gallegos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 31 de enero de 2022. La Administraci\u00f3n P\u00fablica Municipal que preside el alcalde Rom\u00e1n AlbertoCepeda, puso en marcha esta ma\u00f1ana el programa anticorrupci\u00f3n denominado \u201cNit\u00fa, ni yo\u201d el cual busca prevenir y erradicar todo acto de corrupci\u00f3n al interior delgobierno de Torre\u00f3n. En su mensaje el alcalde de Torre\u00f3n Rom\u00e1n Alberto Cepeda mencion\u00f3 que unbuen gobierno se entiende como la forma de ejercicio del poder p\u00fablico conrasgos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-6927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=6927"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6927\/revisions"}],"predecessor-version":[{"id":6929,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/6927\/revisions\/6929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/6928"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=6927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=6927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=6927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}