{"id":7000,"date":"2022-02-03T18:47:33","date_gmt":"2022-02-04T00:47:33","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=7000"},"modified":"2022-02-03T18:47:34","modified_gmt":"2022-02-04T00:47:34","slug":"especializate-con-la-maestria-en-enfermeria-con-acentuacion-en-atencion-de-enfermeria-al-adulto-mayor","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/02\/03\/especializate-con-la-maestria-en-enfermeria-con-acentuacion-en-atencion-de-enfermeria-al-adulto-mayor\/","title":{"rendered":"Especial\u00edzate con la Maestr\u00eda en Enfermer\u00eda con Acentuaci\u00f3n en Atenci\u00f3n de Enfermer\u00eda al Adulto Mayor."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 3 de febrero de 2022.- La Facultad de Enfermer\u00eda \u201cDr.<br>Santiago Vald\u00e9s Galindo\u201d de la Universidad Aut\u00f3noma de Coahuila, convoca a ser<br>parte de la Maestr\u00eda en Enfermer\u00eda con Acentuaci\u00f3n en Atenci\u00f3n de Enfermer\u00eda al<br>Adulto Mayor para el semestre agosto-diciembre 2022.<\/p>\n\n\n\n<p>Los interesados en cursar el programa deber\u00e1n registrarse a trav\u00e9s de la p\u00e1gina<br>www.admisiones.uadec.mx teniendo como fecha l\u00edmite el 11 de febrero y seguir<br>las indicaciones para obtener la ficha para el examen de admisi\u00f3n, que se<br>presentar\u00e1 el 19 de mayo de 2022; posteriormente del 20 al 24 de junio se llevar\u00e1<br>a cabo la entrevista de admisi\u00f3n, la publicaci\u00f3n de resultados se har\u00e1 el 1 de<br>agosto y del 2 al 5 de ese mismo mes el proceso de inscripci\u00f3n.<\/p>\n\n\n\n<p>La Maestr\u00eda busca formar profesionales en la pr\u00e1ctica avanzada de enfermer\u00eda<br>con exigencias de cambio y compromiso social para que coadyuven a disminuir de<br>manera anticipatoria, el impacto de las enfermedades en el adulto mayor con<br>estrategias innovadoras que mejoren los indicadores de calidad, bienestar y<br>control de su salud.<\/p>\n\n\n\n<p>Una de las caracter\u00edsticas m\u00e1s importantes del programa es que se encuentra<br>inscrito en el Padr\u00f3n del Programa Nacional de Posgrados de Calidad del Consejo<br>Nacional de Ciencia y Tecnolog\u00eda, adem\u00e1s, tiene docentes pertenecientes al<br>Sistema Nacional de Investigadores (SNI).<\/p>\n\n\n\n<p>Al concluir su formaci\u00f3n, el egresado ser\u00e1 capaz de desempe\u00f1arse como<br>otorgador del cuidado, gestor, investigador y educador; realizar pr\u00e1ctica avanzada<br>de calidad y procesos para anticipar y solucionar problemas de salud del adulto<br>mayor a nivel hospitalario, comunitario, institucional o ejerciendo la pr\u00e1ctica libre<br>de la profesi\u00f3n.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n comunicarse con la coordinadora de la Maestr\u00eda, la Dra.<br>Reyna Torres Obreg\u00f3n en el correo electr\u00f3nico<br>posgradoenfermeriaus@uadec.edu.mx y en los tel\u00e9fonos (844) 412 1884 y (844)<br>414 2588 ext. 119, visitar la p\u00e1gina de Facebook Departamento de Posgrado e<br>Investigaci\u00f3n Facultad de Enfermer\u00eda U.S. o acudir a las instalaciones de la<br>Facultad que se encuentran en Calzada Francisco I. Madero #1237 en la Zona<br>Centro de Saltillo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 3 de febrero de 2022.- La Facultad de Enfermer\u00eda \u201cDr.Santiago Vald\u00e9s Galindo\u201d de la Universidad Aut\u00f3noma de Coahuila, convoca a serparte de la Maestr\u00eda en Enfermer\u00eda con Acentuaci\u00f3n en Atenci\u00f3n de Enfermer\u00eda alAdulto Mayor para el semestre agosto-diciembre 2022. Los interesados en cursar el programa deber\u00e1n registrarse a trav\u00e9s de la p\u00e1ginawww.admisiones.uadec.mx teniendo como fecha l\u00edmite el 11 de febrero y seguirlas indicaciones para obtener la ficha para&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=7000"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7000\/revisions"}],"predecessor-version":[{"id":7002,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7000\/revisions\/7002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/7001"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=7000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=7000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=7000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}