{"id":718,"date":"2021-03-05T18:48:25","date_gmt":"2021-03-06T00:48:25","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=718"},"modified":"2021-03-05T18:48:26","modified_gmt":"2021-03-06T00:48:26","slug":"amplia-uadec-el-registro-para-fichas-de-admision-al-24-de-marzo","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/03\/05\/amplia-uadec-el-registro-para-fichas-de-admision-al-24-de-marzo\/","title":{"rendered":"Ampl\u00eda UAdeC el Registro para Fichas de Admisi\u00f3n al 24 de Marzo."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 5 de marzo de 2021.\u00a0A los aspirantes a la Universidad Aut\u00f3noma de Coahuila que se les pas\u00f3 la fecha de pago o la impresi\u00f3n de la ficha, as\u00ed como a quienes deseen obtener registro para examen de admisi\u00f3n de bachillerato, licenciatura o posgrado, se les informa que el periodo de registro se ampl\u00eda a partir del 5 al 24 de marzo del 2021.\u00a0<\/p>\n\n\n\n<p>Los solicitantes a ingresar a Escuelas y Facultades de las Unidades Saltillo, Torre\u00f3n y Norte, hacer el registro a trav\u00e9s de la p\u00e1gina&nbsp;<a href=\"http:\/\/www.admisiones.uadec.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.admisiones.uadec.mx<\/a>&nbsp;y llenar el formulario con el nombre completo e id\u00e9ntico al de su acta de nacimiento, adem\u00e1s de tomar o subir una fotograf\u00eda cumpliendo con los requisitos se\u00f1alados.&nbsp;<\/p>\n\n\n\n<p>Al t\u00e9rmino de este aparecer\u00e1 la solicitud de pago para tramitar la ficha con un n\u00famero asignado, la cual deber\u00e1 presentarse en los bancos autorizados o en l\u00ednea para pagar del 5 al 24 de marzo de 2021; el costo de la ficha para bachillerato y licenciatura es de 650 pesos y mil pesos para nivel posgrado.&nbsp;<\/p>\n\n\n\n<p>Una vez que se vea reflejado el pago en l\u00ednea o f\u00edsico, a trav\u00e9s del enlace \u201cConsulta\u201d de la p\u00e1gina de admisiones, se podr\u00e1 imprimir la ficha que da derecho a presentar el examen; tras validar los datos registrados, imprimir la ficha y que \u00e9sta sea clara y legible ya que ser\u00e1 necesaria para identificarse el d\u00eda del examen, la fecha l\u00edmite de impresi\u00f3n es el 31 de marzo de 2021.&nbsp;<\/p>\n\n\n\n<p>Para ingresar a los bachilleratos, el alumno no debe tener m\u00e1s de 17 a\u00f1os cumplidos al momento de la Inscripci\u00f3n Administrativa (entrega de papeler\u00eda), excepto para la Esc. de Bach. Mariano Narv\u00e1ez Gonz\u00e1lez y el Instituto de Ciencias y Humanidades \u201cSalvador Gonz\u00e1lez Lobo\u201d; si un aspirante ya fue alumno de una carrera de Licenciatura, ya no podr\u00e1 registrarse a la misma.&nbsp;<\/p>\n\n\n\n<p>A los aspirantes a la Carrera de M\u00e9dico Cirujano e Ingeniero Biom\u00e9dico, se les aplicar\u00e1 adem\u00e1s un examen de conocimientos, por lo que deber\u00e1n hacer un pago por este concepto; una vez cumplidos los requisitos de registro, se deber\u00e1 comunicar a las propias facultades y escuela de la Unidad Saltillo, Torre\u00f3n y Norte.&nbsp;<\/p>\n\n\n\n<p>Previo al examen se aplicar\u00e1 un simulacro para que el aspirante conozca el proceso para la aplicaci\u00f3n del examen: para bachillerato ser\u00e1 del 17 al 19 de mayo, mientras que para licenciatura ser\u00e1 del 3 al 5 de mayo; el examen oficial se aplicar\u00e1 el 6 y 7 de mayo para licenciatura, el 8 de mayo para medicina y posgrado y el 21 y 22 para bachillerato.&nbsp;<\/p>\n\n\n\n<p>La publicaci\u00f3n de los resultados ser\u00e1 el 6 de junio para bachillerato y licenciatura y el 4 de junio se entregar\u00e1n los resultados en los posgrados a trav\u00e9s de las escuelas y facultades, as\u00ed como en la p\u00e1gina oficial:&nbsp;<a href=\"http:\/\/www.uadec.edu.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.uadec.edu.mx<\/a>; la fecha de aplicaci\u00f3n de las pruebas de admisi\u00f3n es \u00fanica, por lo tanto, no se puede presentar el examen d\u00edas posteriores, sin excepci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Para conocer m\u00e1s sobre la oferta educativa de la UAdeC, visita&nbsp;<a href=\"http:\/\/www.admisiones.uadec.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.admisiones.uadec.mx\/<\/a>; para m\u00e1s informaci\u00f3n, comunicarse al Departamento de Admisiones a los tel\u00e9fonos (844) 438 15 08, 438 16 48 o 438 16 51.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 5 de marzo de 2021.\u00a0A los aspirantes a la Universidad Aut\u00f3noma de Coahuila que se les pas\u00f3 la fecha de pago o la impresi\u00f3n de la ficha, as\u00ed como a quienes deseen obtener registro para examen de admisi\u00f3n de bachillerato, licenciatura o posgrado, se les informa que el periodo de registro se ampl\u00eda a partir del 5 al 24 de marzo del 2021.\u00a0 Los solicitantes a ingresar a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=718"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/718\/revisions"}],"predecessor-version":[{"id":720,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/718\/revisions\/720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/719"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}