{"id":7251,"date":"2022-02-18T18:24:24","date_gmt":"2022-02-19T00:24:24","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=7251"},"modified":"2022-02-18T18:24:25","modified_gmt":"2022-02-19T00:24:25","slug":"expone-plan-de-trabajo-director-de-vialidad-y-movilidad-urbana-a-ediles","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/02\/18\/expone-plan-de-trabajo-director-de-vialidad-y-movilidad-urbana-a-ediles\/","title":{"rendered":"Expone plan de trabajo director de Vialidad y Movilidad Urbana a ediles."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 18 de febrero de 2022.<\/p>\n\n\n\n<p>El director General de Vialidad y Movilidad Urbana, Luis Alberto Morales Cort\u00e9s,<br>compareci\u00f3 hoy en una Primer Sesi\u00f3n de la Comisi\u00f3n de Movilidad y Seguridad<br>Vial del Cabildo de Torre\u00f3n, ah\u00ed expuso el informe de actividades<br>correspondientes al mes de enero.<\/p>\n\n\n\n<p>El titular comparti\u00f3 las acciones prioritarias que considera en su plan de trabajo<br>para que cambie positivamente tanto la imagen y profesionalizaci\u00f3n de los<br>agentes de tr\u00e1nsito, as\u00ed como la influencia en el comportamiento de la poblaci\u00f3n.<\/p>\n\n\n\n<p>Contempla para ello la valoraci\u00f3n del capital humano, diagn\u00f3stico de la<br>infraestructura, diagn\u00f3stico de la incidencia de accidentes, ordenamiento vial y el<br>diagn\u00f3stico de puntos conflictivos como los puntos eje para lograr su objetivo.<\/p>\n\n\n\n<p>Explic\u00f3 el sentido de la direcci\u00f3n a su cargo, que es el vigilar el cumplimiento del<br>reglamento de Movilidad Urbana y dem\u00e1s disposiciones legales de la materia,<br>preservar la vida, la salud y el patrimonio de la ciudadan\u00eda, coment\u00f3.<\/p>\n\n\n\n<p>Por tanto, Morales Cort\u00e9s resalt\u00f3 la importancia de coordinarse con otras \u00e1reas,<br>pues se debe hacer un an\u00e1lisis integral que re\u00fana contar con calles en buen<br>estado, una semaforizaci\u00f3n \u00f3ptima y se\u00f1alizaci\u00f3n puntual en las calles, por<br>ejemplo.<\/p>\n\n\n\n<p>En cuanto a la modificaci\u00f3n de la imagen y percepci\u00f3n de la ciudadan\u00eda hacia los<br>agentes viales, inform\u00f3 que sostuvo una pl\u00e1tica con los elementos para detectar y<br>resolver las fallas que pudieran llevarlos a cometer faltas como servidores<br>p\u00fablicos, de igual manera, adem\u00e1s de incentivar a las peticiones de apoyo de<br>salud mental y nutricional, como fue que manifestaron, se les estar\u00e1 capacitando<br>en Derechos Humanos para que conozcan el manejo y atenci\u00f3n que deben tener<br>hacia el ciudadano.<\/p>\n\n\n\n<p>Lograr la profesionalizaci\u00f3n es la meta de esta Direcci\u00f3n, y seg\u00fan dijo su titular, se<br>empez\u00f3 a trabajar ya en las formas laborales, pero tambi\u00e9n se revisa el proceso<br>de transformaci\u00f3n de lo que ahora es la Ley General de Asentamientos Humanos,<br>que a nivel nacional se modificar\u00e1 a Ley de Seguridad Vial.<\/p>\n\n\n\n<p>Otro de los puntos que se comunic\u00f3 ante la comisi\u00f3n del Cabildo, es el rescate de<br>la Escuela de Educaci\u00f3n Vial \u201cCarlos de la Cueva\u201d, la cual ya retom\u00f3 actividades<br>con motociclistas que trabajan por medio de aplicaci\u00f3n.<\/p>\n\n\n\n<p>Destac\u00f3 tambi\u00e9n el acercamiento con los j\u00f3venes de preparatoria para que<br>cuando sea el momento en que puedan tramitar su licencia de conducir, ya vayan<br>adiestrados en la conducta vial reglamentaria.<\/p>\n\n\n\n<p>El aprovechamiento de las nuevas tecnolog\u00edas a la hora de multar a un conductor<br>ya no retir\u00e1ndole una garant\u00eda sino registrando el chip de su licencia en el clip.<\/p>\n\n\n\n<p>Campa\u00f1as de conducci\u00f3n sin alcohol en coordinaci\u00f3n con la iniciativa privada y<br>verificar las zonas hospitalarias para asegurarse que en las v\u00edas donde hay m\u00e1s<br>percances se pueda acceder a una atenci\u00f3n m\u00e9dica inmediata, fueron otras de las<br>propuestas que est\u00e1n dentro del proyecto de trabajo que present\u00f3 el director esta<br>tarde a los regidores integrantes de la Comisi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 18 de febrero de 2022. El director General de Vialidad y Movilidad Urbana, Luis Alberto Morales Cort\u00e9s,compareci\u00f3 hoy en una Primer Sesi\u00f3n de la Comisi\u00f3n de Movilidad y SeguridadVial del Cabildo de Torre\u00f3n, ah\u00ed expuso el informe de actividadescorrespondientes al mes de enero. El titular comparti\u00f3 las acciones prioritarias que considera en su plan de trabajopara que cambie positivamente tanto la imagen y profesionalizaci\u00f3n de losagentes de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-7251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=7251"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7251\/revisions"}],"predecessor-version":[{"id":7253,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7251\/revisions\/7253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/7252"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=7251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=7251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=7251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}