{"id":741,"date":"2021-03-05T20:13:23","date_gmt":"2021-03-06T02:13:23","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=741"},"modified":"2021-03-05T20:13:23","modified_gmt":"2021-03-06T02:13:23","slug":"presenta-informe-de-resultados-coordinadora-de-unidad-torreon-de-uadec","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/03\/05\/presenta-informe-de-resultados-coordinadora-de-unidad-torreon-de-uadec\/","title":{"rendered":"Presenta informe de resultados Coordinadora de Unidad Torre\u00f3n de UAdeC."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila.- En Sesi\u00f3n Extraordinaria del Consejo Universitario de la Unidad Torre\u00f3n, la Doctora Sandra L\u00f3pez Chavarria, rindi\u00f3 su primer informe de resultados al frente de la Coordinaci\u00f3n de la Unidad Torre\u00f3n, que incluy\u00f3, la solicitud que le han hecho llegar decenas de j\u00f3venes universitarios, para que se reanuden las clases presenciales en esa instituci\u00f3n, mismas que han quedado en suspenso a partir del pasado 20 de marzo del 2020.<br><br>En ese mismo contexto, durante el acto de rendici\u00f3n de cuentas que tuvo lugar esta ma\u00f1ana en el auditorio del Centro Cultural universitario, y que presidi\u00f3 el Rector Salvador Hern\u00e1ndez V\u00e9lez, hizo publica tal solicitud al tiempo que externo presentarla como lo hizo ante el rector ah\u00ed presente, al a Sub Comit\u00e9 T\u00e9cnico Covid-19 para la zona lagunera, para que este dictamine sobre tal petici\u00f3n, que mas adelante deber\u00e1 dar curso las autoridades universitarias.<br><br>En este acto, celebrado en medio de las medidas de prevenci\u00f3n sanitarias vigentes, que limit\u00f3 al m\u00e1ximo al n\u00famero de invitados, que con todo fueron representativos de las propias autoridades centrales de la Universidad, Coordinadores del resto de las Unidades del Norte y Centro del Estado, directivos locales, as\u00ed como nutrida presentaci\u00f3n de liderazgos empresariales y de la comunidad universitaria en la regi\u00f3n, y que integran Universidades p\u00fablicas y privadas.<br><br>La Doctora L\u00f3pez Chavarria ley\u00f3 el extracto del Informe que dijo hab\u00edan hecho llegar con anterioridad a cada uno de los integrantes del Consejo universitario a trav\u00e9s de su correo institucional.<br><br>Afirm\u00f3 que, &#8220;a lo largo del a\u00f1o de gesti\u00f3n, se ha dado impulso a los estudiantes en su evoluci\u00f3n individual, acci\u00f3n que abonar\u00e1 al crecimiento y desarrollo social mas all\u00e1 de nuestra comunidad&#8221;.<br><br>Nuestra prioridad, afirm\u00f3, &#8220;son los estudiantes, tenemos con ellos la gran responsabilidad del quehacer acad\u00e9mico, con calidad, con actitud positiva con la globalizaci\u00f3n demanda&#8221;.<br><br>&#8220;Inmersos en el largo periodo de la pandemia contamos con la misi\u00f3n de forma a nuestros alumnos a trav\u00e9s del conocimiento y el desarrollo de aptitudes de pensamiento. No nos hemos detenido, al contrario, ello ha sido un aliciente&#8221;.<br><br>Afirm\u00f3 que, &#8220;nos hemos adaptado a la adversidad, crecemos, innovamos, nos transformamos y avanzamos como comunidad&#8221;.<br><br>En este contexto, inform\u00f3 haber recibido de parte de grupos de j\u00f3venes universitarios, la solicitud de retorno a clases presenciales, en suspenso desde el inicio de la pandemia del Covid 19, all\u00e1 por el mes de marzo del 2020.<br><br>Agreg\u00f3 que la nueva realidad exige nuevas respuestas, una de las cuales es la capacitaci\u00f3n para sus docentes, la cual se realiza de manera inmediata y eficaz, reconociendo luego el esfuerzo demostrado, acci\u00f3n que no ha sido f\u00e1cil, as\u00ed como la labor coordinada realizada a favor de los alumnos de la Universidad.<br><br>Estoy segura, dijo, &#8220;que seguiremos transformando, pero sobre todo dando buenos resultados y siempre comprometidos con la Universidad&#8221;.<br><br>En su intervenci\u00f3n el Rector Hern\u00e1ndez V\u00e9lez hizo un amplio reconocimiento a los resultados presentados por la funcionaria universitaria, entre los que singulariz\u00f3 los trabajos inherentes a lograr la recertificaciones por parte de CONACYT y otros organismos extrauniversitarios a los estudios que se imparten en las escuelas y Facultades de la Unidad Torre\u00f3n, al tiempo que destacaba tambi\u00e9n la recertificaci\u00f3n que corresponde a la Norma 180\/900.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila.- En Sesi\u00f3n Extraordinaria del Consejo Universitario de la Unidad Torre\u00f3n, la Doctora Sandra L\u00f3pez Chavarria, rindi\u00f3 su primer informe de resultados al frente de la Coordinaci\u00f3n de la Unidad Torre\u00f3n, que incluy\u00f3, la solicitud que le han hecho llegar decenas de j\u00f3venes universitarios, para que se reanuden las clases presenciales en esa instituci\u00f3n, mismas que han quedado en suspenso a partir del pasado 20 de marzo del 2020&#8230;.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-741","post","type-post","status-publish","format-standard","hentry","category-torreon","category-uadec","wpcat-7-id","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=741"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/741\/revisions"}],"predecessor-version":[{"id":742,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/741\/revisions\/742"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}