{"id":7555,"date":"2022-03-09T19:53:28","date_gmt":"2022-03-10T01:53:28","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=7555"},"modified":"2022-03-09T19:53:29","modified_gmt":"2022-03-10T01:53:29","slug":"supervisa-mars-obras-de-infraestructura-vial-en-la-region-centro","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/03\/09\/supervisa-mars-obras-de-infraestructura-vial-en-la-region-centro\/","title":{"rendered":"SUPERVISA MARS OBRAS DE INFRAESTRUCTURA VIAL EN LA REGI\u00d3N CENTRO."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>Visita los municipios de Nadadores, San Buenaventura y Abasolo<\/em><\/strong>.<\/p>\n\n\n\n<p>Nadadores, Coahuila de Zaragoza; a 8 de Marzo de 2022.- En gira de trabajo por municipios de la regi\u00f3n Centro, el gobernador Miguel \u00c1ngel Riquelme Sol\u00eds supervis\u00f3 las labores de infraestructura vial que se realizan en esta zona de Coahuila, en donde reiter\u00f3 que con la uni\u00f3n de esfuerzos entre Estado y municipios se logran acciones que elevan la calidad de vida de sus habitantes.<\/p>\n\n\n\n<p>El Mandatario estatal reconoci\u00f3 el esfuerzo de los diputados federales para que se obtenga un mayor presupuesto para Coahuila, para poder ejecutar un mayor n\u00famero de obras que son necesarias en cada regi\u00f3n de la entidad.<\/p>\n\n\n\n<p>Durante su visita a Nadadores, San Buenaventura y Abasolo, se inform\u00f3 que la aplicaci\u00f3n de recursos en los trabajos en estos tres municipios son por el orden de los 95.7 millones de pesos.\u00a0En esta jornada de trabajo, el Gobernador de Coahuila pidi\u00f3 a los habitantes de todos los municipios seguir adelante con las campa\u00f1as de vacunaci\u00f3n y que acudan a aplicarse los refuerzos en cuidado de su vida.<\/p>\n\n\n\n<p>Reafirm\u00f3 que continuar\u00e1 trabajando en materia de seguridad con los ayuntamientos, porque se mantiene la entidad como uno de los estados m\u00e1s seguros del Pa\u00eds, estando a punto de entregar un nuevo cuartel en Ciudad Acu\u00f1a, bajo el trabajo coordinado que hay con el Ej\u00e9rcito Mexicano.<\/p>\n\n\n\n<p>En Nadadores, acompa\u00f1ado por la alcaldesa Mar\u00eda Alejandra Huerta Alem\u00e1n, Miguel Riquelme resalt\u00f3 que se han mejorado vialidades que fomentan a la vez mayor actividad econ\u00f3mica, lo que se ha evidenciado con las 17 cuadras y 18 mil 463 metros cuadrados de nuevo asfalto, y 21 mil 486 metros cuadrados de recarpeteo, con inversi\u00f3n de 19.4 millones de pesos.<\/p>\n\n\n\n<p>\u201cEstas acciones suman mucho para Nadadores, es un gran esfuerzo que se hace de manera conjunta en servicios b\u00e1sicos y primarios, planeando un presupuesto para obras pese a las reducciones que se tienen en los fondos para obra social a nivel federal, compensando con este tipo de acuerdos para acercar m\u00e1s beneficios a las familias coahuilenses\u201d, expres\u00f3.<\/p>\n\n\n\n<p>Inform\u00f3 que en febrero se registraron 8 mil nuevos empleos creados, gracias a la labor de todos los coahuilenses, porque es un c\u00edrculo virtuoso para tener buenos resultados y en materia de seguridad, y reiter\u00f3 que Nadadores contin\u00faa con su apoyo.<\/p>\n\n\n\n<p>La alcaldesa Mar\u00eda Alejandra Huerta agradeci\u00f3 al gobernador Miguel Riquelme por \u00e9ste, que es un beneficio colectivo, y mencion\u00f3 que la supervisi\u00f3n que este d\u00eda realiza es una acci\u00f3n que demuestra el inter\u00e9s por su gente, con obras requeridas que cumplen los compromisos de manera conjunta en pavimento y recarpeteo.<\/p>\n\n\n\n<p><strong>ALCALDE DE SAN BUENAVENTURA CUENTA CON MI APOYO: MARS.<\/strong><\/p>\n\n\n\n<p>En San Buenaventura, Riquelme Sol\u00eds supervis\u00f3 las obras de pavimentaci\u00f3n y recarpeteo que se llevan a cabo en esta localidad, acompa\u00f1ado del alcalde Hugo Iv\u00e1n Lozano S\u00e1nchez, a quien refrend\u00f3 su compromiso de trabajo conjunto, y reiter\u00f3 ser un aliado de San Buenaventura.<\/p>\n\n\n\n<p>Las obras que se visitaron van desde la rehabilitaci\u00f3n del cuerpo sur de la Carretera Federal 30, tramo Frontera-San Buenaventura, en la que se aplican recursos estimados de 32.5 millones de pesos, hasta recarpeteos y pavimentaciones nuevas, que suman 34.3 millones de pesos adicionales en 65 cuadras.\u00a0\u00a0\u201cEn San Buena se llevan a cabo trabajos sin precedente en la gesti\u00f3n de Gladys Ayala, y que ahora se concreta con Hugo Lozano, lo que demuestra que se trabaja con las nuevas autoridades municipales, y en breve nos sentaremos a invertirle entre los dos, Estado y Municipio, por el bien de nuestra regi\u00f3n; es un gran esfuerzo el que realizamos en conjunto\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Riquelme Sol\u00eds record\u00f3 que se tiene en puerta la continuidad del proyecto de un corredor econ\u00f3mico para Coahuila, que se encuentra planteado en el Plan Estatal de Desarrollo, y se har\u00e1n esfuerzos para tener los cuatro libramientos restantes del corredor desde Mazatl\u00e1n, que pasa por Torre\u00f3n, la Regi\u00f3n Centro, y hasta Ciudad Acu\u00f1a y Piedras Negras, y que se contin\u00faa la promoci\u00f3n econ\u00f3mica de las cinco regiones de la entidad para nuevas inversiones.<\/p>\n\n\n\n<p>El edil Lozano S\u00e1nchez refrend\u00f3 el compromiso de trabajar en equipo con la sociedad, Municipio y Estado, ya que deja mayor obra urbana y social en sectores que demandan estructura vial, agua potable, mejores accesos y v\u00edas de comunicaci\u00f3n.\u00a0\u201cGracias, estas acciones facilitan el vivir cotidiano de los habitantes y les da valor agregado a las propiedades de los vecinos beneficiados; son tiempos dif\u00edciles, pero el compromiso que tiene usted con los coahuilenses se deja ver claramente; aqu\u00ed trabajamos desde el primer d\u00eda\u201d, mencion\u00f3 el Presidente Municipal.<\/p>\n\n\n\n<p>El titular de la Secretar\u00eda de Infraestructura, Desarrollo Urbano y Movilidad del Estado (SIDUM), Miguel Algara Acosta, expuso las obras que se realizan son de rehabilitaci\u00f3n de la carretera con 50 mil 964 metros cuadrados, mientras que de recarpeteo son 42 mil 675 metros cuadrados en 65 calles de colonias como Benito Ju\u00e1rez, Pueblo Nuevo, Privada Granjeros, Zona Centro, Nueva Esperanza, Valle Campestre, Amalia Solorzano, Eulalio Guti\u00e9rrez y Solidaridad.<\/p>\n\n\n\n<p><strong>REITERA COORDINACI\u00d3N CON ABASOLO.<\/strong><\/p>\n\n\n\n<p>Dentro de su gira por esta regi\u00f3n, el gobernador Miguel Riquelme arrib\u00f3 a la Zona Centro del Municipio de Abasolo, en donde junto al alcalde Ramiro Reyes Rodr\u00edguez conoci\u00f3 el avance de la obra de infraestructura vial que se lleva a cabo aqu\u00ed, con el compromiso de seguir en la transformaci\u00f3n de todas las comunidades del estado.<\/p>\n\n\n\n<p>\u201cVengo a trabajar de manera coordinada, a hacer equipo\u201d, subray\u00f3, y reiter\u00f3 al Presidente Municipal su disposici\u00f3n para tener mayor infraestructura en este Municipio, al comentar que se seguir\u00e1, de manera coordinada, como un nuevo polo para mayores empleos, mejores v\u00edas de comunicaci\u00f3n y con nuevos modelos financieros.<\/p>\n\n\n\n<p>Por su parte, el alcalde Reyes Rodr\u00edguez agradeci\u00f3 el apoyo que se brinda por parte del Gobierno Estatal para lograr avanzar en obras que la ciudadan\u00eda requiere: \u201cNos da gusto que venga a este municipio; la infraestructura es fundamental para la actividad principal, que es la agricultura, nos da mayor impulso para el traslado de nuestros productos\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>Mientras que el titular de la SIDUM detall\u00f3 que la rehabilitaci\u00f3n del Libramiento Abasolo-Los Rodr\u00edguez tiene una inversi\u00f3n de 3.3 millones de pesos, as\u00ed como los nuevos accesos viales en diversas calles del municipio, con aplicaci\u00f3n de 6.2 millones de pesos, con m\u00e1s de 22 mil 348 metros cuadrados de pavimento en nueve cuadras.<\/p>\n\n\n\n<p>En esta gira de supervisi\u00f3n de obras por la Regi\u00f3n Centro acompa\u00f1aron al Gobernador, adem\u00e1s, los diputados locales Jorge Antonio Abdal\u00e1 Serna y Guadalupe Oyervides Valdez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Visita los municipios de Nadadores, San Buenaventura y Abasolo. Nadadores, Coahuila de Zaragoza; a 8 de Marzo de 2022.- En gira de trabajo por municipios de la regi\u00f3n Centro, el gobernador Miguel \u00c1ngel Riquelme Sol\u00eds supervis\u00f3 las labores de infraestructura vial que se realizan en esta zona de Coahuila, en donde reiter\u00f3 que con la uni\u00f3n de esfuerzos entre Estado y municipios se logran acciones que elevan la calidad de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7556,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,77,75],"tags":[],"class_list":["post-7555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-infraestructura","category-obra","wpcat-5-id","wpcat-15-id","wpcat-77-id","wpcat-75-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=7555"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7555\/revisions"}],"predecessor-version":[{"id":7557,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7555\/revisions\/7557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/7556"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=7555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=7555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=7555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}