{"id":7673,"date":"2022-03-15T18:21:09","date_gmt":"2022-03-16T00:21:09","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=7673"},"modified":"2022-03-15T18:21:09","modified_gmt":"2022-03-16T00:21:09","slug":"historias-que-no-pedimos-libro-de-testimoniales-de-familias-de-desaparecidos-es-presentado-en-casa-mudejar-de-torreon","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/03\/15\/historias-que-no-pedimos-libro-de-testimoniales-de-familias-de-desaparecidos-es-presentado-en-casa-mudejar-de-torreon\/","title":{"rendered":"\u2018HISTORIAS QUE NO PEDIMOS\u2019, LIBRO DE TESTIMONIALES DE FAMILIAS DE DESAPARECIDOS, ES PRESENTADO EN CASA MUD\u00c9JAR DE TORRE\u00d3N."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila de Zaragoza; a 15 de Marzo de 2022.- Es &#8220;la voz para la injusticia&#8221;, as\u00ed describi\u00f3 Norma Patricia, madre de una joven desaparecida, a la historia contada desde su trinchera y que forma parte del libro &#8220;Historias que no pedimos&#8221;, presentado en el Centro Cultural Casa Mud\u00e9jar de Torre\u00f3n.<\/p>\n\n\n\n<p>Este relato y varios m\u00e1s, son el resultado del Taller de Escritura Testimonial que se imparti\u00f3 en diversos municipios de Coahuila y que ser\u00e1 replicado en lo pr\u00f3ximo, a familiares de desaparecidos, quienes a trav\u00e9s de diversas t\u00e9cnicas, aprendieron a relatar \u201csu dolor m\u00e1s profundo\u201d, para visibilizar y concientizar sobre la tragedia que sufren cientos de familias en el Pa\u00eds ante las desapariciones forzadas.<\/p>\n\n\n\n<p>Esta presentaci\u00f3n fue organizada por la Secretar\u00eda de Cultura de Coahuila, el Instituto Municipal de Cultura y Educaci\u00f3n, en colaboraci\u00f3n con la Comisi\u00f3n Nacional de B\u00fasqueda y cont\u00f3 con la presencia de Martha Alicia Sinecio, Norma Patricia Albino, Alma Gabriela \u00c1lvarez, Juana Isabel Barraza, Yadira Fern\u00e1ndez Guti\u00e9rrez, quienes con la ense\u00f1anza del escritor y columnista Jaime Mu\u00f1oz Vargas, pudieron ofrecer su testimonial a trav\u00e9s de la redacci\u00f3n de sus vivencias.<\/p>\n\n\n\n<p>En este evento, la Secretaria de Cultura en el estado, Ana Sof\u00eda Garc\u00eda Camil, se\u00f1al\u00f3 que es de admirarse la lucha que cada familia emprende para buscar a quienes les faltan, as\u00ed como esta labor de dar testimonio y de revivir en cada palabra, el dolor profundo que tienen en cada d\u00eda de sus vidas.<\/p>\n\n\n\n<p>Como es una experiencia enriquecedora y a decir de una de las escritoras, sanadora, este taller ser\u00e1 replicado en otras ciudades del estado: &#8220;Ya se tiene contemplado Saltillo y Ciudad Acu\u00f1a para este a\u00f1o&#8221;.<\/p>\n\n\n\n<p>Fue durante el segundo semestre de 2019 que se llevaron a cabo dos talleres de Escritura Testimonial con familiares de personas desaparecidas en Piedras Negras, Allende y Torre\u00f3n, y este libro fue el resultado de las experiencias compartidas durante los meses que duraron las sesiones.\u00a0Las voces que se escucharon en estos testimonios nos cuentan los acontecimientos que vivieron.<\/p>\n\n\n\n<p>El escritor lagunero y capacitador de estos talleres, Jaime Mu\u00f1oz Vargas, expres\u00f3: \u201cLos cinco testimonios que escuch\u00e9, y luego le\u00ed\u0301, atraviesan la experiencia del familiar del desaparecido. En todos los casos hay un antes y un despu\u00e9s, un crack, una fractura, un d\u00eda distinto. La idea es que los potenciales lectores de estos textos escuchen con los ojos a Martha, Gabriela, Norma, Juanita y Yadira\u201d.<\/p>\n\n\n\n<p>Al finalizar esta presentaci\u00f3n, las escritoras pidieron que, quien llegue a tener este libro en sus manos, lo lea con plena atenci\u00f3n y despu\u00e9s, lo haga llegar a otra familia, para que as\u00ed, este efecto de empat\u00eda y concientizaci\u00f3n se replique en cada rinc\u00f3n de nuestro estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila de Zaragoza; a 15 de Marzo de 2022.- Es &#8220;la voz para la injusticia&#8221;, as\u00ed describi\u00f3 Norma Patricia, madre de una joven desaparecida, a la historia contada desde su trinchera y que forma parte del libro &#8220;Historias que no pedimos&#8221;, presentado en el Centro Cultural Casa Mud\u00e9jar de Torre\u00f3n. Este relato y varios m\u00e1s, son el resultado del Taller de Escritura Testimonial que se imparti\u00f3 en diversos municipios&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,12,15,28,24,7],"tags":[],"class_list":["post-7673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-cultura","category-gobierno-de-coahuila","category-la-laguna","category-seguridad","category-torreon","wpcat-5-id","wpcat-12-id","wpcat-15-id","wpcat-28-id","wpcat-24-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=7673"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7673\/revisions"}],"predecessor-version":[{"id":7675,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7673\/revisions\/7675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/7674"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=7673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=7673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=7673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}