{"id":7823,"date":"2022-03-24T18:46:46","date_gmt":"2022-03-25T00:46:46","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=7823"},"modified":"2022-03-24T18:46:46","modified_gmt":"2022-03-25T00:46:46","slug":"coordinacion-fundamental-para-conservar-seguro-a-coahuila-mars","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/03\/24\/coordinacion-fundamental-para-conservar-seguro-a-coahuila-mars\/","title":{"rendered":"COORDINACI\u00d3N, FUNDAMENTAL PARA CONSERVAR SEGURO A COAHUILA: MARS."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>\u00a0Durante visita del Subsecretario de Seguridad P\u00fablica, Ricardo Mej\u00eda Berdeja, se logran acuerdos en temas migratorios, infraestructura y armamento.<\/em><\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong><em>&nbsp;Hay voluntad del Gobierno Federal para la coordinaci\u00f3n de esfuerzos con el Estado, reitera el Subsecretario.<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; 24 de Marzo de 2022.- Este jueves, el Gobernador de Coahuila, Miguel \u00c1ngel Riquelme Sol\u00eds, recibi\u00f3 al Subsecretario de Seguridad P\u00fablica Federal, Ricardo Mej\u00eda Berdeja, con quien presidi\u00f3 una mesa de trabajo para atender en conjunto los temas que en com\u00fan atienden el Estado y la Federaci\u00f3n, resaltando en los mensajes que la coordinaci\u00f3n entre los niveles de Gobierno y de las corporaciones ha sido fundamental para conseguir que Coahuila sea un Estado con \u00edndices delictivos a la baja.<\/p>\n\n\n\n<p>Durante el encuentro, Mej\u00eda Berdeja reiter\u00f3 la voluntad de coordinaci\u00f3n plena por parte del Gobierno Federal, a trav\u00e9s de la Secretar\u00eda de Seguridad P\u00fablica, y establecer as\u00ed los mecanismos m\u00e1s eficientes de vigilancia, prevenci\u00f3n y atenci\u00f3n de las situaciones de riesgo como parte de la estrategia de seguridad, que ya ha demostrado buenos resultados para la tranquilidad de Coahuila.<\/p>\n\n\n\n<p>En ese sentido, en la reuni\u00f3n se revisaron las estad\u00edsticas de il\u00edcitos cometidos en la entidad, que muestran una tendencia a la baja para llegar, al d\u00eda de hoy, a su punto m\u00e1s bajo de los \u00faltimos a\u00f1os, seg\u00fan datos que proporcionan las diferentes corporaciones y que peri\u00f3dicamente se han dado a conocer por las fuentes oficiales.<\/p>\n\n\n\n<p>El gobernador Riquelme Sol\u00eds acord\u00f3 con el Subsecretario federal comenzar los procesos ante el Instituto de Administraci\u00f3n y Aval\u00faos de Bienes Nacionales (INDAABIN) para que el Estado reciba en cesi\u00f3n las instalaciones del Centro Federal de Rehabilitaci\u00f3n Social n\u00famero 10, ubicado en el Municipio de Monclova, adem\u00e1s de que durante el proceso de los tr\u00e1mites legales se iniciar\u00e1n una serie de visitas al inmueble para determinar las condiciones y las necesidades que se tengan para su rehabilitaci\u00f3n por parte del Gobierno de Coahuila.<\/p>\n\n\n\n<p>Respecto al tema migratorio, Riquelme Sol\u00eds y Mej\u00eda Berdeja coincidieron en la necesidad de reforzar de manera conjunta los operativos para la revisi\u00f3n, detecci\u00f3n y retorno en el menor tiempo posible de personas extranjeras que se encuentran en territorio coahuilense sin documentos que avalen su estancia legal.<\/p>\n\n\n\n<p>Se revisaron las estad\u00edsticas del 2021 y los primeros meses del a\u00f1o en curso, estableciendo el acuerdo de reforzar los filtros carreteros en coordinaci\u00f3n plena entre la Polic\u00eda Estatal, la Fiscal\u00eda General, el Ej\u00e9rcito Mexicano, la Guardia Nacional y el Instituto Nacional de Migraci\u00f3n.<\/p>\n\n\n\n<p>En este mismo tema, el gobernador Riquelme Sol\u00eds inform\u00f3 que se realizar\u00e1n reuniones de evaluaci\u00f3n diarias de los resultados y operaci\u00f3n de los puntos de revisi\u00f3n, cuyo resultado ser\u00e1 compartido tambi\u00e9n con la Oficina de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos (CBP, por sus siglas en ingl\u00e9s).<\/p>\n\n\n\n<p>Riquelme Sol\u00eds pidi\u00f3 al Subsecretario federal dar seguimiento puntual a la compra de armamentos, municiones y dem\u00e1s equipos policiales, especialmente respecto a la compra de rifles de alto calibre, para agilizarlos y que se entreguen a la Polic\u00eda Estatal para reforzar el blindaje del estado y garantizar el no ingreso de la delincuencia organizada al territorio estatal.<\/p>\n\n\n\n<p>La reuni\u00f3n se llev\u00f3 a cabo con la asistencia del Secretario de Gobierno de Coahuila, Fernando de las Fuentes Hern\u00e1ndez; la Secretaria de Seguridad P\u00fablica, Sonia Villarreal P\u00e9rez; el Fiscal General del Estado, Gerardo M\u00e1rquez Guevara; el Coordinador General de Comunicaci\u00f3n e Imagen Institucional, Fernando Sim\u00f3n Guti\u00e9rrez P\u00e9rez; el titular de la Unidad de Administraci\u00f3n y Finanzas, Manuel de Jes\u00fas Luj\u00e1n L\u00f3pez; y el titular de la Unidad de Pol\u00edtica Policial, Penitenciaria y Seguridad Privada, Antonio Hazael Ruiz Ortega.<\/p>\n\n\n\n<p>Tambi\u00e9n el titular de la Unidad de Informaci\u00f3n, Infraestructura Inform\u00e1tica y Vinculaci\u00f3n Tecnol\u00f3gica, Miguel \u00c1ngel Urrutia Lozano; el Coordinador Nacional Antisecuestro, Marco Antonio Vargas Gonz\u00e1lez; el Director de la Guardia Nacional, general Cruz Isaac Mu\u00f1oz Navarro; el Director General de Control y Verificaci\u00f3n Migratoria, Antonio Molina D\u00edaz; y la Directora General de Inform\u00e1tica y Telecomunicaciones de la&nbsp; Fiscal\u00eda, Liliana D\u00e1vila Torres, e Israel Pita Garrido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Durante visita del Subsecretario de Seguridad P\u00fablica, Ricardo Mej\u00eda Berdeja, se logran acuerdos en temas migratorios, infraestructura y armamento. \u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Hay voluntad del Gobierno Federal para la coordinaci\u00f3n de esfuerzos con el Estado, reitera el Subsecretario. Saltillo, Coahuila de Zaragoza; 24 de Marzo de 2022.- Este jueves, el Gobernador de Coahuila, Miguel \u00c1ngel Riquelme Sol\u00eds, recibi\u00f3 al Subsecretario de Seguridad P\u00fablica Federal, Ricardo Mej\u00eda Berdeja, con quien presidi\u00f3 una mesa de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7824,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,24],"tags":[],"class_list":["post-7823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-seguridad","wpcat-5-id","wpcat-15-id","wpcat-24-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=7823"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7823\/revisions"}],"predecessor-version":[{"id":7825,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7823\/revisions\/7825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/7824"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=7823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=7823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=7823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}