{"id":7929,"date":"2022-03-31T18:28:49","date_gmt":"2022-04-01T00:28:49","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=7929"},"modified":"2022-03-31T18:28:50","modified_gmt":"2022-04-01T00:28:50","slug":"avanza-vacunacion-transfronteriza-a-menores-en-coahuila","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/03\/31\/avanza-vacunacion-transfronteriza-a-menores-en-coahuila\/","title":{"rendered":"AVANZA VACUNACI\u00d3N TRANSFRONTERIZA A MENORES EN COAHUILA."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>Tras concluir con la zona norte, inici\u00f3 la aplicaci\u00f3n de dosis a menores de 5 a 11 a\u00f1os de la Regi\u00f3n Carbon\u00edfera.<\/em><\/strong><\/p>\n\n\n\n<p>San Juan de Sabinas, Coahuila de Zaragoza; a 31 de Marzo del 2022.- Como parte de la estrategia del Gobierno de Coahuila, a trav\u00e9s de la Secretaria de Salud del Estado, realizada ante autoridades norteamericanas, la Secretar\u00eda de Salud otorg\u00f3 apoyo a los estudiantes de 5 a 14 a\u00f1os \u2014primordialmente con comorbilidades\u2014 de Sabinas y San Juan de Sabinas para que se trasladaran al Municipio de Piedras Negras a recibir la vacuna contra el Covid-19.<\/p>\n\n\n\n<p>Roberto Bernal G\u00f3mez, Secretario de Salud en la entidad, indic\u00f3 que en coordinaci\u00f3n con los ayuntamientos mencionados viajaron este d\u00eda alrededor de 200 estudiantes para recibir las dosis.<\/p>\n\n\n\n<p>\u201cAtendemos una indicaci\u00f3n del gobernador Miguel \u00c1ngel Riquelme Sol\u00eds de iniciar ahora con la Regi\u00f3n Carbon\u00edfera, para posteriormente apoyar a la Regi\u00f3n Centro y as\u00ed cubrir toda la entidad\u201d, asent\u00f3.<\/p>\n\n\n\n<p>Lo primero fue otorgar a los sectores vulnerables en salud, con comorbilidades, para despu\u00e9s programar al resto de los estudiantes que cuentan con 5 a 14 a\u00f1os de edad.<\/p>\n\n\n\n<p>Bernal G\u00f3mez explic\u00f3 que se cont\u00f3 con el apoyo durante el recorrido de personal de la Jurisdicci\u00f3n Sanitaria 03, desde la salida hasta su retorno, por si presentan alg\u00fan malestar.<\/p>\n\n\n\n<p>La log\u00edstica consiste en llegar al Puente Internacional de Piedras Negras y posteriormente retornar en las mismas unidades de transporte, en cuesti\u00f3n de horas.<\/p>\n\n\n\n<p>Para esta vacunaci\u00f3n en la Regi\u00f3n Carbon\u00edfera se tiene estimado que ser\u00e1n&nbsp; 80 dosis para estudiantes de M\u00fazquiz, mientras que ser\u00e1 80 para San Juan de Sabinas y 60 para estudiantes de Sabinas.<\/p>\n\n\n\n<p>\u201cEso en primera etapa, sin embargo seguimos revisando el censo, por si alg\u00fan estudiante no ha sido contemplado\u201d, agreg\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Tras concluir con la zona norte, inici\u00f3 la aplicaci\u00f3n de dosis a menores de 5 a 11 a\u00f1os de la Regi\u00f3n Carbon\u00edfera. San Juan de Sabinas, Coahuila de Zaragoza; a 31 de Marzo del 2022.- Como parte de la estrategia del Gobierno de Coahuila, a trav\u00e9s de la Secretaria de Salud del Estado, realizada ante autoridades norteamericanas, la Secretar\u00eda de Salud otorg\u00f3 apoyo a los estudiantes de 5 a 14&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4,15,14,22],"tags":[],"class_list":["post-7929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-covid","category-gobierno-de-coahuila","category-salud","category-vacunas","wpcat-5-id","wpcat-4-id","wpcat-15-id","wpcat-14-id","wpcat-22-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=7929"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7929\/revisions"}],"predecessor-version":[{"id":7931,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/7929\/revisions\/7931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/7930"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=7929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=7929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=7929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}