{"id":8877,"date":"2022-05-26T18:48:32","date_gmt":"2022-05-26T23:48:32","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=8877"},"modified":"2022-05-26T18:48:32","modified_gmt":"2022-05-26T23:48:32","slug":"gobierno-del-estado-de-coahuila-informa-13","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/05\/26\/gobierno-del-estado-de-coahuila-informa-13\/","title":{"rendered":"Gobierno del Estado de Coahuila informa:"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila de Zaragoza; a 26 de Mayo de 2022.- La Subsecretar\u00eda de Protecci\u00f3n Civil del Estado (PC) informa que esta ma\u00f1ana se origin\u00f3 un incendio en la recicladora Suministro de Materiales Express S.A. de C.V., al oriente de la ciudad de Torre\u00f3n, lugar al que acudieron brigadas de varias corporaciones a atender el siniestro.<\/p>\n\n\n\n<p>Esta empresa se ubica en el Parque Industrial Mieleras.<\/p>\n\n\n\n<p>PC comunica que se est\u00e1n tomando las acciones necesarias para evacuar cualquier empresa contigua al incendio y salvaguardar la integridad de las personas, no se reportan lesionados.<\/p>\n\n\n\n<p>Al momento el incendio se encuentra controlado y brindan apoyo elementos de la Unidad Municipal de Protecci\u00f3n Civil, Bomberos Torre\u00f3n, Bomberos de Matamoros, Bomberos de Francisco I. Madero, Bomberos de San Pedro de las Colonias, y Bomberos de G\u00f3mez Palacio, as\u00ed como de parte de personal y equipos de empresas de particulares como Grupo Pe\u00f1oles, Grupo Simsa, Grupo Intergas, Grupo Lala, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila de Zaragoza; a 26 de Mayo de 2022.- La Subsecretar\u00eda de Protecci\u00f3n Civil del Estado (PC) informa que esta ma\u00f1ana se origin\u00f3 un incendio en la recicladora Suministro de Materiales Express S.A. de C.V., al oriente de la ciudad de Torre\u00f3n, lugar al que acudieron brigadas de varias corporaciones a atender el siniestro. Esta empresa se ubica en el Parque Industrial Mieleras. PC comunica que se est\u00e1n tomando&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,54],"tags":[],"class_list":["post-8877","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-gobierno-de-coahuila","category-proteccion-civil","wpcat-5-id","wpcat-15-id","wpcat-54-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/8877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=8877"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/8877\/revisions"}],"predecessor-version":[{"id":8878,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/8877\/revisions\/8878"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=8877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=8877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=8877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}