{"id":8934,"date":"2022-05-29T18:58:47","date_gmt":"2022-05-29T23:58:47","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=8934"},"modified":"2022-05-29T18:58:48","modified_gmt":"2022-05-29T23:58:48","slug":"el-congreso-capitalino-impondra-la-medalla-al-merito-periodistico","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/05\/29\/el-congreso-capitalino-impondra-la-medalla-al-merito-periodistico\/","title":{"rendered":"El Congreso capitalino impondr\u00e1 la Medalla al M\u00e9rito Period\u00edstico."},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li>El reconocimiento data de 2016 en honor a Miguel \u00c1ngel Granados Chapa.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>En M\u00e9xico hay registro de once periodistas asesinados en lo que va del a\u00f1o.<\/li><\/ul>\n\n\n\n<p>. Situaci\u00f3n cr\u00edtica, M\u00e9xico por arriba de Ucrania, pa\u00eds invadido por Rusia.<\/p>\n\n\n\n<p>El Congreso de la ciudad de M\u00e9xico impondr\u00e1 la Medalla al M\u00e9rito Period\u00edstico a los comunicadores Liliana Sosa, Lourdes Mendoza, Fernanda Tapia, Genaro Lozano, Leopoldo Mend\u00edvil y Jos\u00e9 V\u00edctor Rodr\u00edguez.<\/p>\n\n\n\n<p>\u201cSe trata de reconocer la labor profesional de las personas que se dedican a la loable tarea de comunicar; que en M\u00e9xico es catalogada como un oficio de alto riesgo que pone su vida en peligro\u201d, afirm\u00f3 la legisladora Ana Jocelyn Villagr\u00e1n Villasana, quien preside la comisi\u00f3n legislativa correspondiente.<\/p>\n\n\n\n<p>La periodista Liliana Sosa es conductora de diversos noticiarios en Grupo Multimedios y se hizo acreedora de dicho reconocimiento en la categor\u00eda de Televisi\u00f3n junto con Genaro Lozano de Grupo Televisa; mientras que Lourdes Mendoza y Leopoldo Mendivil se hicieron acreedores al galard\u00f3n en la categor\u00eda de nota informativa y reportaje.<\/p>\n\n\n\n<p>Por su parte, Jos\u00e9 V\u00edctor Rodr\u00edguez &#8211;cofundador del Centro de Derechos Humanos \u201cZeferino Ladrillero\u201d\u2014y corresponsal en M\u00e9xico de la Voz de Am\u00e9rica (VOA) ser\u00e1 reconocido por sus aportes en su columna \u201cSociedad\u201d, g\u00e9nero period\u00edstico que se distribuye a trav\u00e9s de SDP Noticias, el diario Contra R\u00e9plica, la Agencia de Noticias Libertad (ANI) y la Agencia Latinoamericana de Informaci\u00f3n (Alai).<\/p>\n\n\n\n<p>En este sentido, la legisladora Villagr\u00e1n Villasana explic\u00f3 que esta condecoraci\u00f3n se impone por el Poder Legislativo capitalino por el \u201ctrabajo que contribuye al desarrollo de los principios democr\u00e1ticos, entendidos como un sistema de vida fundado en el constante mejoramiento econ\u00f3mico, social y cultural\u201d.<\/p>\n\n\n\n<p>Entre los galardonados, adem\u00e1s est\u00e1n Elizabeth E. Ju\u00e1rez Montes de Oca y Jorge Ramos P\u00e9rez (La Silla Rota), en Radio; Judith S\u00e1nchez Reyes y Aurelio S\u00e1nchez Ram\u00edrez, en Nota Informativa y Reportaje; Daniel Flores Padilla, en Congreso; Jorge Carballo Diaz y Javier Arturo Jim\u00e9nez Nete en Fotograf\u00eda; Enrique Mart\u00ed Lazcano V\u00e1zquez y Edmundo Perfecto Olivares Alcal\u00e1, en categor\u00eda Docente; Fernanda Tapia Canovi y Glor\u00eda Lara, en YouTube; Ang\u00e9lica Cruz Aguilar y Eduardo Blancas, en la categor\u00eda La voz chilanga en el extranjero.<\/p>\n\n\n\n<p>La Medalla al M\u00e9rito Period\u00edstico \u201cMiguel \u00c1ngel Granados Chapa\u201d data desde 2016 cuando el Congreso local se identificaba como Asamblea Legislativa del entonces Distrito Federal en homenaje al periodista, autor de la columna Plaza P\u00fablica, que falleci\u00f3 a sus 70 a\u00f1os el 17 de octubre de 2011.<\/p>\n\n\n\n<p>En lo que va de este 2012, un total de once personas que ejerc\u00edan el periodismo han sido asesinadas en M\u00e9xico; cifra que ubica a nuestro pa\u00eds como el m\u00e1s peligroso para ejercer esta profesi\u00f3n por arriba de Ucrania, pa\u00eds donde se lleva a cabo una invasi\u00f3n militar por parte de Rusia.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Jos\u00e9 Luis Gamboa Arenas, asesinado a pu\u00f1aladas el 15 de enero, en Veracruz<\/li><li>Margarito Esquivel Mart\u00ednez, asesinado con arma de fuego el 17 de enero, en Tijuana<\/li><li>Lourdes Maldonado, asesinada a balazos a las afueras de su casa, el 23 de enero, en Tijuana<\/li><li>Roberto Toledo, asesinado afuera de las oficinas del diario Monitor Michoac\u00e1n, el 31 de enero<\/li><li>Heber L\u00f3pez V\u00e1zquez, asesinado de cinco balazos el 10 de febrero, cuando estaba en su oficina, ubicada en el centro de la ciudad de Salina Cruz, en Oaxaca<\/li><li>Jorge Camero Zazueta, asesinado a balazos al salir de un gimnasio, el 24 de febrero en la localidad de Empalme, en Sonora<\/li><li>Juan Carlos Mu\u00f1iz, asesinado de dos balazos en la cabeza el 4 de marzo, en Fresnillo, Zacatecas<\/li><li>Armando Linares L\u00f3pez, ejecutado dentro de su casa el 5 de marzo, en Zit\u00e1cuaro, Michoac\u00e1n<\/li><li>Luis Enrique Ram\u00edrez, hallado muerto el 6 de mayo, tras ser secuestrado cerca de su casa, en Sinaloa<\/li><li>Yessenia Mollinedo, asesinada el 9 de mayo en un ataque armado directo en Cosoleacaque, Veracruz<\/li><li>Sheila Johana Garc\u00eda Oliveira, muri\u00f3 en el mismo ataque armado en Cosoleacaque, Veracruz, en el que fue asesinada su compa\u00f1era Yessenia Mollinedo<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El reconocimiento data de 2016 en honor a Miguel \u00c1ngel Granados Chapa. En M\u00e9xico hay registro de once periodistas asesinados en lo que va del a\u00f1o. . Situaci\u00f3n cr\u00edtica, M\u00e9xico por arriba de Ucrania, pa\u00eds invadido por Rusia. El Congreso de la ciudad de M\u00e9xico impondr\u00e1 la Medalla al M\u00e9rito Period\u00edstico a los comunicadores Liliana Sosa, Lourdes Mendoza, Fernanda Tapia, Genaro Lozano, Leopoldo Mend\u00edvil y Jos\u00e9 V\u00edctor Rodr\u00edguez. \u201cSe trata&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-8934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diputados","wpcat-66-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/8934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=8934"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/8934\/revisions"}],"predecessor-version":[{"id":8936,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/8934\/revisions\/8936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/8935"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=8934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=8934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=8934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}