{"id":9370,"date":"2022-06-17T17:51:07","date_gmt":"2022-06-17T22:51:07","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=9370"},"modified":"2022-06-17T17:51:07","modified_gmt":"2022-06-17T22:51:07","slug":"museo-acertijo-celebra-el-dia-del-padre-con-2x1-en-entradas","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/06\/17\/museo-acertijo-celebra-el-dia-del-padre-con-2x1-en-entradas\/","title":{"rendered":"MUSEO ACERTIJO CELEBRA EL D\u00cdA DEL PADRE CON 2X1 EN ENTRADAS."},"content":{"rendered":"\n<p>Comarca Lagunera.- Con el prop\u00f3sito de que las familias de la regi\u00f3n laguna de<br>Durango celebren el d\u00eda del padre con un momento de esparcimiento y aprendizaje<br>interactivo, el Museo Acertijo los invita para que asistan este pr\u00f3ximo s\u00e1bado 19 y<br>domingo 20 de junio, de 11 de la ma\u00f1ana a 7 de la noche y aprovechen la promoci\u00f3n<br>de 2&#215;1 en el costo de boleto de entrada.<\/p>\n\n\n\n<p>As\u00ed lo inform\u00f3 M\u00f3nica Villegas Flores, jefa de departamento del Museo, quien destac\u00f3<br>que tienen la capacidad para recibir cerca de 300 visitantes y durante este fin de<br>semana estar\u00e1n brindando la promoci\u00f3n de 2&#215;1 en las entradas. El costo de entrada<br>al museo es de 50 pesos y se paga boleto a partir de los tres a\u00f1os.<\/p>\n\n\n\n<p>El Museo Interactivo Acertijo ofrece m\u00e1s de 100 exposiciones, talleres y sumado a ello<br>los asistentes podr\u00e1n disfrutar de una funci\u00f3n de cine familiar, en la sala de cine del<br>museo, en los horarios de 1:00, 3:00 y 5:00 de la tarde.<\/p>\n\n\n\n<p>A trav\u00e9s de las actividades interactivas chicos y grandes podr\u00e1n jugar, aprender y<br>experimentar sobre ciencia, tecnolog\u00eda, cultura, el ser humano, biolog\u00eda y muchos<br>otros temas, ideales para acudir en familia y divertirse.<\/p>\n\n\n\n<p>Para mayores informes o para realizar alguna reservaci\u00f3n, los interesados podr\u00e1n<br>hacerlo a trav\u00e9s de la p\u00e1gina de facebook: Acertijo Museo Interactivo Laguna<br>Durango.<\/p>\n\n\n\n<p>Finalmente hizo un llamado a todas las familias de la regi\u00f3n para que se animen a<br>celebrar el d\u00eda del padre de una manera diferente con juegos, aprendizaje y sana<br>convivencia con sus seres queridos, en el Museo Interactivo Acertijo, ubicado en:<br>Calzada Forjadores y Jes\u00fas Garc\u00eda Corona s\/n Colonia Brittingham en G\u00f3mez<br>Palacio, frente a la casa de gobierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comarca Lagunera.- Con el prop\u00f3sito de que las familias de la regi\u00f3n laguna deDurango celebren el d\u00eda del padre con un momento de esparcimiento y aprendizajeinteractivo, el Museo Acertijo los invita para que asistan este pr\u00f3ximo s\u00e1bado 19 ydomingo 20 de junio, de 11 de la ma\u00f1ana a 7 de la noche y aprovechen la promoci\u00f3nde 2&#215;1 en el costo de boleto de entrada. As\u00ed lo inform\u00f3 M\u00f3nica Villegas Flores,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9371,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,40,64],"tags":[],"class_list":["post-9370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-durango","category-gobierno-de-durango","wpcat-12-id","wpcat-40-id","wpcat-64-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=9370"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9370\/revisions"}],"predecessor-version":[{"id":9372,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9370\/revisions\/9372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/9371"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=9370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=9370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=9370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}