{"id":9580,"date":"2022-06-28T18:29:22","date_gmt":"2022-06-28T23:29:22","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=9580"},"modified":"2022-06-28T18:29:23","modified_gmt":"2022-06-28T23:29:23","slug":"anuncia-turismo-coahuila-cabalgata-santo-domingo-sabinas","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/06\/28\/anuncia-turismo-coahuila-cabalgata-santo-domingo-sabinas\/","title":{"rendered":"ANUNCIA TURISMO COAHUILA CABALGATA SANTO DOMINGO \u2013 SABINAS."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>M\u00e1s de 300 jinetes recorren 320 kil\u00f3metros en el semi desierto coahuilense durante siete d\u00edas.<\/em><\/strong><\/p>\n\n\n\n<p>Ramos Arizpe, Coahuila de Zaragoza; a 28 de Junio de 2022.- Gracias a las excelentes condiciones de seguridad que imperan en el estado, este a\u00f1o se llevar\u00e1 a cabo la Edici\u00f3n 31 de la Cabalgata Santo Domingo-Sabinas del 3 al 9 de septiembre, que recorre 320 kil\u00f3metros en seis diferentes municipios de Coahuila.<\/p>\n\n\n\n<p>Con la representaci\u00f3n del gobernador Miguel \u00c1ngel Riquelme Sol\u00eds, Azucena Ramos Ramos, Secretaria de Turismo y Desarrollo de Pueblos M\u00e1gicos, anunci\u00f3 este evento en el que se espera la participaci\u00f3n de m\u00e1s de 300 jinetes.<\/p>\n\n\n\n<p>Ramos Ramos estuvo acompa\u00f1ada por Jos\u00e9 Mar\u00eda Morales Padilla, Alcalde de Ramos Arizpe; Diana Haro Mart\u00ednez, Alcaldesa de Sabinas; Sandra Valenciana Guerra, presidenta de esta cabalgata; as\u00ed como por R\u00e9gulo Zapata Jaime, fundador de este tradicional recorrido a caballo que se realiza desde 1992.<\/p>\n\n\n\n<p>La Cabalgata Santo Domingo \u2013 Sabinas conmemora el recorrido realizado en 1880 por un grupo de jinetes que se aventur\u00f3 por el desierto de Coahuila hasta llegar a un caudaloso r\u00edo y fundar ah\u00ed lo que es hoy la Ciudad de Sabinas, principal motor de la Regi\u00f3n Carbon\u00edfera.<\/p>\n\n\n\n<p>La titular de Turismo de la entidad record\u00f3 que hace un a\u00f1o la llamada \u201cMadre de las Cabalgatas\u201d fue nombrada como Patrimonio Cultural Intangible de Coahuila por parte del Congreso del Estado.<\/p>\n\n\n\n<p>\u201cEste recorrido a caballo, que partir\u00e1 desde el Ejido Santo Domingo, Municipio de Ramos Arizpe, cumple ya m\u00e1s de tres d\u00e9cadas uniendo a los cabalgantes en este recorrido de 320 kil\u00f3metros sobre el terreno semides\u00e9rtico\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>Agreg\u00f3 que con esta cabalgata se apoya al comercio de los municipios por donde pasa el recorrido, y que gracias a ello m\u00faltiples familias se ver\u00e1n beneficiadas al aportar diversos servicios a los participantes y sumar\u00e1n para que sea una grata experiencia para los turistas.<\/p>\n\n\n\n<p>\u201cEste es un momento muy importante para Coahuila, una etapa en la que las instancias p\u00fablicas y privadas estamos trabajando fuertemente y de manera coordinada para impulsar la actividad econ\u00f3mica, y en particular para diversificar la econom\u00eda de la Regi\u00f3n Carbon\u00edfera, por eso los invitamos a apoyar estos eventos para seguir creando juntos m\u00e1s oportunidades que generen recursos inmediatos para que la econom\u00eda de nuestros municipios siga avanzando a trav\u00e9s del turismo.<\/p>\n\n\n\n<p>Reiter\u00f3 el compromiso del Gobierno del Estado para seguir apoyando a los organizadores en varios aspectos para lograr resultados positivos: \u201cLo mejor es continuar unidos en esta ruta que nos beneficia a todos\u201d.<\/p>\n\n\n\n<p>La presidenta de la cabalgata, Sandra Valenciana, inform\u00f3 que el recorrido de m\u00e1s de 320 kil\u00f3metros pasa por seis municipios de la entidad, al iniciar la traves\u00eda en Santo Domingo &#8211; Pared\u00f3n; Pared\u00f3n &#8211; Espinazo; Espinazo &#8211; El Marques; El Marques &#8211; Los Cascabeles; Los Cascabeles &#8211; Hermanas; Hermanas &#8211; La Bazooka; La Bazooka &#8211; Sabinas.<\/p>\n\n\n\n<p>Mencion\u00f3 que para este a\u00f1o se develar\u00e1 un mural de un paisaje de la Hacienda el Mimbre, que medir\u00e1 cinco metros de altura por 25 metros de largo.<\/p>\n\n\n\n<p>Por su parte, el Alcalde de Ramos Arizpe, Jos\u00e9 Mar\u00eda Morales Padilla, reiter\u00f3 todo el apoyo de su Municipio para que esta cabalgata sea todo un \u00e9xito.<\/p>\n\n\n\n<p>\u201cLa historia nos une con Sabinas\u201d, expres\u00f3.<\/p>\n\n\n\n<p>En su intervenci\u00f3n, Diana Haro Mart\u00ednez, Alcaldesa de Sabinas, record\u00f3 que el pr\u00f3ximo 12 de septiembre este Municipio celebra el 80 Aniversario de haber sido elevado a categor\u00eda de Ciudad, por lo que la cabalgata se unir\u00e1 a las festividades de su localidad.<\/p>\n\n\n\n<p>En este anuncio de la Cabalgata Santo Domingo \u2013 Sabinas estuvieron presentes, adem\u00e1s, Alejandro Gonz\u00e1lez Far\u00edas, Secretario del Ayuntamiento de Ramos Arizpe; Jos\u00e9 Humberto Garc\u00eda Zertuche, Secretario de Desarrollo Rural en Ramos Arizpe, y Andr\u00e9s Velasco Cuevas, presidente de la OCV Saltillo.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0M\u00e1s de 300 jinetes recorren 320 kil\u00f3metros en el semi desierto coahuilense durante siete d\u00edas. Ramos Arizpe, Coahuila de Zaragoza; a 28 de Junio de 2022.- Gracias a las excelentes condiciones de seguridad que imperan en el estado, este a\u00f1o se llevar\u00e1 a cabo la Edici\u00f3n 31 de la Cabalgata Santo Domingo-Sabinas del 3 al 9 de septiembre, que recorre 320 kil\u00f3metros en seis diferentes municipios de Coahuila. Con la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9581,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,34],"tags":[],"class_list":["post-9580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-turismo","wpcat-5-id","wpcat-15-id","wpcat-34-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=9580"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9580\/revisions"}],"predecessor-version":[{"id":9582,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9580\/revisions\/9582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/9581"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=9580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=9580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=9580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}