{"id":9774,"date":"2022-07-06T18:38:21","date_gmt":"2022-07-06T23:38:21","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=9774"},"modified":"2022-07-06T18:38:22","modified_gmt":"2022-07-06T23:38:22","slug":"reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-388","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/07\/06\/reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-388\/","title":{"rendered":"REPORTE COAHUILA DEL PLAN ESTATAL DE PREVENCI\u00d3N Y CONTROL COVID- 19."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 6 de julio del 2022.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa:<\/p>\n\n\n\n<p>1.- Al d\u00eda de hoy se registran 894&nbsp; nuevos casos en Coahuila, incluidas dos defunciones.<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE CASOS<\/p>\n\n\n\n<p>291 SALTILLO<\/p>\n\n\n\n<p>243 TORRE\u00d3N<\/p>\n\n\n\n<p>79 MONCLOVA<\/p>\n\n\n\n<p>41 PIEDRAS NEGRAS<\/p>\n\n\n\n<p>33 MATAMOROS<\/p>\n\n\n\n<p>28 RAMOS ARIZPE<\/p>\n\n\n\n<p>26 FRANCISCO I. MADERO<\/p>\n\n\n\n<p>20 SABINAS<\/p>\n\n\n\n<p>17 M\u00daZQUIZ<\/p>\n\n\n\n<p>16 ACU\u00d1A<\/p>\n\n\n\n<p>16 SAN PEDRO<\/p>\n\n\n\n<p>15 FRONTERA<\/p>\n\n\n\n<p>15 PARRAS DE LA FUENTE<\/p>\n\n\n\n<p>11 SAN JUAN DE SABINAS<\/p>\n\n\n\n<p>8 CASTA\u00d1OS<\/p>\n\n\n\n<p>6 SAN BUENAVENTURA<\/p>\n\n\n\n<p>5 CUATRO CI\u00c9NEGAS<\/p>\n\n\n\n<p>5 ARTEAGA<\/p>\n\n\n\n<p>5 NAVA<\/p>\n\n\n\n<p>4 ZARAGOZA<\/p>\n\n\n\n<p>3 GENERAL CEPEDA<\/p>\n\n\n\n<p>3 NADADORES<\/p>\n\n\n\n<p>2 VILLA UNI\u00d3N<\/p>\n\n\n\n<p>1 MORELOS<\/p>\n\n\n\n<p>1 VIESCA<\/p>\n\n\n\n<p>DEFUNCIONES<\/p>\n\n\n\n<p>TORRE\u00d3N<\/p>\n\n\n\n<p>Hombre de 78 a\u00f1os (caso ya reportado)<\/p>\n\n\n\n<p>SABINAS<\/p>\n\n\n\n<p>Mujer de 74 a\u00f1os (caso ya reportado)<\/p>\n\n\n\n<p>2.- Existen AHORA en Coahuila 5,237&nbsp; casos activos de COVID \u2013 19<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE CASOS ACTIVOS<\/p>\n\n\n\n<p>-Torre\u00f3n 1,809<\/p>\n\n\n\n<p>-Saltillo 1,530<\/p>\n\n\n\n<p>-Monclova 354<\/p>\n\n\n\n<p>-Piedras Negras 280<\/p>\n\n\n\n<p>-Ramos Arizpe 183<\/p>\n\n\n\n<p>-San Pedro 150<\/p>\n\n\n\n<p>-Matamoros 141<\/p>\n\n\n\n<p>-Francisco I. Madero 126<\/p>\n\n\n\n<p>-Parras de la Fuente 103<\/p>\n\n\n\n<p>-Acu\u00f1a 83<\/p>\n\n\n\n<p>-Sabinas 71<\/p>\n\n\n\n<p>-Frontera 61<\/p>\n\n\n\n<p>-San Buenaventura 58<\/p>\n\n\n\n<p>-San Juan de Sabinas 45<\/p>\n\n\n\n<p>-M\u00fazquiz 40<\/p>\n\n\n\n<p>-Nava 37<\/p>\n\n\n\n<p>-Cuatro Ci\u00e9negas 25<\/p>\n\n\n\n<p>-Casta\u00f1os 20<\/p>\n\n\n\n<p>-Ocampo 12<\/p>\n\n\n\n<p>-Allende 19<\/p>\n\n\n\n<p>-Zaragoza 18<\/p>\n\n\n\n<p>-Nadadores 18<\/p>\n\n\n\n<p>-Arteaga 17<\/p>\n\n\n\n<p>-General Cepeda 13<\/p>\n\n\n\n<p>-Villa Uni\u00f3n 9<\/p>\n\n\n\n<p>-Viesca 3<\/p>\n\n\n\n<p>-Progreso 3<\/p>\n\n\n\n<p>-Morelos 3<\/p>\n\n\n\n<p>-Sacramento 2<\/p>\n\n\n\n<p>-Lamadrid 2<\/p>\n\n\n\n<p>-Abasolo 2<\/p>\n\n\n\n<p>-Hidalgo 0<\/p>\n\n\n\n<p>-Sierra Mojada 0<\/p>\n\n\n\n<p>-Ju\u00e1rez 0<\/p>\n\n\n\n<p>-Candela 0<\/p>\n\n\n\n<p>-Guerrero 0<\/p>\n\n\n\n<p>-Escobedo 0<\/p>\n\n\n\n<p>-Jim\u00e9nez 0<\/p>\n\n\n\n<p>3.- Al d\u00eda de hoy, se contabilizan en Coahuila EN TOTAL 155,219 casos, incluidos 8,828 decesos.<\/p>\n\n\n\n<p>4.- HOSPITALIZADOS: 50<\/p>\n\n\n\n<p>Monclova 2<\/p>\n\n\n\n<p>Torre\u00f3n 27 (25 confirmados, 2 sospechosos)<\/p>\n\n\n\n<p>Saltillo 16<\/p>\n\n\n\n<p>Piedras Negras 2&nbsp;<\/p>\n\n\n\n<p>Acu\u00f1a 1<\/p>\n\n\n\n<p>San Juan de Sabinas 2<\/p>\n\n\n\n<p>5.- TOTAL DE RECUPERADOS: 141,154<\/p>\n\n\n\n<p>38,231 SALTILLO<\/p>\n\n\n\n<p>29,014 TORRE\u00d3N<\/p>\n\n\n\n<p>13,724 MONCLOVA<\/p>\n\n\n\n<p>11,426 PIEDRAS NEGRAS<\/p>\n\n\n\n<p>6,106 ACU\u00d1A<\/p>\n\n\n\n<p>4,493 SABINAS<\/p>\n\n\n\n<p>3,910 FRONTERA<\/p>\n\n\n\n<p>3,796 SAN PEDRO<\/p>\n\n\n\n<p>3,670 M\u00daZQUIZ<\/p>\n\n\n\n<p>3,437 RAMOS ARIZPE<\/p>\n\n\n\n<p>3,371 SAN JUAN DE SABINAS<\/p>\n\n\n\n<p>3,139 PARRAS DE LA FUENTE<\/p>\n\n\n\n<p>2,680 FRANCISCO I. MADERO<\/p>\n\n\n\n<p>2,536 MATAMOROS<\/p>\n\n\n\n<p>1,850 CUATRO CI\u00c9NEGAS<\/p>\n\n\n\n<p>1,703 NAVA<\/p>\n\n\n\n<p>1,281&nbsp; ALLENDE<\/p>\n\n\n\n<p>1,333 SAN BUENAVENTURA<\/p>\n\n\n\n<p>1,223 CASTA\u00d1OS<\/p>\n\n\n\n<p>676 ZARAGOZA<\/p>\n\n\n\n<p>633 ARTEAGA<\/p>\n\n\n\n<p>522 VILLA UNI\u00d3N<\/p>\n\n\n\n<p>352 MORELOS<\/p>\n\n\n\n<p>340 GENERAL CEPEDA<\/p>\n\n\n\n<p>334 NADADORES<\/p>\n\n\n\n<p>271 SACRAMENTO<\/p>\n\n\n\n<p>270 OCAMPO<\/p>\n\n\n\n<p>203 LAMADRID<\/p>\n\n\n\n<p>158 VIESCA<\/p>\n\n\n\n<p>91 PROGRESO<\/p>\n\n\n\n<p>83 JIM\u00c9NEZ<\/p>\n\n\n\n<p>78 SIERRA MOJADA<\/p>\n\n\n\n<p>52 CANDELA<\/p>\n\n\n\n<p>39 ESCOBEDO<\/p>\n\n\n\n<p>38 GUERRERO<\/p>\n\n\n\n<p>34 ABASOLO<\/p>\n\n\n\n<p>31 JU\u00c1REZ<\/p>\n\n\n\n<p>26 HIDALGO<\/p>\n\n\n\n<p>6.- El Gobierno de Coahuila recomienda a las familias evitar salir a lugares de alta concurrencia.&nbsp; Si es necesario, acudir a aquellos ubicados al aire libre.<\/p>\n\n\n\n<p>Privilegiar aquellos que cumplen con los protocolos establecidos por los Subcomit\u00e9s Regionales de Salud.<\/p>\n\n\n\n<p>7.- Se exhorta a aquellos (as) ciudadanos (as) que tengan que salir a la calle USAR CUBREBOCA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 6 de julio del 2022.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa: 1.- Al d\u00eda de hoy se registran 894&nbsp; nuevos casos en Coahuila, incluidas dos defunciones. DISTRIBUCI\u00d3N DE CASOS 291 SALTILLO 243 TORRE\u00d3N 79 MONCLOVA 41 PIEDRAS NEGRAS 33 MATAMOROS 28 RAMOS ARIZPE&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-9774","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-covid","wpcat-5-id","wpcat-4-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=9774"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9774\/revisions"}],"predecessor-version":[{"id":9775,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9774\/revisions\/9775"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=9774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=9774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=9774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}