{"id":9819,"date":"2022-07-08T20:57:29","date_gmt":"2022-07-09T01:57:29","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=9819"},"modified":"2022-07-08T20:57:30","modified_gmt":"2022-07-09T01:57:30","slug":"coloca-mars-primera-piedra-de-expansion-de-golden-logistics","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/07\/08\/coloca-mars-primera-piedra-de-expansion-de-golden-logistics\/","title":{"rendered":"COLOCA MARS PRIMERA PIEDRA DE EXPANSI\u00d3N DE GOLDEN LOGISTICS."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>La empresa invertir\u00e1 100 mdp en su nuevo proyecto de ampliaci\u00f3n.<\/em><\/strong><\/p>\n\n\n\n<p>Torre\u00f3n, Coahuila de Zaragoza; a 8 de Julio de 2022.- El gobernador Miguel \u00c1ngel Riquelme Sol\u00eds, acompa\u00f1ado por el alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, coloc\u00f3 la primera piedra de la ampliaci\u00f3n de la empresa Golden Logistics, proyecto en el que se invertir\u00e1n m\u00e1s de 100 millones de pesos.<\/p>\n\n\n\n<p>Esta compa\u00f1\u00eda, fundada en 1998, est\u00e1 dedicada a satisfacer las necesidades de transportaci\u00f3n de empresas para el env\u00edo de sus productos desde y a cualquier parte del mundo.<\/p>\n\n\n\n<p>En su mensaje, Riquelme Sol\u00eds mencion\u00f3 que gracias a este tipo de inversiones, Coahuila y la Comarca Lagunera se encuentran listos para hacerle frente a los nuevos retos.<\/p>\n\n\n\n<p>En ese sentido, el Mandatario estatal se\u00f1al\u00f3 que la entidad est\u00e1 ubicada en los primeros lugares de seguridad, en los \u00faltimos lugares de corrupci\u00f3n y en los primeros sitios de confianza de los empresarios y de sus socios.<\/p>\n\n\n\n<p>Miguel Riquelme destac\u00f3 que los aspectos m\u00e1s relevantes por los que los inversionistas voltean a ver a Coahuila, son la seguridad, que la entidad es tercera a nivel nacional en competitividad y que existe Estado de Derecho, pero tambi\u00e9n por la paz laboral, la paz magisterial y la mano de obra calificada.<\/p>\n\n\n\n<p>\u201cEsta inversi\u00f3n no es menor y es de esta bendita tierra, y conf\u00eda en los suyos; por eso es merecedora de un reconocimiento. Gracias por confiar en Torre\u00f3n y en Coahuila\u201d, expres\u00f3.<\/p>\n\n\n\n<p>El Mandatario estatal ratific\u00f3 que seguir\u00e1 apost\u00e1ndole a la seguridad y a la paz social, y por eso se debe aprovechar y valorar.<\/p>\n\n\n\n<p>De la misma manera, puntualiz\u00f3 que para que a la entidad le vaya bien, se debe continuar trabajando juntos: \u201cEste proyecto tiene mucho que aportar, el nuevo cl\u00faster se empieza a asentar en la entidad y va a necesitar m\u00e1s espacio y albergar m\u00e1s empresas\u201d, expuso en referencia a la producci\u00f3n de autos el\u00e9ctricos.&nbsp;<\/p>\n\n\n\n<p>Claudio Mel\u00e9ndez, Director General del Consejo de Golden Logistics, expres\u00f3 la gratitud de hacer entrega de una etapa m\u00e1s de su proyecto.<\/p>\n\n\n\n<p>Mencion\u00f3 que en esta empresa se han invertido 700 millones de pesos a lo largo de 24 a\u00f1os. Inform\u00f3 adem\u00e1s que son 90 mil metros cuadrados de nave, con m\u00e1s de 2 mil metros de cisternas contra incendios, vialidades y patios comunes.<\/p>\n\n\n\n<p>\u201cContamos con la fortuna de tener 19 socios comerciales, con lo que se generan m\u00e1s de mil 200 de empleos, y se cuenta con una reserva territorial para futuros proyectos de nivel industrial\u201d, dijo.<\/p>\n\n\n\n<p>Claudio Mel\u00e9ndez inform\u00f3, adem\u00e1s, que se contar\u00e1 desde ahora con una segunda etapa. La ampliaci\u00f3n es de 22 hect\u00e1reas, con vialidades amplias, preparaciones sanitarias, instalaciones el\u00e9ctricas, 4 mil metros de \u00e1reas verdes y se contempla una donaci\u00f3n municipal de un \u00e1rea de deporte, m\u00e1s una nave industrial de 10 mil metros cuadrados. En esta segunda etapa es una inversi\u00f3n arriba de los 125 millones de pesos.<\/p>\n\n\n\n<p>\u201cReconozco al Estado y Municipio por la voluntad de sus Administraciones para facilitar los tr\u00e1mites, para que empresas sigan llegando a esta ciudad\u201d, recalc\u00f3.<\/p>\n\n\n\n<p>En su mensaje, Rom\u00e1n Cepeda Gonz\u00e1lez, Alcalde de Torre\u00f3n, aprovech\u00f3 para reconocer a los integrantes del Consejo de Golden Logistics por sus m\u00e1s de dos d\u00e9cadas de invertir en La Laguna.<\/p>\n\n\n\n<p>\u201cSon m\u00e1s de 24 a\u00f1os de trabajo y m\u00e1s de 100 millones de inversi\u00f3n en esta nueva etapa. La tarea que hoy nos compete, a seis meses de mi Gobierno, es generar condiciones, confianza y plena coordinaci\u00f3n con nuestro gran aliado: el gobernador Miguel Riquelme\u201d, asegur\u00f3.<\/p>\n\n\n\n<p>En esta ceremonia de colocaci\u00f3n de la primera piedra de la ampliaci\u00f3n de Golden Logistics asistieron, adem\u00e1s, Antonio Guti\u00e9rrez Jard\u00f3n, diputado federal; Claudio Bres Garza, Secretario de Econom\u00eda del Estado; Manuel Covarrubias, miembro del Consejo de Golden Logistics, y Jes\u00fas Garrido, Gerente General de Motores de John Deere.<\/p>\n\n\n\n<p>Adem\u00e1s de funcionarios estatales y municipales, empresarios y sociedad en general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0La empresa invertir\u00e1 100 mdp en su nuevo proyecto de ampliaci\u00f3n. Torre\u00f3n, Coahuila de Zaragoza; a 8 de Julio de 2022.- El gobernador Miguel \u00c1ngel Riquelme Sol\u00eds, acompa\u00f1ado por el alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, coloc\u00f3 la primera piedra de la ampliaci\u00f3n de la empresa Golden Logistics, proyecto en el que se invertir\u00e1n m\u00e1s de 100 millones de pesos. Esta compa\u00f1\u00eda, fundada en 1998, est\u00e1 dedicada a satisfacer las necesidades&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,65,28,7],"tags":[],"class_list":["post-9819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-inversion","category-la-laguna","category-torreon","wpcat-5-id","wpcat-15-id","wpcat-65-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=9819"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9819\/revisions"}],"predecessor-version":[{"id":9821,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/9819\/revisions\/9821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/9820"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=9819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=9819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=9819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}